{"id":33812,"date":"2022-01-11T14:30:17","date_gmt":"2022-01-11T13:30:17","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=33812"},"modified":"2021-12-21T16:56:46","modified_gmt":"2021-12-21T15:56:46","slug":"cipolline-in-agrodolce-pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/01\/11\/cipolline-in-agrodolce-pap\/","title":{"rendered":"Cipolline in agrodolce &#8211; in pentola a pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Vivendo all&#8217;estero, esattamente a Patatolandia, ogni tanto si hanno delle &#8220;voglie italiane&#8221; che si vuole soddisfare.<\/p>\n<p style=\"text-align: justify;\">Altre volte, invece, anche se di VERE voglie non si tratta, si hanno ispirazioni nella preparazione culinaria.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">In questo caso ho trovato al supermercato queste cipolline &#8220;<strong>Perlzwiebeln<\/strong>&#8221; ed e&#8217; stato subito tormentone nella mia testa, un richiamo a voce unica urlato da ogni singola cipollina, tutto un &#8230; &#8220;cipolline borretane in agrodolce&#8221; da DOVER preparare.<\/p>\n<figure id=\"attachment_33827\" aria-describedby=\"caption-attachment-33827\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33827\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409299-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409299-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409299-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409299-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409299-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33827\" class=\"wp-caption-text\">Cipolline in agrodolce<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">E cosi&#8217; e&#8217; stato provato e fatto.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Cipolline in agrodolce<\/strong><\/p>\n<pre>500gr cipolline (Perlzwiebeln nel mio caso)\r\n1\/2 tazzina di aceto (*)\r\nolio\r\n15 g di zucchero (*)\r\n3 chiodi di garofano (facoltativo)\r\n1\/2 tazzina d\u00e2\u20ac\u2122acqua\r\npepe (*)\r\nsale<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate, pelate, togliete le radici delle cipolline<br \/>\nMettete le cipolline nella pentola a pressione con un filo di olio, i chiodi di garofano (se li usate) sale e pepe.<br \/>\nAccendete il fornello, facendo rosolare per qualche minuto le cipolline.<\/p>\n<p style=\"text-align: justify;\">Aggiungo mezza tazzina (da caffe&#8217;) di aceto (o la parte agra che volete utilizzare) facendo sfumare.<br \/>\nInserite mezza tazzina (da caffe&#8217;) di acqua e lo zucchero.<\/p>\n<p style=\"text-align: justify;\">Chiudete la pentola e portatela a pressione, inizia a soffiare calcolate una decina di minuti.<\/p>\n<p style=\"text-align: justify;\">Se dopo il tempo di cottura il sughetto dovesse essere ancora liquido, continuate la cottura &#8211; senza coperchio &#8211; per qualche minuto, alzando la fiamma.<\/p>\n<figure id=\"attachment_33828\" aria-describedby=\"caption-attachment-33828\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33828\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409318-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409318-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409318-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409318-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409318-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33828\" class=\"wp-caption-text\">Cipolline in agrodolce<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Eliminate i chiodi di garofano (se li avete inseriti) prima di servire le cipolline in agrodolce.<\/p>\n<figure id=\"attachment_33830\" aria-describedby=\"caption-attachment-33830\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33830\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/cipolline_agrodolce-1024x576.jpeg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/cipolline_agrodolce-1024x576.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/cipolline_agrodolce-150x84.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/cipolline_agrodolce-300x169.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/cipolline_agrodolce-768x432.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33830\" class=\"wp-caption-text\">Cipolline in agrodolce<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">L&#8217;<strong>aceto<\/strong> nella preparazione puo&#8217; essere di diversa tipologia:<br \/>\n&#8211; balsamico di Modena (colore ambrato e un sapore particolare)<br \/>\n&#8211; aceto bianco<br \/>\n&#8211; vino bianco<\/li>\n<li style=\"text-align: justify;\">Lo <strong>zucchero<\/strong> puo&#8217; essere sostituito con<br \/>\n&#8211; miele (millefiori)<br \/>\n&#8211; zucchero di canna<\/li>\n<li style=\"text-align: justify;\">Sarebbe meglio utilizzare il <strong>pepe<\/strong> <strong>bianco<\/strong>, cosi&#8217; da non avere inestetici puntini neri nella preparazione<\/li>\n<li style=\"text-align: justify;\">Non le ho chiamate _volutamente_ borretane in quanto non lo sono. Ma nulla toglie nel non utilizzarle!<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Per accompagnare questo contorno di <em>cipolline in agrodolce<\/em>, ho pensato di cucinare del <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/09\/04\/salmone-melograno\/\">salmone<\/a><\/strong><\/em>, anch&#8217;esso in agrodolce, ma addolcito con succo di melograno.<\/p>\n<figure id=\"attachment_33829\" aria-describedby=\"caption-attachment-33829\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33829\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409272-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409272-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409272-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409272-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/01\/1635185409272-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33829\" class=\"wp-caption-text\">Cipolline e salmone in agrodolce<\/figcaption><\/figure>\n<hr \/>\n<p style=\"text-align: justify;\">La &#8220;<strong>Cipolla Perlata<\/strong>&#8221; (conosciuta anche come &#8220;cipolla a bottone&#8221;) \/ Perlzwiebeln (Allium ampeloprasum gruppo delle cipolle perlate, syn.: Allium porrum var. Sectivum) appartiene alla sottofamiglia della famiglia dei porri (Allioideae).<br \/>\n\u00c3\u02c6 un gruppo coltivato del porro campestre (Allium ampeloprasum).<br \/>\nLe cipolle perlate raggiungono un diametro compreso tra 15 e 35 mm e hanno una buccia esterna luccicante da bianca a argentea.<\/p>\n<p style=\"text-align: justify;\">La cipolla perlata e la cipolla d&#8217;argento sembrano molto simili, ma appartengono a due specie botaniche diverse.<\/p>\n<p style=\"text-align: justify;\">Le cipolle perlate sono state coltivate principalmente in Germania, Paesi Bassi e Italia.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivendo all&#8217;estero, esattamente a Patatolandia, ogni tanto si hanno delle &#8220;voglie italiane&#8221; che si vuole soddisfare. Altre volte, invece, anche se di VERE voglie non si tratta, si hanno ispirazioni nella preparazione culinaria.<\/p>\n","protected":false},"author":2,"featured_media":33830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22,180],"tags":[53],"class_list":["post-33812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food","category-pentola-a-pressione","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=33812"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33812\/revisions"}],"predecessor-version":[{"id":33832,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33812\/revisions\/33832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/33830"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=33812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=33812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=33812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}