{"id":33465,"date":"2022-01-18T13:41:21","date_gmt":"2022-01-18T12:41:21","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=33465"},"modified":"2021-11-01T17:18:42","modified_gmt":"2021-11-01T16:18:42","slug":"freekeh-cosa-come-cuocerlo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/01\/18\/freekeh-cosa-come-cuocerlo\/","title":{"rendered":"Freekeh &#8211; Cosa e&#8217; e come cuocerlo."},"content":{"rendered":"<p style=\"text-align: justify;\">In diversi mi avete chiesto che cosa e&#8217; il &#8220;<strong>freekeh<\/strong>&#8220;.<br \/>\nEccovi accontentati.<\/p>\n<p style=\"text-align: justify;\">Il <strong>Freekeh<\/strong>, noto anche come <strong>Farik<\/strong> (in arabo: \u00d9\u0081\u00d8\u00b1\u00d9\u0160\u00d9\u0192\u00d8\u00a9\u00e2\u20ac\u017d), \u00c3\u00a8 un tipo di grano verde (Triticum turgidum var. Durum) che \u00c3\u00a8 raccolto prematuramente e tostato.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Solitamente viene raccolto nel mese di aprile, ma varia a seconda del clima e della zona in cui questo cereale \u00c3\u00a8 coltivato. \u00c3\u02c6 un alimento usato in diversi paesi del bacino del Mediterraneo, ed i maggiori produttori si trovano in Palestina, Egitto, Libano e Siria.<br \/>\n\u00c3\u02c6 un prodotto molto pi\u00c3\u00b9 ricco in proteine, vitamine e minerali del grano normale. Inoltre, ha un valore nutrizionale superiore a quello del riso, ed \u00c3\u00a8 ricco in calcio, ferro, potassio e zinco.<\/p>\n<figure id=\"attachment_33506\" aria-describedby=\"caption-attachment-33506\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33506 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305217-e1633524955356-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305217-e1633524955356-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305217-e1633524955356-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305217-e1633524955356-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305217-e1633524955356-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305217-e1633524955356-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33506\" class=\"wp-caption-text\">Freekeh, noto anche come Farik (in arabo: \u00d9\u0081\u00d8\u00b1\u00d9\u0160\u00d9\u0192\u00d8\u00a9\u00e2\u20ac\u017d)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il <strong>freekeh<\/strong> \u00c3\u00a8 particolarmente diffuso nelle cucine levantine, araba, egiziana, nord-africane e del Medio Oriente.<\/p>\n<p style=\"text-align: justify;\">Il Freekeh si pu\u00c3\u00b2 trovare in versioni differenti, ovvero intero oppure spezzato.<\/p>\n<figure id=\"attachment_33505\" aria-describedby=\"caption-attachment-33505\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33505 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305209-e1633524962925-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305209-e1633524962925-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305209-e1633524962925-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305209-e1633524962925-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305209-e1633524962925-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305209-e1633524962925-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33505\" class=\"wp-caption-text\">Freekeh, noto anche come Farik<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Si consuma principalmente intero e risulta un ottimo sostituto del cous cous o del riso.<br \/>\nEssendo un cereale molto versatile, puo&#8217; essere mangiato da solo, semplicemente con un goccio di olio, oppure condito con verdure o, meglio ancora, accompagnato da carni stufate, come richiede la tradizione.<\/p>\n<p style=\"text-align: justify;\">Puo&#8217; integrare zuppe ma anche essere consumato a colazione in una ciotola a parte accompagnato da frutta per chi ama gli inizi di giornata salutari e pieni di energia.<\/p>\n<p style=\"text-align: justify;\">\u00c3\u02c6 un ottimo sostituto di cereali come la quinoa ed il farro.<\/p>\n<p style=\"text-align: justify;\">Come molti prodotti a base di grano, il freekeh viene cotto con acqua bollente. La sua cottura dipende dalla pezzatura e granulometria.<\/p>\n<figure id=\"attachment_33509\" aria-describedby=\"caption-attachment-33509\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33509 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305240-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305240-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305240-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305240-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305240-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33509\" class=\"wp-caption-text\">Freekeh, noto anche come Farik<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Possiamo dunque distinguere questi modi (Info prese in Internet da diverse fonti<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>Freekeh integrale<\/strong><\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\">Microonde (2:1)<br \/>\nMettete 2 tazze di acqua bollente, 1 tazza di Freekeh e \u00c2\u00bd cucchiaino di sale (opzionale) in una ciotola profonda per microonde.<br \/>\nForno a microonde (1000w) scoperto in alto per 14 minuti. Coprite e lasciate riposare per altri 10 minuti.<\/li>\n<li style=\"text-align: justify;\">Metodo di assorbimento (4:1)<br \/>\nMettere 1 tazza di Freekeh, 4 tazze di acqua fredda e \u00c2\u00bd cucchiaino di sale (facoltativo) in una casseruola e portare a ebollizione.<br \/>\nAbbassate il fuoco al minimo, coprite con il coperchio. Cuocete dolcemente per altri 35-40 minuti circa finch\u00c3\u00a9 i grani risultano teneri o finch\u00c3\u00a9 il liquido non viene assorbito.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>Freekeh spezzato<\/strong><\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\">Microonde (2:1)<br \/>\nMettete 2 tazze di acqua bollente, 1 tazza di Freekeh e \u00c2\u00bd cucchiaino di sale (opzionale) in una ciotola profonda per microonde.<br \/>\nForno a microonde (1000w) scoperto in alto per 14 minuti. Coprite e lasciate riposare per altri 10 minuti.<\/li>\n<li style=\"text-align: justify;\">Metodo di assorbimento (3:1)<br \/>\nMettere 1 tazza di Freekeh, 3 tazze di acqua fredda e \u00c2\u00bd cucchiaino di sale (facoltativo) in una casseruola e portare a ebollizione.<\/li>\n<\/ul>\n<figure id=\"attachment_33508\" aria-describedby=\"caption-attachment-33508\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33508 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305232-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305232-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305232-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305232-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633517305232-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33508\" class=\"wp-caption-text\">Freekeh, noto anche come Farik<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>Cuocere il freekeh come la pasta (tanto:cereali)<\/strong><\/span><br \/>\nRiempite una pentola d&#8217;acqua e aggiungete i cereali. Portateli a ebollizione, quindi abbassate la fiamma e fate sobbollire per 45 minuti o finch\u00c3\u00a9 il freekeh non sar\u00c3\u00a0 gonfio e morbido. Scolate l&#8217;acqua in eccesso con un colino come fareste con la pasta.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>Cuocere il freekeh come il riso (2,5:1)<\/strong><\/span><br \/>\nMettete due tazze e mezzo di acqua in una casseruola e portare a ebollizione. Aggiungete una tazza di freekeh, mezzo cucchiaino di sale e olio d&#8217;oliva o burro. Riducete il fuoco, fate sobbollire e coprite la pentola fino a quando l&#8217;acqua non viene assorbita. Al termine, sgranate i cereali.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>Cuocere il freekeh in stock\/brodo, come la zuppa<\/strong><\/span><br \/>\nIl freekeh pu\u00c3\u00b2 essere cotto direttamente nel brodo mentre il resto della zuppa cuoce invece che separatamente. Aggiungete semplicemente il freekeh alla pentola insieme a qualsiasi altro ingrediente, come cipolle e verdure, versateci sopra il brodo e lasciate sobbollire per un&#8217;ora.<\/p>\n<p style=\"text-align: justify;\">Ancora una volta mi sono affidata alla <em><strong><a href=\"https:\/\/www.nabalifairkost.com\/\">Nabali<\/a><\/strong><\/em>, trovandomi decisamente bene, sia come prodotto che come spedizione.<br \/>\nQuesta societa&#8217; si impegna nel sostenere gli agricoltori e le cooperative nelle regioni socialmente ed economicamente svantaggiate dei territori palestinesi e del Marocco, attraverso il commercio equo e diretto di cibi di gastronomia.<\/p>\n<p style=\"text-align: justify;\">Se siete curiosi di (ri)-vedere l&#8217;utilizzo di questo cereale, allora potete seguire questo link che vi portera&#8217; alla ricetta del &#8220;<em><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/10\/12\/freekeh-pilaf-ottolenghi\/\"><strong>Freekeh pilaf<\/strong><\/a><\/em>&#8221; (dello chef Ottolenghi).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-33510\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-pilaf-1024x633.jpeg\" alt=\"\" width=\"525\" height=\"325\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-pilaf-1024x633.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-pilaf-150x93.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-pilaf-300x185.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-pilaf-768x475.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Oppure questo, per una ottima &#8220;<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/10\/26\/freekeh-salat\/\">Salata Freekeh<\/a><\/strong><\/em>&#8221; vegetariana\/vegana.<\/p>\n<figure id=\"attachment_33834\" aria-describedby=\"caption-attachment-33834\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33834\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-salat-1024x647.jpeg\" alt=\"\" width=\"525\" height=\"332\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-salat-1024x647.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-salat-150x95.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-salat-300x190.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/freekeh-salat-768x486.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33834\" class=\"wp-caption-text\">Freejeh Salat<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Una decidina di anni fa avevo scritto dell&#8217;acquisto del <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2011\/06\/04\/farro-verde-gruenkern\/\">Gruenkern<\/a><\/strong><\/em><br \/>\nNon fate confusione!<br \/>\nIl &#8220;<strong>Gruenkern<\/strong>&#8221; , o farro verde, deriva dal farro.<br \/>\nIl <strong>Freekeh<\/strong>, invece, dal grano.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diversi mi avete chiesto che cosa e&#8217; il &#8220;freekeh&#8220;. Eccovi accontentati. Il Freekeh, noto anche come Farik (in arabo: \u00d9\u0081\u00d8\u00b1\u00d9\u0160\u00d9\u0192\u00d8\u00a9\u00e2\u20ac\u017d), \u00c3\u00a8 un tipo di grano verde (Triticum turgidum var. Durum) che \u00c3\u00a8 raccolto prematuramente e tostato.<\/p>\n","protected":false},"author":2,"featured_media":33509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,58,22],"tags":[234,54],"class_list":["post-33465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-curiosita","category-food","tag-asia_occidentale","tag-cereali"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=33465"}],"version-history":[{"count":11,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33465\/revisions"}],"predecessor-version":[{"id":33839,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33465\/revisions\/33839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/33509"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=33465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=33465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=33465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}