{"id":33418,"date":"2021-10-03T17:08:24","date_gmt":"2021-10-03T15:08:24","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=33418"},"modified":"2021-10-04T17:14:09","modified_gmt":"2021-10-04T15:14:09","slug":"brasato-al-barbera","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/10\/03\/brasato-al-barbera\/","title":{"rendered":"Brasato al Barbera"},"content":{"rendered":"<p style=\"text-align: justify;\">Non esiste solamente il &#8220;<em>brasato al barolo<\/em>&#8220;, versione molto famosa per la preparazione e, soprattutto, la cottura della carne.<br \/>\nE&#8217; possibile trovare anche il &#8220;<em><strong>brasato al Barbera<\/strong><\/em>&#8221; e, nonostante oggi sia la Festa Nazionale della Germania, ho pensato di portare in tavola.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">E&#8217; dunque un secondo piatto per le &#8220;grandi occasioni&#8221;, per ritrovarsi al desco famigliare e, diciamolo, comporta anche un certo tempo per la preparazione (= cottura).<\/p>\n<p style=\"text-align: justify;\">In un primo momento ho pensato di cuocerlo nella pentola a pressione, poi ho modificato la mia intenzione, preferendo una lunga e lenta cottura tradizionale.<\/p>\n<figure id=\"attachment_33423\" aria-describedby=\"caption-attachment-33423\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33423\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/brasato-1024x580.jpeg\" alt=\"\" width=\"525\" height=\"297\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/brasato-1024x580.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/brasato-150x85.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/brasato-300x170.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/brasato-768x435.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33423\" class=\"wp-caption-text\">brasato al barbera<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/www.cucchiaio.it\/ricetta\/brasato-al-barbera\/\">Brasato al Barbera<\/a><\/strong><\/em> &#8211; 4 persone<\/p>\n<pre>800 g di polpa di manzo\r\n1 bottiglia di Barbera\r\n\r\n1 cipolla\r\n1 costa di sedano\r\n1 carota\r\n1 spicchio d'aglio\r\n3 bacche di ginepro\r\n4 chiodi di garofano\r\n1 bastoncino di cannella\r\n1 foglia di alloro\r\n\r\n1\/2 bicchiere di Brandy\r\n40 g di burro\r\nolio extravergine di oliva\r\nsale\r\npepe nero<\/pre>\n<p><strong>Procedimenti<\/strong><\/p>\n<p style=\"text-align: justify;\">Incomiciate con il legare la carne con lo spago da cucina.<br \/>\nTrasferite la carne in una ciotola con il sedano e la carota tagliati a tocchetti, la cipolla mondata, tagliata in quarti e steccata con i chiodi di garofano. Aggiungete l&#8217;aglio, la cannella, le bacche di ginepro,<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-33401\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007576-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007576-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007576-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007576-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007576-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Versate il Barbera, coprite con della pellicola alimentare e lasciate marinare per 12 ore.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-33400\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007567-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007567-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007567-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007567-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/06\/1633169007567-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Trascorso questo tempo sgocciolate la carne dalla marinata e filtrate quest&#8217;ultima conservando il vino per le fasi successive. Trasferite nel mixer le verdure e tritatele finemente.<\/p>\n<p style=\"text-align: justify;\">Fate appassire questo trito in una casseruola con olio e burro.<br \/>\nUnite la carne e fatela rosolare uniformemente senza mai forarla. Sfumate con il liquore, lasciatelo evaporare e aggiustate di sale e pepe.<\/p>\n<p style=\"text-align: justify;\">Aggiungete adesso met\u00c3\u00a0 del vino tenuto da parte, coprite e abbassate la fiamma.<br \/>\nLasciate cuocere per circa 3 ore, girandola di tanto in tanto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-33421\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093363-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093363-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093363-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093363-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093363-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Qualora il fondo di cottura dovesse asciugarsi troppo unite altro vino.<\/p>\n<p style=\"text-align: justify;\">A cottura ultimata scolate la carne e tenetela in caldo mentre frullate il fondo di cottura.<br \/>\nServite il brasato al Barbera a fette nappandolo con la sua salsa.<\/p>\n<figure id=\"attachment_33422\" aria-describedby=\"caption-attachment-33422\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-33422\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093352-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093352-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093352-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093352-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/10\/1633273093352-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-33422\" class=\"wp-caption-text\">brasato al barbera<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Avendo deciso di non cuocere a pressione, ho optato per il forno olandese\/dutch oven\/pentola olandese<\/li>\n<li style=\"text-align: justify;\">Ho evitato di frullare la seconda volta la carne, dopo la cottura<\/li>\n<li style=\"text-align: justify;\">Ottimo accompagnamento e&#8217; con polenta, pure&#8217; di patate (come abbiamo fatto noi) , &#8220;semmel knodel&#8221; oppure dei <em><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/09\/16\/burgunderbraten-serviettenknodel\/\"><strong>Serviettenkn\u00c3\u00b6del<\/strong><\/a><\/em><\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non esiste solamente il &#8220;brasato al barolo&#8220;, versione molto famosa per la preparazione e, soprattutto, la cottura della carne. E&#8217; possibile trovare anche il &#8220;brasato al Barbera&#8221; e, nonostante oggi sia la Festa Nazionale della Germania, ho pensato di portare in tavola.<\/p>\n","protected":false},"author":2,"featured_media":33423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[249],"class_list":["post-33418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-dutch_oven"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=33418"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33418\/revisions"}],"predecessor-version":[{"id":33425,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/33418\/revisions\/33425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/33423"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=33418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=33418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=33418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}