{"id":32532,"date":"2022-07-27T13:36:07","date_gmt":"2022-07-27T11:36:07","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=32532"},"modified":"2023-03-26T17:13:21","modified_gmt":"2023-03-26T15:13:21","slug":"spuma-di-caffe","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/07\/27\/spuma-di-caffe\/","title":{"rendered":"Spuma di caffe&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">Con questo caldo torrido non si puo&#8217; resistere e bisogna bere tanto.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Perche&#8217; non optare per una bevanda rinfrescante, dissetante e che ci soddisfi?<\/p>\n<p style=\"text-align: justify;\">Avete mai provato a preparare la &#8220;spuma al caffe'&#8221;?<br \/>\nSe utilizzate un frullatore funzionante, e non il mio frullino da latte manuale, potreste ottenere tanta schiuma con poca quantita&#8217; di ingredienti.<br \/>\nUna nuvola vaporosa da tuffarsi all&#8217;interno, e da degustare in un attimo di relax<\/p>\n<figure id=\"attachment_38127\" aria-describedby=\"caption-attachment-38127\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38127\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703077-e1657987754144-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703077-e1657987754144-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703077-e1657987754144-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703077-e1657987754144-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703077-e1657987754144-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-38127\" class=\"wp-caption-text\">Crema al caffe&#8217;<\/figcaption><\/figure>\n<p><strong>Ingredienti &#8211; Spuma di caffe&#8217;<\/strong> &#8211; 1 persona<\/p>\n<pre>3 cucchiai di caff\u00c3\u00a8 solubile\r\n3 cucchiai di zucchero\r\n30 ml di acqua\r\n\r\nghiaccio (opzionale)\r\npanna montata (opzionale)\r\npanna da montare (opzionale)\r\nlatte da montare (opzionale)\r\n\r\n<strong>Per decorare (opzionale)<\/strong>\r\n biscotti q.b.\r\n gocce di cioccolato q.b.\r\n cannella a.b.\r\n cacao amaro<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Montate il caff\u00c3\u00a8, lo zucchero e l\u00e2\u20ac\u2122acqua per qualche minuto con il frullatore a immersione.<br \/>\nCompletate con panna montata o latte montato e decorate con cacao amaro, gocce di cioccolato o cannella. Oppure degustatelo al naturale.<\/p>\n<p style=\"text-align: justify;\">Per una versione piu&#8217; golosa, potete optare alternando la crema di montata con dei biscottini sbriciolati<\/p>\n<p style=\"text-align: justify;\">Versate il tutto in un bicchiere alternando, biscotti sbriciolati e la crema di caffe&#8217;.<br \/>\nInfine guarnire con gocce di cioccolato e cannella.<\/p>\n<figure id=\"attachment_38126\" aria-describedby=\"caption-attachment-38126\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38126\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703068-e1657987745149-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703068-e1657987745149-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703068-e1657987745149-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703068-e1657987745149-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2022\/07\/ok_1657985703068-e1657987745149-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-38126\" class=\"wp-caption-text\">Crema al caffe&#8217;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Vorrei poi suggerirvi di provare anche un &#8220;<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/10\/23\/dalgona-coffee\/\">dalgona caffe&#8217;<\/a><\/strong><\/em>&#8220;, molto simile alla crema appena proposta, ma di origine coreana.<br \/>\nOppure preparare del <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/11\/25\/caffe-shekerato\/\">caffe&#8217; shakerato<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">E per i poveri bambini assetati che non bevono caffe&#8217;?<br \/>\nNessun problema! Qui vi propongo bevande alternative analcoliche<\/p>\n<ul style=\"text-align: justify;\">\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/08\/07\/tonga_otai\/\">Otai<\/a><\/strong><\/em> &#8211; dal Regno di Tonga &#8211; una bevanda a base di anguria, ananas e cocco<\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/04\/03\/el-salvador_fresco-de-chan\/\">Fresco de Chan<\/a><\/strong><\/em> &#8211; dal El Salvador &#8211; estratto di fragola con semi di chia<\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2022\/03\/04\/khakshir-semini-in-acqua\/\">Kakshir<\/a><\/strong><\/em> &#8211; dalla Persia &#8211; con dei piccoli semini, forse un po&#8217; complicati da recuperare<\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/10\/11\/pulp-fiction-milkshake\/\">Milk Shake <\/a><\/strong><\/em>&#8211; gelato alla vaniglia e ghiaccio tritato<\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/07\/12\/agua-fresca-anguria-cocomero\/\">Agua fresca all&#8217;anguria<\/a><\/strong><\/em><\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/06\/27\/agua-fresca\/\">Agua fresca al mango<\/a><\/strong><\/em>, direttamente dal Messico<\/li>\n<li><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/08\/28\/turchia_ayran\/\"><em><strong>Ayran<\/strong><\/em><\/a> dalla Turchia<\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/08\/14\/togo_jus-gingembre\/\">Succo allo zenzero<\/a><\/strong><\/em>, dal Togo<\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/07\/03\/korean-style-strawberry-milk\/\">Latte alla fragola in stile coreano<\/a><\/strong><\/em><\/li>\n<li><em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/05\/28\/guinea_te-freddo-ibisco\/\">Te freddo all&#8217;ibisco<\/a><\/strong><\/em>, dalla Guinea<\/li>\n<\/ul>\n<figure id=\"attachment_32403\" aria-describedby=\"caption-attachment-32403\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-32403\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/07\/Latte_fragola_coreano_2-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/07\/Latte_fragola_coreano_2-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/07\/Latte_fragola_coreano_2-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/07\/Latte_fragola_coreano_2-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/07\/Latte_fragola_coreano_2-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-32403\" class=\"wp-caption-text\">Latte alla fragola in stile coreano<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Se poi tutte queste proposte non fanno per voi, possiamo riflettere su una <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/08\/17\/acqua-aromatizzata\/\">acqua aromatizzata<\/a><\/strong><\/em>, a gusto personale.<br \/>\nPer passare a dell&#8217;<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/07\/25\/terere-yerba-mate-freddo\/\">erba mate<\/a><\/strong><\/em>, anche senza bombilla, da preparare a freddo (terere).<br \/>\nOppure acquistare uno dei tanti gusti di te, predisposti per la loro preparazione a freddo, come <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/08\/03\/teekanne-frio\/\">questo<\/a><\/strong><\/em> (ad esempio).<\/p>\n<p style=\"text-align: justify;\">Insomma, in qualsiasi modo vogliate assumere liquidi, fatelo con questo caldo!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con questo caldo torrido non si puo&#8217; resistere e bisogna bere tanto.<\/p>\n","protected":false},"author":2,"featured_media":38128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,22],"tags":[],"class_list":["post-32532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevande","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/32532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=32532"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/32532\/revisions"}],"predecessor-version":[{"id":41441,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/32532\/revisions\/41441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/38128"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=32532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=32532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=32532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}