{"id":31585,"date":"2021-09-16T14:36:00","date_gmt":"2021-09-16T12:36:00","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=31585"},"modified":"2022-01-24T17:11:17","modified_gmt":"2022-01-24T16:11:17","slug":"pane-spinaci-uova-quaglia","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/09\/16\/pane-spinaci-uova-quaglia\/","title":{"rendered":"Cestini di pane con spinaci e uova di quaglia"},"content":{"rendered":"<p style=\"text-align: justify;\">Nonostante la mia scarsa capacita&#8217; di cucinare, cerco sempre di variare il cibo che propongo sulla tavola quotidiana.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Da qualche tempo a questa parte, almeno una volta a settimana preparo delle uova, sotto forma di preparazioni diverse.<br \/>\nCucino le uova all&#8217;occhio di bue, in una piccola frittatina, come <em><strong>finger-food<\/strong><\/em>, come piatto unico dolce serale <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2012\/06\/18\/kaiserschmarrn\/\">Kaiserschmarrn<\/a><\/strong><\/em>, <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/08\/03\/uova-strapazzate\/\">strapazzate<\/a><\/strong><\/em>, sode accompagnandole ad una insalata mista, se ho tempo per preparare la salsa di pomodoro allora vado di <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/03\/01\/libia_shakshuka\/\">shakshuka<\/a><\/strong><\/em>.<br \/>\nInsomma, le vado a scovare un po&#8217; tutte..<\/p>\n<p style=\"text-align: justify;\">Oggi ho pensato di preparare dei nidi di spinaci,\u00c2\u00a0 con appunti delle uova.<br \/>\nPensando ad un piccolo antipasto, per dei semplici bocconcini sfiziosi, o per delle mono-porzioni in caso di dieta, si possono sostituire le uova di gallina con quelle di quaglia, notoriamente piu&#8217; piccole.<\/p>\n<figure id=\"attachment_31604\" aria-describedby=\"caption-attachment-31604\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31604 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149652-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149652-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149652-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149652-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149652-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31604\" class=\"wp-caption-text\">Cestini di pane con spinaci e uova quaglia<\/figcaption><\/figure>\n<p>Dunque.. ecco&#8230;<\/p>\n<p><strong>Ingredienti &#8211; Cestini di pane con spinaci e uova di quaglia <\/strong>&#8211; 10 porzioni<strong><br \/>\n<\/strong><\/p>\n<pre>400 grammi di spinaci surgelati\r\n10 uova di quaglia\r\ngrana o altro formaggio\r\n10 fette di pan carre'\r\nsale\r\npepe<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate con il lessare gli spinaci, in poca acqua salata per un paio di minuti.<br \/>\nPotete effettuare questa operazione utilizzando una pentola a pressione, una pentola normale oppure inserendoli nel forno a microonde.<br \/>\nUna volta cotti, scolate gli spinaci, lasciateli intiepidire e strizzateli ben bene, per rimuovere la maggiore quantita&#8217; possibile di acqua.<\/p>\n<p style=\"text-align: justify;\">Nel frattempo, prendete le fette di pan carre&#8217; e, se volete, rimuovete la crosta esterna.<br \/>\nAiutandovi con un mattarello schiacciate ogni singola fetta di pane, cercando di mantenere la forma quadrata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31612\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149701-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149701-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149701-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149701-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149701-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Inserite ogni fettina schiacciata in un contenitore da muffin.<br \/>\nOnestamente non ho imburrato\/oleato lo stampo ed il &#8220;nido&#8221; e&#8217; uscito senza problemi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31613\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149707-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149707-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149707-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149707-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149707-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">In ogni singola forma, inserite del formaggio grattugiato sul fondo, oppure dei pezzetti di formaggio a pasta dura.<br \/>\nPersonalmente eviterei la mozzarella, giusto perche&#8217; questa in cottura rilascia il suo liquido di conservazione, andando a bagnare terribilmente il pane.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31610\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149689-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149689-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149689-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149689-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149689-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Fate tostare il pane in forno statico, preriscaldato a 180gradi, per una decina di minuti, nella teglia da muffin, cosi&#8217; da conservarne la forma.<\/p>\n<p style=\"text-align: justify;\">Rimuovete ed inserite un pochino di spinaci lessati, reinserite nel forno e proseguite la cottura, per un&#8217;altra decina di minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31607\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149671-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149671-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149671-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149671-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149671-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Prendete le uova di quaglia (o di gallina)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31609\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149683-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149683-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149683-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149683-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149683-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">, rompete un uovo alla volta, ed inseritelo in ogni &#8220;cestino&#8221;.<br \/>\nFate attenzione nella rottura dell&#8217;uovo, nonostante siano piccole, le uova di quaglia sono anche resistenti!<br \/>\nEventualmente versate l&#8217;uovo in una tazzina e ritravasatelo nel singolo &#8220;nido&#8221;.<\/p>\n<figure id=\"attachment_31606\" aria-describedby=\"caption-attachment-31606\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31606 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149665-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149665-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149665-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149665-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620228149665-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31606\" class=\"wp-caption-text\">Cestini di pane con spinaci e uova quaglia<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Rimettete in forno\u00c2\u00a0 e proseguite la cottura sino a quando l&#8217;albume da trasparente non sara&#8217; diventato bianco. Non prolungate troppo la cottura, o anche al tuorlo cuocera&#8217; subito, creando una crosticina sulla sua superficie.<\/p>\n<p>Salate, pepate e &#8230; buon appetito!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante la mia scarsa capacita&#8217; di cucinare, cerco sempre di variare il cibo che propongo sulla tavola quotidiana.<\/p>\n","protected":false},"author":2,"featured_media":31604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,22,60,61],"tags":[62],"class_list":["post-31585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antipasti","category-food","category-secondi_piatti","category-uova-formaggio","tag-pasqua"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=31585"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31585\/revisions"}],"predecessor-version":[{"id":35542,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31585\/revisions\/35542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/31604"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=31585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=31585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=31585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}