{"id":31554,"date":"2021-09-04T14:14:02","date_gmt":"2021-09-04T12:14:02","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=31554"},"modified":"2021-07-04T17:31:50","modified_gmt":"2021-07-04T15:31:50","slug":"salmone-melograno","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/09\/04\/salmone-melograno\/","title":{"rendered":"Salmone glassato al melograno (al forno)."},"content":{"rendered":"<p style=\"text-align: justify;\">Quella che vi propongo oggi e&#8217; una ricetta con del <strong>salmone glassato<\/strong> decisamente gustosa, dal sapore &#8220;orientaleggiante&#8221; e preparata con solamente 3 ingredienti in tutto.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Facile, veloce, ottima.<br \/>\nChe cosa si puo&#8217; chiedere di piu&#8217; per un pasto leggermente diverso dal solito, non pesante ma relativamente light?<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Salmone glassato al melograno (al forno)<\/strong> &#8211; 3 persone<\/p>\n<pre>3 trancetti di salmone\r\n1 spicchio di aglio\r\nsalsa di soia (2 cucchiai)\r\nsucco di melograno (circa 100ml)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate preriscaldando il forno, modalita&#8217; statica, a 200\u00c2\u00b0.<\/p>\n<p style=\"text-align: justify;\">Unite in una ciotola capiente il succo di melograno, la salsa di soia e l&#8217;aglio tritato (lasciatelo intero nel caso in cui non lo gradiste troppo).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31574\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368335-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368335-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368335-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368335-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368335-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31573\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368329-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368329-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368329-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368329-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368329-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nMescolate bene tutti gli ingredienti ed aggiungete il salmone, coprendolo con il composto.<br \/>\nCoprite la ciotola e lasciate marinare il pesce per circa 15 minuti.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31572\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368323-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368323-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368323-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368323-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368323-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Su una teglia da forno (*) disponete i tranci di salmone, facendo attenzione a posizionarli con la pelle sul fondo, e cuoceteli in forno per circa 7 minuti.<\/p>\n<figure id=\"attachment_31571\" aria-describedby=\"caption-attachment-31571\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31571\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368318-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368318-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368318-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368318-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368318-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31571\" class=\"wp-caption-text\">Salmone glassato al melograno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Nel frattempo, versate la marinata avanzata in un pentolino e fatela bollire a fuoco medio-alto per qualche minuto, cosi&#8217; da restringerla un poco rendendola sciropposa.<\/p>\n<p style=\"text-align: justify;\">Trascorso il tempo di cottura del salmone, versate meta&#8217; della marinata ridotta sul salmone.<br \/>\nRiprendete la cottura del pesce in forno per altri 5-7 minuti o fino a quando il salmone non e&#8217; cotto.<\/p>\n<figure id=\"attachment_31570\" aria-describedby=\"caption-attachment-31570\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-31570\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368312-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368312-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368312-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368312-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1620128368312-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31570\" class=\"wp-caption-text\">Salmone glassato al melograno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Impiattate e versate la meta&#8217; della marinata avanzata sul salmone.<br \/>\nServite subito.<\/p>\n<p style=\"text-align: justify;\"><strong>Note Personali<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Ho coperto la teglia con carta forno, cosi&#8217; che la pulizia potesse divenire piu&#8217; veloce.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Per accompagnare questo piatto e&#8217; ottimo del riso pilaf bianco, con una insalatina di stagione.<br \/>\nNoi lo abbiamo degustato con una <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/03\/11\/insalata-arancia-finocchio\/\">insalatina di arancia e finocchi<\/a><\/strong><\/em>, ed una crocchetta di patate, anche perche&#8217; il forno era gia&#8217; acceso \ud83d\ude09<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Il gusto e&#8217; interessante, e si bilancia a seconda della quantita&#8217; dei 2 liquidi inseriti.<br \/>\nSe volete potete, chiaramente, aumentare o diminuire le dosi a seconda dei vostri gusti.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quella che vi propongo oggi e&#8217; una ricetta con del salmone glassato decisamente gustosa, dal sapore &#8220;orientaleggiante&#8221; e preparata con solamente 3 ingredienti in tutto.<\/p>\n","protected":false},"author":2,"featured_media":31570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,60],"tags":[107],"class_list":["post-31554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-secondi_piatti","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=31554"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31554\/revisions"}],"predecessor-version":[{"id":31576,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31554\/revisions\/31576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/31570"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=31554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=31554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=31554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}