{"id":31026,"date":"2021-05-27T14:06:38","date_gmt":"2021-05-27T12:06:38","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=31026"},"modified":"2022-02-28T15:19:08","modified_gmt":"2022-02-28T14:19:08","slug":"arrosto-di-sedano-rapa-al-forno","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/05\/27\/arrosto-di-sedano-rapa-al-forno\/","title":{"rendered":"Arrosto di sedano rapa al forno"},"content":{"rendered":"<p style=\"text-align: justify;\">Sono l&#8217;ultima a scoprire le cose,.<br \/>\nLe novita&#8217;, alle volte, non fanno proprio per me.<br \/>\nLe sorprese? Devo sempre pianificare tutto. Come in questo caso.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Ebbene si, era da diverso tempo, probabilmente anni, che gira(va) sul Web questa idea: prendere un sedano rapa e\u00c2\u00a0 cuocerlo al forno.<\/p>\n<p style=\"text-align: justify;\">Nonostante i miei difetti di &#8220;pianificare tutto e tutti&#8221;, resto sempre molto curiosa e vorrei sempre provare.<br \/>\nHo preso coraggio ed ho acquistato la materia prima (il sedano rapa, appunto) che e&#8217; restato in frigorifero per guardarmi per diversi giorni.<\/p>\n<figure id=\"attachment_31037\" aria-describedby=\"caption-attachment-31037\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31037 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240565-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240565-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240565-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240565-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240565-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31037\" class=\"wp-caption-text\">sedano rapa<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Il freno non e&#8217; stata la difficolta&#8217; nella preparazione di questa portata, ma il fatto che non avrei saputo come fosse accettata dai commensali.<\/p>\n<p style=\"text-align: justify;\">Se volete provare anche voi, ecco come ho preparato il &#8220;<strong>sedano rapa al forno<\/strong>&#8220;, mischiando alcune tra le ricette che ho trovato in rete.<\/p>\n<p><strong>Ingredienti &#8211; Sedano rapa al forno<\/strong><\/p>\n<pre>1 sedano rapa\r\nerbe fresche (preferibilmente)\r\n2 cucchiai di olio\r\n2-3 cucchiai di salsa di soia<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preriscaldate il forno a 180gradi, statico.<\/p>\n<p style=\"text-align: justify;\">Iniziate con la preparazione del condimento, cosi&#8217; da avere la possibilita&#8217; di insaporirsi bene.<br \/>\nMischiate salsa di soia, olio, erbe a vostro gusto in una ciotolina, evitate di aggiungere sale, dato che la sapidita&#8217; e&#8217; gia&#8217; fornita dalla soia.<br \/>\nSe volete potete aggiungere anche aglio, cipolla sminuzzata, etc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31035\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240554-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240554-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240554-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240554-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240554-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo aver lavato bene e rimosso la pelle al sedano rapa (fate attenzione perche&#8217; e&#8217; veramente duro), risciacquatele, soprattutto sul fondo dove puo&#8217; esserci ancora del terriccio.<\/p>\n<figure id=\"attachment_31036\" aria-describedby=\"caption-attachment-31036\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31036 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240560-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240560-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240560-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240560-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240560-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31036\" class=\"wp-caption-text\">sedano rapa<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Affettate il sedano ma, attenzione, non tagliate arrivando sino in fondo alla fetta, cosi&#8217; da non separare le fette.<br \/>\nDiciamo di restare a qualche cm dalla base (se di riusciute).<\/p>\n<p style=\"text-align: justify;\">Inserite il condimento tra le fetta, aiutandovi con un cucchiaio od un pennello da cucina, e spennellate nuovamente il tutto.<\/p>\n<p style=\"text-align: justify;\">Avvolgetelo bene in carta di alluminio, posizionatelo sulla teglia (posta al centro) ed infornate per qualche ora, sino a quando non risultera&#8217; tenero.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31034\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240548-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240548-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240548-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240548-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240548-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>A fine cottura, se vi dovesse avanzare del liquido, potete metterlo in un pentolino e farlo restringere, magari con della fecola\/farina\/farina di semi di carruba, cosi&#8217; da accompagnarlo all&#8217; &#8220;arrosto&#8221;, come una salsa.<\/p>\n<figure id=\"attachment_31033\" aria-describedby=\"caption-attachment-31033\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31033 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240534-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240534-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240534-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240534-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619244240534-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-31033\" class=\"wp-caption-text\">Arrosto di sedano rapa<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Il nostro sedano rapa era veramente grande, pesava 1,5 kg.<\/li>\n<li style=\"text-align: justify;\">Vista la sua dimensione, ho pensato di effettuare dei fori anche sulla base, cosi&#8217; da facilitarne la cottura<\/li>\n<li style=\"text-align: justify;\">Dopo 1,5h non era ancora cotto, per verificare lo stato avevo rotto la carta forno, cosi&#8217; lo ho sistemato su una pentolina da forno, coprendolo con nuova carta di alluminio.<\/li>\n<li style=\"text-align: justify;\">Ho alzato la temperatura del forno a 200gradi e proseguito con la cottura per almeno altri 40 minuti.<\/li>\n<li style=\"text-align: justify;\">Come vedete, le tempistiche non sono sempre le stesse. Tutto dipende dal forno, dalla dimensione del sedano rapa e dalla profondita&#8217; dei tagli effettuati.<\/li>\n<li style=\"text-align: justify;\">Sicuramente lasciando intero il sedano, il tempo di cottura sara&#8217; superiore.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Devo ammettere che sono restata piacevolmente sorpresa dal risultato.<br \/>\nStranamente Tobias non ha fatto tante storie, a differenza di Stephan.<br \/>\nPer la prossima volta, perche&#8217; ci sara&#8217; una prossima volta, vista la facilita&#8217; di preparazione e le poche calorie, vorrei posizionarlo direttamente sulla teglia, coprendolo bene con la carta.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono l&#8217;ultima a scoprire le cose,. Le novita&#8217;, alle volte, non fanno proprio per me. Le sorprese? Devo sempre pianificare tutto. Come in questo caso.<\/p>\n","protected":false},"author":2,"featured_media":31033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22,60],"tags":[256,49],"class_list":["post-31026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food","category-secondi_piatti","tag-vegetariano","tag-ww"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=31026"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31026\/revisions"}],"predecessor-version":[{"id":31039,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/31026\/revisions\/31039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/31033"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=31026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=31026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=31026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}