{"id":30831,"date":"2021-12-22T15:14:23","date_gmt":"2021-12-22T14:14:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=30831"},"modified":"2022-01-23T15:30:26","modified_gmt":"2022-01-23T14:30:26","slug":"siria_kibbeh_aperto","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/12\/22\/siria_kibbeh_aperto\/","title":{"rendered":"# 191 &#8211; Repubblica Araba di Siria. Kibbeh aperto\/scomposto (Ottolenghi)"},"content":{"rendered":"<p style=\"text-align: justify;\">La <strong>Siria<\/strong> (in arabo: \u00d8\u00b3\u00d9\u02c6\u00d8\u00b1\u00d9\u0160\u00d8\u00a7\u00e2\u20ac\u017d, S\u00c5\u00abriya), ufficialmente<strong> Repubblica Araba di Siria<\/strong> (in arabo: \u00d8\u00a7\u00d9\u201e\u00d8\u00ac\u00d9\u2026\u00d9\u2021\u00d9\u02c6\u00d8\u00b1\u00d9\u0160\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d8\u00b9\u00d8\u00b1\u00d8\u00a8\u00d9\u0160\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d8\u00b3\u00d9\u02c6\u00d8\u00b1\u00d9\u0160\u00d8\u00a9\u00e2\u20ac\u017d), \u00c3\u00a8 uno Stato del Vicino Oriente, in Asia occidentale.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Confina a nord con la Turchia, a est con l&#8217;Iraq, a sud con la Giordania, a ovest con Israele e Libano. Sempre a ovest si affaccia sul mar Mediterraneo. La Siria \u00c3\u00a8 una repubblica semipresidenziale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30807\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/06\/asia_occidentale-1024x881.jpg\" alt=\"\" width=\"525\" height=\"452\" \/><\/p>\n<p style=\"text-align: justify;\">La capitale \u00c3\u00a8 <em>Damasco<\/em>.<br \/>\nLingua ufficiale \u00c3\u00a8 l&#8217;arabo. Nelle scuole sono insegnati l&#8217;inglese e il francese. Sono parlati da parte delle minoranze anche il curdo, il turco, l&#8217;armeno, l&#8217;aramaico e il circasso, sia cabardo sia in minor numero occidentale. Le lingue degli Assiri sono siriaco e il neoaramaico.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Kibbeh<\/strong> \u00c3\u00a8 una famiglia di piatti a base di carne macinata speziata, cipolle e grano, popolare nella cucina mediorientale.<\/p>\n<p style=\"text-align: justify;\">Nella cucina levantina, il kibbeh viene solitamente preparato pestando il grano bulgur (grano spezzato) insieme alla carne (agnello macinato) in una pasta fine e formandola in palline con pinoli tostati e spezie. Pu\u00c3\u00b2 anche essere a strati e cotto su un vassoio, fritto, grigliato o servito crudo.<\/p>\n<p style=\"text-align: justify;\">Il kibbeh \u00c3\u00a8 considerato un piatto nazionale della Siria e specialmente ad Aleppo, ed \u00c3\u00a8 un piatto popolare in Medio Oriente, ad esempio in Libano, Palestina, Giordania.<br \/>\nSi trovano versioni a Cipro, Egitto, Israele, Iraq, Iran, Golfo Persico, Armenia e Turchia, e tra il popolo assiro. Si trova anche in tutti i paesi dell&#8217;America Latina che hanno ricevuto un numero considerevole di immigrati dal Levante durante la fine del XIX e l&#8217;inizio del XX secolo, e in parti del Nord America.<\/p>\n<p style=\"text-align: justify;\">La parola deriva dall&#8217;arabo classico kubbah (kibbeh in arabo nord-levantino), che significa &#8220;palla&#8221; o &#8220;cupola&#8221;.<\/p>\n<p style=\"text-align: justify;\">La citt\u00c3\u00a0 di Aleppo (Halab) nel nord della Siria \u00c3\u00a8 famosa per avere pi\u00c3\u00b9 di 17 tipi diversi.<br \/>\nQuesti includono kibbeh preparato con sommacco (kibbe sum\u00c4\u0081qiyye), yogurt (kibbe labaniyye), mela cotogna (kibbe safarjaliyye), succo di limone (kibbe \u00e1\u00b8\u00a5\u00c4\u0081m\u00e1\u00b8\u008da), salsa di melograno, salsa di ciliegie e altre variet\u00c3\u00a0, come il &#8220;disco&#8221; kibbeh (kibbe ar\u00c4\u0081\u00e1\u00b9\u00a3 ), il kibbeh &#8220;piatto&#8221; (kibbe bi\u00e1\u00b9\u00a3f\u00c4\u00ab\u00e1\u00b8\u00a5a o kibbe b\u00e1\u00b9\u00a3\u00c4\u201cniyye) e il kibbeh crudo (kibbeh nayyeh).<\/p>\n<p style=\"text-align: justify;\">Ecco perche&#8217; ho pensato di preparare un Kibbeh aperto\/scomposto, prendendo la ricetta da &#8220;<em>Jerusalem<\/em>&#8221; di <em>Ottolenghi<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Kibbeh aperto\/scomposto (Ottolenghi)<\/strong> &#8211; per 6 persone (teglia da 20 cm di diametro)<\/p>\n<pre>125 g di bulgur (o grano spezzato)\r\n90 ml di olio d\u00e2\u20ac\u2122oliva\r\n2 spicchi di aglio schiacciati\r\n2 cipolle medie, tritate finemente\r\n1 peperoncino verde, tritato finemente\r\n350 g macinato di agnello\r\n1 cucchiaino di pimento macinato\r\n1 cucchiaino di cannella in polvere\r\n1 cucchiaino di coriandolo macinato\r\n2 cucchiai di coriandolo fresco tritato grossolanamente\r\n60 g di pinoli\r\n3 cucchiai di prezzemolo tritato grossolanamente\r\n2 cucchiai di farina\r\n50 g di tahini\r\n2 cucchiaini di succo di limone\r\n1 cucchiaino di sumach\r\nsale e pepe nero<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preriscaldate il forno statico a 200gradi.<\/p>\n<p style=\"text-align: justify;\">Mettete il bulgur in una ciotola e copritelo con acqua bollente per il doppio del volume.<br \/>\nCoprite la ciotola e lasciate assorbire il liquido al cereale per 20 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34840\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181747-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181747-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181747-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181747-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181747-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Intanto riscaldate l\u00e2\u20ac\u2122olio in una padella larga e rosolate la cipolla, l\u00e2\u20ac\u2122aglio e il peperoncino.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34843\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181770-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181770-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181770-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181770-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181770-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAggiungete la carne tritata e lasciate cuocere fino a doratura. Inserite le spezie, sale e pepe. Continuate la cottura per 5 minuti.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34842\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181762-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181762-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181762-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181762-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181762-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nTogliete la padella dal fuoco e cospargete con una parte di pinoli e erbe aromatiche fresche.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34841\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181755-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181755-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181755-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181755-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181755-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quando il bulgur \u00c3\u00a8 ammorbidito, scolatelo dall\u00e2\u20ac\u2122acqua in eccesso e aggiungete la farina, 1 cucchiaio di olio, un pizzico di sale e una macinata di pepe.<br \/>\nPremete il bulgur sul fondo di una teglia in modo da ottenere una base omogenea e ben livellata.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34839\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181731-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181731-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181731-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181731-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181731-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nDistribuite sul bulgur la carne macinata e premete di nuovo.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34838\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181724-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181724-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181724-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181724-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181724-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nInfornate in forno statico a 200\u00c2\u00b0C per 20 minuti o fino a quando la carne non \u00c3\u00a8 ben dorata.<\/p>\n<p style=\"text-align: justify;\">Mentre il kibbeh \u00c3\u00a8 in forno, potete preparare il topping di tahini mescolando il tahini con il succo di limone e un pizzico di sale. Potete aggiungere anche un po\u00e2\u20ac\u2122 di acqua, per ottenere una salsa densa ma liquida.<\/p>\n<p style=\"text-align: justify;\">Rimuovete il kibbeh dal forno, distribuite sulla parte superiore la salsa appena preparata con il tahini e cospargete con i pinoli.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34836\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181708-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181708-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181708-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181708-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181708-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<figure id=\"attachment_34835\" aria-describedby=\"caption-attachment-34835\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-34835\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181700-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181700-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181700-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181700-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181700-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-34835\" class=\"wp-caption-text\">Siria. Kibbeh<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34837\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181716-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181716-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181716-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181716-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/ok_1640194181716-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nReinfornate per altri 10 minuti, fino a quando il tahini ha preso un po\u00e2\u20ac\u2122 di colore e i pinoli si sono dorati.<\/p>\n<p style=\"text-align: justify;\">Lasciate che il kibbeh si raffreddi per un paio di minuti oppure fino a temperatura ambiente, cospargendolo con il sumach e dell&#8217;olio d\u00e2\u20ac\u2122oliva.<\/p>\n<figure id=\"attachment_34844\" aria-describedby=\"caption-attachment-34844\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-34844\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/Kibbeh-1024x580.jpeg\" alt=\"\" width=\"525\" height=\"297\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/Kibbeh-1024x580.jpeg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/Kibbeh-150x85.jpeg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/Kibbeh-300x170.jpeg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/12\/Kibbeh-768x435.jpeg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-34844\" class=\"wp-caption-text\">Siria. Kibbeh<\/figcaption><\/figure>\n<p><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Ho sostituito il macinato di agnello con un misto di carne.<\/li>\n<li style=\"text-align: justify;\">Per la mia preparazione ho dimezzato la quantita&#8217;<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La <strong>gastronomia siriana<\/strong> si riferisce agli stili e ai costumi culinari degli abitanti siriani.<br \/>\nInsieme alle gastronomie del Libano, della Giordania e della Palestina formano quella che \u00c3\u00a8 nota come cucina levantina. Si pu\u00c3\u00b2 dire che ha alcune influenze della cucina mediterranea e soprattutto della cucina egiziana. La vicinanza del confine con la Turchia rende alcuni piatti e metodi di preparazione molto simili.<\/p>\n<p style=\"text-align: justify;\">Una delle preparazioni pi\u00c3\u00b9 comuni \u00c3\u00a8 l&#8217;uso della focaccia <strong>pita<\/strong> (khubz), che \u00c3\u00a8 rotonda e viene solitamente ricoperta da uno strato di <strong>hummus<\/strong>, formando cos\u00c3\u00ac una sorta di salsa per intingere. L&#8217;altro piatto tipico siriano \u00c3\u00a8 il <strong>Baba ghanoush<\/strong> a base di melanzane.<\/p>\n<p style=\"text-align: justify;\">Nel campo delle insalate, uno dei piatti pi\u00c3\u00b9 apprezzati \u00c3\u00a8 il <strong>tabbouleh<\/strong> e il <strong>fattoush<\/strong>. Ci sono piatti che includono verdure come cetrioli ripieni (mahshe), dolmas, kebab, kibbeh, kibbeh nayyeh, mujaddara e shawarma e snack shanklish.<br \/>\nI siriani propongono prima dei piatti principali una sorta di tapas in quello che viene chiamato meze (tipico della cucina mediterranea orientale). Zataar, carne macinata e formaggio manakish sono popolari come antipasto.<br \/>\nI siriani sono famosi per i loro formaggi siriani.<br \/>\nUna bevanda molto popolare \u00c3\u00a8 l&#8217;<strong>arak<\/strong>.<br \/>\nUno dei dolci pi\u00c3\u00b9 popolari \u00c3\u00a8 il <strong>baklava<\/strong>, che \u00c3\u00a8 fatto con pasta fillo a volte farcita con noci tritate o pistacchi, il tutto con miele.<\/p>\n<p>astamtae biwujbatik<br \/>\n\u00d8\u00a7\u00d8\u00b3\u00d8\u00aa\u00d9\u2026\u00d8\u00aa\u00d8\u00b9 \u00d8\u00a8\u00d9\u02c6\u00d8\u00ac\u00d8\u00a8\u00d8\u00aa\u00d9\u0192<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Siria (in arabo: \u00d8\u00b3\u00d9\u02c6\u00d8\u00b1\u00d9\u0160\u00d8\u00a7\u00e2\u20ac\u017d, S\u00c5\u00abriya), ufficialmente Repubblica Araba di Siria (in arabo: \u00d8\u00a7\u00d9\u201e\u00d8\u00ac\u00d9\u2026\u00d9\u2021\u00d9\u02c6\u00d8\u00b1\u00d9\u0160\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d8\u00b9\u00d8\u00b1\u00d8\u00a8\u00d9\u0160\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d8\u00b3\u00d9\u02c6\u00d8\u00b1\u00d9\u0160\u00d8\u00a9\u00e2\u20ac\u017d), \u00c3\u00a8 uno Stato del Vicino Oriente, in Asia occidentale.<\/p>\n","protected":false},"author":2,"featured_media":34830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,64,22,138,51,60],"tags":[176,234,88,253],"class_list":["post-30831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-carne","category-food","category-piatti_unici","category-primi_piatti","category-secondi_piatti","tag-176","tag-asia_occidentale","tag-frutta_secca","tag-ottolenghi"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=30831"}],"version-history":[{"count":13,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30831\/revisions"}],"predecessor-version":[{"id":34848,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30831\/revisions\/34848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/34830"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=30831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=30831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=30831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}