{"id":30668,"date":"2021-11-04T15:00:32","date_gmt":"2021-11-04T14:00:32","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=30668"},"modified":"2022-01-23T16:30:31","modified_gmt":"2022-01-23T15:30:31","slug":"turkmenistan_kelem-corbasy","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/11\/04\/turkmenistan_kelem-corbasy\/","title":{"rendered":"# 182 &#8211; Repubblica del Turkmenistan. Kelem \u00c3\u2021orbasy (Zuppa di Cavolo Bianco)"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>Turkmenistan<\/strong>, ufficialmente <strong>Repubblica del Turkmenistan<\/strong>, a volte italianizzato in <strong>Turcomannia<\/strong>, \u00c3\u00a8 una repubblica presidenziale (de facto dittatura totalitaria monopartitica) situata nell&#8217;Asia Centrale, con <em>A\u00c5\u0178gabat<\/em> come capitale.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Confina con l&#8217;Iran, l&#8217;Afghanistan, l&#8217;Uzbekistan e il Kazakistan e si affaccia sul Mar Caspio. \u00c3\u02c6 la seconda potenza economica dell&#8217;Asia Centrale (dopo il Kazakistan) grazie ai suoi giacimenti ricchi di gas naturale e alla coltivazione del cotone.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30669\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/asia_centrale-e1618583107750.jpg\" alt=\"\" width=\"420\" height=\"266\" \/><\/p>\n<p style=\"text-align: justify;\">La presenza dell&#8217;industria pesante \u00c3\u00a8 minima in Turkmenistan, pertanto la qualit\u00c3\u00a0 dell&#8217;aria \u00c3\u00a8 decisamente buona; fa eccezione A\u00c5\u0178gabat, avvolta da un velo quasi permanente di smog.<\/p>\n<p style=\"text-align: justify;\">La lingua ufficiale \u00c3\u00a8 il turkmeno (lingua altaica &#8220;turco meridionale&#8221;), parlato come unica lingua dal 72% degli abitanti, mentre il russo \u00c3\u00a8 riconosciuto nella costituzione come lingua per la comunicazione tra diversi gruppi etnici.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Non ho riflettuto molto sulla preparazione del piatto di questa Nazione.<br \/>\nDiciamo che e&#8217; uscito cosi&#8217;, velocemente e senza pensieri&#8230; rendendo gradita una fredda serata autunnale.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"https:\/\/turkmenkitchen.com\/tm\/2012\/06\/12\/kelem-corbasy\/\">Zuppa Di Cavolo Bianco (Kelem \u00c3\u2021orbasy) <\/a><\/strong><\/em>&#8211; 3 persone<\/p>\n<pre>3 cucchiai di olio vegetale\r\n4 foglie di cavolo bianco, sminuzzate\r\n1 carota piccola, a cubetti\r\n1 cipolla piccola, tritata finemente\r\n1\/2 costa di sedano, tritata\r\n1 patata piccola, a cubetti\r\n1 dado da brodo vegetale\r\n2 foglie di alloro\r\n1 litro d'acqua\r\n1 cucchiaino di sale\r\n1 pizzico di peperoncino rosso macinato\r\n1 cucchiaio di riso\r\n1 spicchio d'aglio, tritato finemente\r\n1 cucchiaino di succo di limone<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Scaldate l&#8217;olio in una pentola capiente.<br \/>\nAggiungete il cavolo, la carota e la cipolla. Cuocete a fuoco vivo, mescolando continuamente, per 1-2 minuti.<br \/>\nAggiungete il sedano, la patata, il dado da brodo, le foglie di alloro e l&#8217;acqua.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34031\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089408-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089408-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089408-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089408-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089408-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34032\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089400-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089400-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089400-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089400-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089400-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quando la zuppa inizia a bollire, aggiungete il sale e il pepe rosso macinato, quindi riducete il fuoco a medio e coprite. Dopo 10-12 minuti, aggiungete il riso e l&#8217;aglio.<\/p>\n<p style=\"text-align: justify;\">Cuocete per altri 7-8 minuti, aggiungete il succo di limone e spegnete il fuoco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-34033\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089389-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089389-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089389-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089389-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/1636045089389-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Versate la zuppa nelle ciotole, guarnite con una cucchiaiata di yogurt e condire con pepe nero (facoltativo).<\/p>\n<figure id=\"attachment_34035\" aria-describedby=\"caption-attachment-34035\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-34035\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/Turkmenistan-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/Turkmenistan-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/Turkmenistan-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/Turkmenistan-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/11\/Turkmenistan-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-34035\" class=\"wp-caption-text\">Turkmenistan. Kelem \u00c3\u2021orbasy (Zuppa di Cavolo Bianco)<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La quantita&#8217; di riso richiesta mi e&#8217; parsa esigua, cosi&#8217; ho inserito 3 cucchiai.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La gastronomia <strong>turkmena<\/strong> si inserisce perfettamente nel suo contesto geografico e presenta pertanto caratteristiche tipiche della regione centroasiatica.<\/p>\n<p style=\"text-align: justify;\">Il pasto \u00c3\u00a8 costituito generalmente da due portate principali e, secondo la tradizione, dovrebbe essere consumato sedendo sul pavimento e servendosi da bassi tavoli senza l&#8217;impiego di posate. Oggi i costumi si sono in gran parte modificati e le modalit\u00c3\u00a0 con cui vengono consumati i pasti sono pressocch\u00c3\u00a9 analoghe a quelle occidentali.<br \/>\nIn generale gli ingredienti principali della gastronomia turkmena sono rappresentati dal riso, dalle verdure e dalla carne ovina.<br \/>\nIl piatto nazionale del paese, diffuso anche in alcuni stati limitrofi, \u00c3\u00a8 il <strong>plov<\/strong>, una preparazione a base di riso cotto con lo zafferano e condito con pezzetti di carne di agnello e carote.<br \/>\nLa pietanza che pi\u00c3\u00b9 spesso si accompagna al plov \u00c3\u00a8 la <strong>\u00c5\u00a1urba<\/strong>, una minestra a base di carne di agnello cotta con i legumi particolarmente adatta ai rigori della stagione invernale.<br \/>\nIl pane tradizionale \u00c3\u00a8 il <strong>\u00c4\u008dorek<\/strong>, costituito da focacce di grano cotte sul momento all&#8217;interno di particolari forni a legna e servite calde.<br \/>\nLe due portate principali sono solitamente seguite da una portata di frutta fresca, tra le quali sono da assaggiare l&#8217;uva e il melone, particolarmente rinomato per il suo aroma.<br \/>\nLa bevanda pi\u00c3\u00b9 diffusa \u00c3\u00a8 il t\u00c3\u00a8 verde, detto <strong>gek<\/strong>, servito sia durante i pasti che nel corso della giornata, ma tra le bevande va ancora ricordato lo shubat, un liquido denso ottenuto dalla fermentazione del latte di cammella.<\/p>\n<p>&nbsp;<\/p>\n<p>Nahary\u00c5\u02c6yzdan lezzet aly\u00c5\u02c6<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Turkmenistan, ufficialmente Repubblica del Turkmenistan, a volte italianizzato in Turcomannia, \u00c3\u00a8 una repubblica presidenziale (de facto dittatura totalitaria monopartitica) situata nell&#8217;Asia Centrale, con A\u00c5\u0178gabat come capitale.<\/p>\n","protected":false},"author":2,"featured_media":34029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,22,51,67,57],"tags":[176,231],"class_list":["post-30668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-food","category-primi_piatti","category-riso_risotti","category-zuppa","tag-176","tag-asia_centrale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=30668"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30668\/revisions"}],"predecessor-version":[{"id":34036,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30668\/revisions\/34036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/34029"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=30668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=30668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=30668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}