{"id":30208,"date":"2021-04-19T14:30:33","date_gmt":"2021-04-19T12:30:33","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=30208"},"modified":"2022-01-22T17:38:06","modified_gmt":"2022-01-22T16:38:06","slug":"kuwait_murabiyan","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/04\/19\/kuwait_murabiyan\/","title":{"rendered":"# 158 &#8211; Stato del Kuwait. Murabiyan"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>Kuwait<\/strong> (pron. [ku\u00cb\u02c6wait]), ufficialmente <strong>Stato del Kuwait<\/strong>, \u00c3\u00a8 un emirato sovrano, situato nell&#8217;Asia sud-occidentale (Medio Oriente), in un&#8217;area particolarmente ricca di petrolio. Lo Stato si affaccia sul golfo Persico e confina con l&#8217;Arabia Saudita a sud e con l&#8217;Iraq a nord.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Capitale di questo emirato e&#8217; <em>Al Kuwait<\/em>.<br \/>\nIl nome \u00c3\u00a8 il diminutivo di una parola araba che significa piccola fortezza (lungo il litorale). L&#8217;antico nome della regione era Qurayn.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30807\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/06\/asia_occidentale-1024x881.jpg\" alt=\"\" width=\"525\" height=\"452\" \/><\/p>\n<p style=\"text-align: justify;\">La lingua ufficiale \u00c3\u00a8 l&#8217;arabo, comunque l&#8217;inglese \u00c3\u00a8 generalmente studiato e conosciuto. Alcuni immigrati parlano le loro lingue d&#8217;origine.<\/p>\n<p style=\"text-align: justify;\">Il <strong>Murabiyan<\/strong> e&#8217; un altro modo per la preparazione del riso, ma questa volta e&#8217; pieno di gamberetti: sia nel riso stesso che nella guarnizione!<\/p>\n<p>Tra le tante ricette a disposizione, ho deciso di seguirne una vista su YouTube.<\/p>\n<p><strong>Ingredienti &#8211; Murabiyan<\/strong><\/p>\n<pre><strong>Per la guarnizione <\/strong>\r\n2 cipolle\r\n2 pomodori\r\naneto fresco (abbondante)\r\ncoriandolo fresco (abbondante)\r\ngamberi\r\nsucco di lime\r\nsale\r\npepe\r\ncurcuma in polvere\r\n1 cucchiaio di olio\r\nchili\r\ncurry\r\ncumino\r\n\r\n<strong>Per il riso:<\/strong>\r\n2 cucchiai di olio\r\n1 cipolla\r\ncannella\r\nalloro\r\nchiodi di garofano\r\ncoriandolo\r\naglio\r\nsale\r\naneto\r\ncurcuma\r\ncurry\r\ncumino\r\nriso\r\nacqua<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tritate 2 cipolle.<br \/>\nAffettate a dadini 2 pomodori.<br \/>\nTagliate l&#8217;aneto ed il coriandolo.<\/p>\n<p style=\"text-align: justify;\">Marinate i gamberi con il succo del limone, pepe, curcuma in polvere e sale.<\/p>\n<p style=\"text-align: justify;\">Scaldate l&#8217;olio in un a padella, aggiungete la cipolla e cuocete fino a farla dorare.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30937\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680606-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680606-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680606-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680606-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680606-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Inserite il chili facendo ben insaporire, poi il pomodoro, il curry, la curcuma, il cumino ed il pepe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30938\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680601-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680601-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680601-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680601-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680601-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Il composto sara&#8217; e sembrera&#8217; molto asciutto, ma va bene cosi&#8217;.<\/p>\n<p style=\"text-align: justify;\">Aggiungete i gamberetti, continuando a cuocere per 2\/3 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30939\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680595-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680595-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680595-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680595-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680595-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">A questo punto inserite le erbe (aneto e coriandolo), mescolando ancora per circa 3 minuti.<br \/>\nMettete da parte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30940\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680590-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680590-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680590-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680590-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680590-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30941\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680584-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680584-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680584-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680584-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680584-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Per il riso.<\/strong><br \/>\nInserite 2 cucchiai di olio in una padella ed aggiungete una cipolla, fino a farla dorare.<br \/>\nAggiungete cannella, alloro, chiodi di garofano, coriandolo, aglio, sale, aneto, curcuma, curry e cumino.<br \/>\nMescolate bene per miscelare le spezie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30942\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680579-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680579-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680579-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680579-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680579-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la meta&#8217; del composto di gamberi precedentemente preparato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30943\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680573-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680573-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680573-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680573-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680573-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Inserite il riso (meglio se con chicchi piccoli) lavato precedentemente.<br \/>\nPoi coprite di acqua e continuate la cottura, portando ad ebollizione&#8230;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30944\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680568-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680568-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680568-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680568-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680568-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">sino a quando l&#8217;acqua non sara&#8217; stata assorbita e ridotta della meta&#8217;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30945\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680562-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680562-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680562-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680562-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680562-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">A questo punto, sempre senza mescolare, coprite con coperchio, abbassate e portate avanti la cottura per altri 15\/20 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30946\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680557-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680557-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680557-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680557-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680557-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Versate la miscela di gamberetti\/riso su un piatto da portata, disponete sopra la guarnizione con gli ulteriori gamberetti, tenuta in caldo.<\/p>\n<p style=\"text-align: justify;\">Decorate con erbe fresche..<\/p>\n<figure id=\"attachment_30947\" aria-describedby=\"caption-attachment-30947\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30947\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680551-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680551-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680551-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680551-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680551-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-30947\" class=\"wp-caption-text\">Kuwait. Murabiyan<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Per il riso ne ho pesato 180gr<\/li>\n<li style=\"text-align: justify;\">Ho utilizzato poco piu&#8217; del doppio di acqua rispetto al volume del riso.<\/li>\n<\/ul>\n<figure id=\"attachment_30948\" aria-describedby=\"caption-attachment-30948\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30948\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680546-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680546-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680546-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680546-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618835680546-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-30948\" class=\"wp-caption-text\">Kuwait. Murabiyan<\/figcaption><\/figure>\n<hr \/>\n<p style=\"text-align: justify;\">La cucina <strong>kuwaitiana<\/strong> \u00c3\u00a8 la cucina tradizionale araba locale del Kuwait.<\/p>\n<p style=\"text-align: justify;\">Fa parte della cucina dell&#8217;Arabia Orientale e condivide somiglianze con cucine dei paesi vicini, come la cucina dell&#8217;Arabia Saudita, nonch\u00c3\u00a9 influenze di diverse cucine mediorientali e asiatiche.<br \/>\nUn piatto importante nella cucina kuwaitiana sono i machboos, un piatto a base di riso solitamente preparato con riso basmati condito con spezie e pollo o montone.<\/p>\n<p style=\"text-align: justify;\">Il pesce \u00c3\u00a8 una parte significativa della dieta kuwaitiana. I preferiti locali sono l&#8217;hamour (cernia), che viene tipicamente servito alla griglia, fritto o con riso biryani a causa della sua consistenza e gusto, safi (pesce coniglio), muggine e sobaity (orata).<\/p>\n<p style=\"text-align: justify;\">La focaccia tradizionale del Kuwait si chiama khubz iraniano, una grande focaccia cotta in un forno speciale e spesso \u00c3\u00a8 condita con semi di sesamo.<\/p>\n<p style=\"text-align: justify;\">Tra i piatti piu&#8217; tradizionali troviamo<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\"><strong>Biryani<\/strong> (arabo: \u00d8\u00a8\u00d8\u00b1\u00d9\u0160\u00d8\u00a7\u00d9\u2020\u00d9\u0160) &#8211; piatto molto comune, che consiste in riso molto condito cotto con pollo o agnello. Originario del sub-continente indiano.<\/li>\n<li style=\"text-align: justify;\"><strong>Gabout<\/strong> (arabo: \u00d9\u201a\u00d8\u00a8\u00d9\u02c6\u00d8\u00b7) &#8211; gnocchi di farina ripieni in uno stufato di carne denso.<\/li>\n<li style=\"text-align: justify;\"><strong>Lepre<\/strong> (in arabo: \u00d9\u2021\u00d8\u00b1\u00d9\u0160\u00d8\u00b3) &#8211; grano cotto con carne e poi schiacciato, solitamente condito con zucchero alla cannella.<\/li>\n<li style=\"text-align: justify;\"><strong>Jireesh<\/strong> (Yireesh) (arabo: \u00d8\u00ac\u00d8\u00b1\u00d9\u0160\u00d8\u00b4) &#8211; purea di farro cotto con pollo o agnello, pomodori e alcune spezie.<\/li>\n<li style=\"text-align: justify;\"><strong>Machboos<\/strong> (arabo: \u00d9\u2026\u00d8\u00ac\u00d8\u00a8\u00d9\u02c6\u00d8\u00b3) &#8211; piatto a base di montone, pollo o pesce accompagnato su riso profumato che \u00c3\u00a8 stato cotto in brodo ben speziato di pollo \/ montone. Questo e&#8217; il piatto considerato nazionale.<\/li>\n<li style=\"text-align: justify;\"><strong>Mashkhool<\/strong> (arabo: \u00d9\u2026\u00d8\u00b4\u00d8\u00ae\u00d9\u02c6\u00d9\u201e) &#8211; riso bianco e sul fondo della pentola ci sono anelli di cipolla con curcuma e pepe nero, a volte si aggiungono anche patate e melanzane sul fondo della pentola.<\/li>\n<li style=\"text-align: justify;\"><strong>Marabyan<\/strong> (arabo: \u00d9\u2026\u00d8\u00b1\u00d8\u00a8\u00d9\u0160\u00d9\u2020) &#8211; riso cucinato con gamberetti freschi o secchi.<\/li>\n<li style=\"text-align: justify;\"><strong>Maglooba<\/strong> (arabo: \u00d9\u2026\u00d9\u201a\u00d9\u201e\u00d9\u02c6\u00d8\u00a8\u00d8\u00a9) &#8211; riso cotto con carne, patate e melanzane.<\/li>\n<li style=\"text-align: justify;\"><strong>Margoog<\/strong> (arabo: \u00d9\u2026\u00d8\u00b1\u00d9\u201a\u00d9\u02c6\u00d9\u201a) &#8211; stufato di verdure, di solito contenente zucca e melanzane, cotto con pezzi sottili di pasta stesa.<\/li>\n<li style=\"text-align: justify;\"><strong>Mumawwash<\/strong> (arabo: \u00d9\u2026\u00d9\u2026\u00d9\u02c6\u00d8\u00b4) &#8211; riso cotto con lenticchie verdi e pu\u00c3\u00b2 essere guarnito con gamberetti secchi.<\/li>\n<li style=\"text-align: justify;\"><strong>Muaddas<\/strong> (arabo: \u00d9\u2026\u00d8\u00b9\u00d8\u00af\u00d8\u00b3) &#8211; riso cotto con lenticchie rosse e pu\u00c3\u00b2 essere guarnito con gamberetti secchi.<\/li>\n<li style=\"text-align: justify;\"><strong>Mutabbaq<\/strong> samak (arabo: \u00d9\u2026\u00d8\u00b7\u00d8\u00a8\u00d9\u201a \u00d8\u00b3\u00d9\u2026\u00d9\u0192) &#8211; pesce servito su riso. Il riso viene cotto in un brodo di pesce ben speziato.<\/li>\n<li style=\"text-align: justify;\"><strong>Quzi<\/strong> (arabo: \u00d9\u201a\u00d9\u02c6\u00d8\u00b2\u00d9\u0160) &#8211; agnello arrosto ripieno di riso, carne, uova e altri ingredienti.<\/li>\n<li style=\"text-align: justify;\"><strong>Gers Ogaily<\/strong> &#8211; Conosciuta anche come &#8220;torta profumata&#8221; Gers Ogaily \u00c3\u00a8 un popolare dolce tradizionale noto per il suo ricco colore giallo e aromi aromatici di zafferano, cardamomo, acqua di rose e semi di sesamo tostati utilizzati nella miscela.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\u00d8\u00a3\u00d8\u00aa\u00d9\u2026\u00d9\u2020\u00d9\u2030 \u00d9\u201e\u00d9\u0192 \u00d9\u02c6\u00d8\u00ac\u00d8\u00a8\u00d8\u00a9 \u00d8\u00b4\u00d9\u2021\u00d9\u0160\u00d8\u00a9<br \/>\n\u00e2\u20ac\u02dcatamanaa lak wajabat shahia<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n<pre><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Il Kuwait (pron. [ku\u00cb\u02c6wait]), ufficialmente Stato del Kuwait, \u00c3\u00a8 un emirato sovrano, situato nell&#8217;Asia sud-occidentale (Medio Oriente), in un&#8217;area particolarmente ricca di petrolio. Lo Stato si affaccia sul golfo Persico e confina con l&#8217;Arabia Saudita a sud e con l&#8217;Iraq a nord.<\/p>\n","protected":false},"author":2,"featured_media":30211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,22,77,138,51,67],"tags":[176,234],"class_list":["post-30208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-food","category-pesce","category-piatti_unici","category-primi_piatti","category-riso_risotti","tag-176","tag-asia_occidentale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=30208"}],"version-history":[{"count":12,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30208\/revisions"}],"predecessor-version":[{"id":30950,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30208\/revisions\/30950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/30211"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=30208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=30208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=30208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}