{"id":30199,"date":"2021-05-02T14:06:03","date_gmt":"2021-05-02T12:06:03","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=30199"},"modified":"2022-01-23T16:40:53","modified_gmt":"2022-01-23T15:40:53","slug":"vanuatu_kumala_salad","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/05\/02\/vanuatu_kumala_salad\/","title":{"rendered":"# 162 &#8211; Repubblica di Vanuatu. Kumala Salad"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Vanuatu<\/strong> (AFI: \/vanu\u00cb\u02c6atu\/), il cui nome ufficiale \u00c3\u00a8 <strong>Repubblica di Vanuatu<\/strong> (in bislama: Ripablik blong Vanuatu, in inglese: Republic of Vanuatu, in francese: R\u00c3\u00a9publique de Vanuatu) \u00c3\u00a8 uno Stato insulare situato nell&#8217;Oceano Pacifico meridionale.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">L&#8217;arcipelago, che ha origine vulcanica, si trova circa a 1750 km a est dell&#8217;Australia, 500 km a nord est della Nuova Caledonia, a ovest delle Figi e a sud delle Isole Salomone.<br \/>\nLe isole che lo compongono furono denominate Nuove Ebridi durante il periodo coloniale.<\/p>\n<p style=\"text-align: justify;\">Vanuatu \u00c3\u00a8 una repubblica parlamentare, con capitale <em>Port Vila<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30388\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/australasia-e1618405900634.png\" alt=\"\" width=\"500\" height=\"375\" \/><\/p>\n<p style=\"text-align: justify;\">Le lingue ufficiali sono il bislama (vanuatuano &#8211; una lingua creola che si \u00c3\u00a8 evoluta a partire dall&#8217;inglese), l&#8217;inglese e il francese. Nell&#8217;arcipelago si parlano inoltre 113 lingue indigene; uno di questi \u00c3\u00a8 la lingua araki, parlata solo da 8 persone.<\/p>\n<p style=\"text-align: justify;\">Le prime tracce di presenza umana sulle isole risalgono al 4000 a.C. mentre quelle di insediamenti stabili risalgono al 1300 a.C. quando popolazioni melanesiane appartenenti alla cultura Lapita incominciarono a colonizzare le isole settentrionali muovendosi progressivamente verso ovest.<\/p>\n<p style=\"text-align: justify;\">L&#8217;arcipelago \u00c3\u00a8 situato in corrispondenza della Placca delle Nuove Ebridi, ed \u00c3\u00a8 soggetto a frequenti fenomeni sismici che talvolta provocano anche degli tsunami.<\/p>\n<p style=\"text-align: justify;\">A Vanuatu crescono circa 20 specie di palme, di cui 14 endemiche.<br \/>\nLe orchidee ornano gli alberi di molte zone; se ne contano 158 specie. Meno gradevoli sono le erbe infestanti introdotte, come la lantana e la diffusa micania.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Essendo un&#8217;isola ho pensato di preparare del pesce alla griglia, accompagnandolo ad una insalata particolare ma decisamente facile nella sua preparazione, trovata per caso tra le ricette di Expo Milano 2015<\/p>\n<p><strong>Ingredienti &#8211; <em><a href=\"https:\/\/www.deabyday.tv\/cucina-e-ricette\/contorni\/guide\/11760\/La-Kumala-Salad--una-ricetta-veloce-per-sentire-le-onde-dell-Oceano-Pacifico.html\">Kumala Salad<\/a><\/em><\/strong><\/p>\n<pre>6 patate dolci cotte\r\n1 cipolla grande\r\n1 spicchio di aglio\r\n1 cucchiaino di zenzero tritato\r\n3 uova sode (*)\r\n1 tazza di latte di cocco  (*)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tagliate le uova sode in spicchi.<br \/>\nTagliate le patate dolci a cubetti.<br \/>\nTritate le cipolle e fatele rosolare in un po\u00e2\u20ac\u2122 di olio di semi insieme all\u00e2\u20ac\u2122aglio e allo zenzero<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-31502\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555176-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555176-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555176-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555176-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555176-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Togliete il soffritto dal fuoco e unite il latte di cocco.<br \/>\nMescolare il tutto.<\/p>\n<p style=\"text-align: justify;\">Aggiungete al composto le patate e le uova.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31503 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555164-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555164-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555164-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555164-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/05\/ok_1619958555164-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Se volete alleggerire la preparazione, al posto del latte di cocco potete utilizzare un mix di mayonese e yoghurt.<\/li>\n<li style=\"text-align: justify;\">Altro suggerimento per l&#8217;alleggerimento e&#8217; quello di sostituire le uova con dei quadratini di mela.<\/li>\n<li style=\"text-align: justify;\">Potete insaporire la &#8220;crema&#8221; con zeste di arancio ed un pizzico di curry in polvere<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La gastronomia \u00c3\u00a8 un mix perfetto di molte cucine diverse come quella tradizionale del Pacifico, quella asiatica e quella europea.<br \/>\nTra i pasti tradizionali troviamo il granchio al cocco, solitamente servito con aglio, peperoncino, curry o salse al cocco. Alcune altre specialit\u00c3\u00a0 locali sono le lumache fatte , il natou, la rousette (volpe volante o un pipistrello della frutta), ostriche di mangrovie e nems.<\/p>\n<p style=\"text-align: justify;\">Il piatto nazionale di Vanuatu e&#8217; il <strong>Laplap<\/strong> (a volte scritto lap lap).<br \/>\nQuesto si prepara grattugiando le radici dell&#8217;albero del pane, delle banane, del taro o dell&#8217;igname, fino ad ottenere una pasta vegetale. Questa viene poi avvolta in foglie di banana e cotta con crema di cocco in un forno sotterraneo di pietra. All&#8217;impasto si possono aggiungere carni come maiale, manzo, pollo o volpe volante.<\/p>\n<p style=\"text-align: justify;\">Papaya, ananas, mango, platano e patate dolci sono abbondanti per gran parte dell&#8217;anno.<br \/>\nIl latte e la panna di cocco sono usati per insaporire molti piatti.<\/p>\n<p>&nbsp;<\/p>\n<p>Enjoy your meal!<br \/>\nBon appetite!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vanuatu (AFI: \/vanu\u00cb\u02c6atu\/), il cui nome ufficiale \u00c3\u00a8 Repubblica di Vanuatu (in bislama: Ripablik blong Vanuatu, in inglese: Republic of Vanuatu, in francese: R\u00c3\u00a9publique de Vanuatu) \u00c3\u00a8 uno Stato insulare situato nell&#8217;Oceano Pacifico meridionale.<\/p>\n","protected":false},"author":2,"featured_media":30201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22,237,61],"tags":[176,107,238,183],"class_list":["post-30199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food","category-oceania","category-uova-formaggio","tag-176","tag-frutta","tag-melanesia","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=30199"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30199\/revisions"}],"predecessor-version":[{"id":31504,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/30199\/revisions\/31504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/30201"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=30199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=30199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=30199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}