{"id":29604,"date":"2021-03-29T14:01:37","date_gmt":"2021-03-29T12:01:37","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=29604"},"modified":"2022-01-23T15:44:51","modified_gmt":"2022-01-23T14:44:51","slug":"spagna_ensaimada-de-mallorca","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/03\/29\/spagna_ensaimada-de-mallorca\/","title":{"rendered":"# 151 &#8211; Regno di Spagna. Ensa\u00c3\u00afmada de Mallorca Llisa"},"content":{"rendered":"<p style=\"text-align: justify;\">La <strong>Spagna<\/strong>, ufficialmente<strong> Regno di Spagna<\/strong> (in spagnolo e galiziano: Reino de Espa\u00c3\u00b1a, in basco: Espainiako Erresuma, in dialetto aranese: Regne d&#8217;Espanha, in catalano e valenciano: Regne d&#8217;Espanya), \u00c3\u00a8 uno Stato membro dell&#8217;Unione europea (dal 1\u00c2\u00ba gennaio 1986) e della NATO (dal 1982).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Organizzata sotto forma di monarchia parlamentare, la Spagna \u00c3\u00a8 situata nell&#8217;Europa sud-occidentale.<br \/>\nDal 1561, eccetto che per un breve periodo tra il 1601 e il 1606, la capitale \u00c3\u00a8 <em>Madrid<\/em>.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\nLingua ufficiale in tutto lo stato \u00c3\u00a8 il castigliano o spagnolo. In alcune comunit\u00c3\u00a0 autonome rivestono carattere di coufficialit\u00c3\u00a0 con il castigliano il catalano-valenciano (Catalogna, Isole Baleari e Comunit\u00c3\u00a0 Valenzana) il galiziano (Galizia) e il basco (Paesi Baschi e Navarra).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L&#8217;<strong>ensaimada<\/strong> \u00c3\u00a8 un dolce tipico dell&#8217;isola di Maiorca.<br \/>\nA partire dal 1996 \u00c3\u00a8 stata riconosciuta come prodotto Indicazione geografica protetta &#8220;<strong>Ensa\u00c3\u00afmada de Mallorca<\/strong>&#8220;; la fama del dolce ha chiaramente varcato i confini dell&#8217;isola, dato che \u00c3\u00a8 tra i pi\u00c3\u00b9 famosi piatti maiorchini, offerto in tutte le pasticcerie del luogo in una scatola ottagonale.<\/p>\n<p style=\"text-align: justify;\">Gli ingredienti sono: farina di frumento, acqua, uova, zucchero, lievito e, in aggiunta, strutto di maiale (in catalano sa\u00c3\u00afm, da cui il dolce prende il nome).<br \/>\nLa sua maggiore prerogativa consiste nella sua forma a spirale, che si ripete sia nella struttura interna che in quella esterna. Il suo impasto \u00c3\u00a8 costituito da strati, similmente a quanto accade nella pasta sfoglia.<br \/>\n\u00c3\u02c6 un classico esempio di dolce a lievitazione lenta.<\/p>\n<figure id=\"attachment_29745\" aria-describedby=\"caption-attachment-29745\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29745\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/emsaimada.jpg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/emsaimada.jpg 960w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/emsaimada-150x100.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/emsaimada-300x200.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/emsaimada-768x512.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-29745\" class=\"wp-caption-text\">Foto da Internet. Emsaimada<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Una volta preparata la pasta, la si lascia lievitare, dopodich\u00c3\u00a9 si stende facendo uno strato molto fine che va cosparso col grasso di maiale, si arrotola e si dispone il rotolo in spirale e infine si lascia levitare una seconda volta. Data la finezza della sfoglia, assai elastica, spesso oggi si consiglia di usare una farina forte come la manitoba.<\/p>\n<p style=\"text-align: justify;\">Si pu\u00c3\u00b2 cospargere di zucchero in polvere, o eventualmente riempire.<br \/>\nIl riempimento tradizionale \u00c3\u00a8 fatto di cabell d&#8217;\u00c3\u00a0ngel (una sorta di marmellata di zucca), ma sono in uso i ripieni pi\u00c3\u00b9 svariati. Ad esempio, in Argentina si pu\u00c3\u00b2 trovare ripiena di dulce de leche.<\/p>\n<p style=\"text-align: justify;\">Durante il periodo di Carnevale si \u00c3\u00a8 soliti preparare l&#8217;ensaimada con sobrassada dolce, e cospargerla di dolce di zucca.<\/p>\n<p style=\"text-align: justify;\">\u00c3\u02c6 possibile che derivi da un dolce ebraico (che ovviamente non prevedeva l&#8217;uso di grasso di maiale).<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211;<em><strong><a href=\"https:\/\/www.gazzettadelgusto.it\/cibo-e-storia\/ensaimada-de-mallorca-ricetta-storia\/\"> Ensa\u00c3\u00afmada de Mallorca Llisa <\/a><\/strong><\/em><\/p>\n<pre>520gr farina forte (farina Manitoba) (*)\r\n80gr zucchero\r\n125ml latte\r\n125ml acqua\r\n150gr strutto\r\n2 uova\r\n25gr lievito di birra fresco\r\n2 cucchiai olio di girasole\r\n1 cucchiaio miele\r\n1 cucchiaio vaniglia (essenza)\r\n1 cucchiaino sale\r\nzucchero a velo<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola preparate un lievitino unendo l&#8217;acqua, il lievito di birra sbriciolato e il miele.<br \/>\nMescolate bene con un cucchiaio di legno fino a che il lievito e il miele si sciolgano completamente nell&#8217;acqua.<br \/>\nUnite un cucchiaio di farina setacciata e mescolate avendo cura che non si formino grumi.<br \/>\nCoprite con pellicola per alimenti e lasciate riposare in un luogo asciutto e tiepido per circa 10 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29736\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796848-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796848-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796848-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796848-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796848-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Setacciate la farina insieme al sale e tenete da parte.<br \/>\nIn una ciotola capiente unite le uova, met\u00c3\u00a0 del latte, lo zucchero, l&#8217;olio, l&#8217;essenza di vaniglia e met\u00c3\u00a0 della farina setacciata.<br \/>\nMescolate per un minuto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29738\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796854-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796854-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796854-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796854-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796854-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete il lievitino preparato in precedenza e continuate a mescolare per circa 2 minuti.<br \/>\nUnite adagio il latte e la farina rimasta. Dovete ottenere un impasto molto umido e morbido (impastando a mano impiegherete circa 10-12 minuti, con una planetaria i tempi si riducono di circa la met\u00c3\u00a0).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29737\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796843-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796843-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796843-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796843-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796843-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Coprite l&#8217;impasto e lasciatelo lievitare per un&#8217;ora in un posto asciutto e tiepido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29735\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796837-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796837-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796837-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796837-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796837-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Trascorso il tempo necessario, dividete l&#8217;impasto in 12 panetti e trasferiteli su un piano di lavoro imburrato, lasciandoli leggermente distanziati l&#8217;uno dall&#8217;altro.<br \/>\nCopriteli con la pellicola e lasciate lievitare fino che raddoppiano di volume.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29733\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796831-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796831-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796831-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796831-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796831-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29734\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796825-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796825-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796825-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796825-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796825-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lasciate ammorbidire lo strutto a temperatura ambiente per qualche minuto e sbattetelo energicamente con una forchetta fino a ottenere una consistenza cremosa.<\/p>\n<p style=\"text-align: justify;\">Con le mani unte, prendete uno dei panetti, schiacciatelo e stendetelo sul piano di lavoro imburrato, formando un rettangolo di circa 20 x 15 cm.<br \/>\nSpalmate nel centro un po&#8217; di strutto e arrotolate il panetto su se stesso, formate un filone allungato, tirandolo un po&#8217; dai lati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29732\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796819-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796819-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796819-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796819-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796819-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ripetete la stessa operazione con tutti i panetti, copriteli con pellicola da cucina lasciandoli riposare per 30 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29731\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796808-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796808-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796808-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796808-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796808-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ungete due teglie da forno.<br \/>\nPrendete uno dei cilindri e posizionatelo sulla teglia arrotolandolo a formare una spirale. Fate lo stesso con gli altri cilindri e posizionateli almeno a 7 cm l&#8217;uno dall&#8217;altro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29730\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796793-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796793-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796793-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796793-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616942796793-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Lasciate riposare per un&#8217;ora in luogo tiepido, devono raddoppiare di volume.<br \/>\nRiscaldate il forno a 200\u00c2\u00b0C .<\/p>\n<figure id=\"attachment_29744\" aria-describedby=\"caption-attachment-29744\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-29744\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484228-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484228-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484228-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484228-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484228-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-29744\" class=\"wp-caption-text\">Ensa\u00c3\u00afmada de Mallorca Llisa<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Infornate le ensaimadas per circa 8 minuti.<\/p>\n<figure id=\"attachment_29743\" aria-describedby=\"caption-attachment-29743\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-29743\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484211-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484211-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484211-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484211-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484211-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-29743\" class=\"wp-caption-text\">Ensa\u00c3\u00afmada de Mallorca Llisa<\/figcaption><\/figure>\n<figure id=\"attachment_29742\" aria-describedby=\"caption-attachment-29742\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-29742\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484181-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484181-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484181-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484181-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1616947484181-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-29742\" class=\"wp-caption-text\">Ensa\u00c3\u00afmada de Mallorca Llisa<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Mettetele sopra una griglia a raffreddare e poi spolverizzatele con zucchero a velo.<\/p>\n<p><strong>Note Personali e Varie<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">La farina da me usata e&#8217; stata la Panettone<\/li>\n<li style=\"text-align: justify;\">Ho seguito l&#8217;inserimento degli ingredienti come da ricetta, ma ho impiegato parecchio tempo a creare l&#8217;impasto corretto.<br \/>\nGli ingredienti si erano relativamente amalgamati e la ciotola risultava pulita, ma la consistenza dell&#8217;impasto non andava bene in quanto si stracciava. Alla fine ce l&#8217;ho fatta.<\/li>\n<li style=\"text-align: justify;\">Non avendo lo strutto, ho utilizzato del burro<\/li>\n<li style=\"text-align: justify;\">Non capisco come, ma sono cresciuti in altezza mentre avrebbero dovuto restare relativamente bassi ed arrotondati \ud83d\ude09<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La <strong>cucina spagnola<\/strong> \u00c3\u00a8 fortemente radicata nelle tradizioni pi\u00c3\u00b9 antiche e ha il merito di aver promosso dall&#8217;inizio del XVI secolo l&#8217;ingresso di prodotti nuovi in Europa (patata, pomodoro, mais, cacao, caff\u00c3\u00a8, ecc.) provenienti dalle Americhe.<\/p>\n<p style=\"text-align: justify;\">Tra gli antipasti ( \u00e2\u20ac\u0153<strong>aperitivo<\/strong>&#8221; ), le preparazioni pi\u00c3\u00b9 tipiche sono i frutti di mare (<strong>mariscos<\/strong>), olive verdi e nere, salumi e il salchichon di Vic. Gli aperitivi sono noti anche come <strong>tapas<\/strong>, o anche pincho nel Paese basco. Tra gli antipasti caldi ricordiamo la <strong>tortilla de patatas<\/strong> (frittata con patate) che si serve soprattutto come piatto forte e preparata secondo molte varianti.<\/p>\n<p style=\"text-align: justify;\">La <strong>paella<\/strong>, la preparazione pi\u00c3\u00b9 conosciuta della cucina spagnola, \u00c3\u00a8 un piatto unico preparato con riso, carne di pollo, coniglio, pesce (gamberoni e scampi), frutti di mare (mitili e vongole), verdure (pomodori, peperoni, piselli o taccole). Il termine spagnolo &#8220;paella&#8221; si riferisce alla padella che si usa per cucinare questa pietanza, la &#8220;paellera&#8221; (padella di ferro larga e dai bordi bassi munita di due manici).<br \/>\nTra le minestre, quella calda pi\u00c3\u00b9 nota \u00c3\u00a8 la <strong>sopa de ajo<\/strong> (zuppa d&#8217;aglio), tra quelle fredde il <strong>gazpacho<\/strong> (zuppa di vegetali crudi) e il <strong>salmorejo<\/strong> (zuppa di pomodoro tipica di Cordova).<\/p>\n<p style=\"text-align: justify;\">Anche le pietanze di carne e pesce sono varie e gustose. Altro piatto importante di origine contadina \u00c3\u00a8 il <strong>cocido<\/strong>, un bollito misto preparato con tipi diversi di carne a seconda delle regioni e con differenti verdure e legumi. Un&#8217;altra preparazione caratteristica \u00c3\u00a8 il <strong>cochinillo<\/strong> (porcellino neonato) arrostito al forno.<br \/>\nI piatti di pesce, invece, trovano le migliori caratteristiche nella <strong>zuppa zarzuela de mariscos<\/strong>, nel <strong>baccal\u00c3\u00a0 alla vizcayna<\/strong> e nel <strong>merluzzo alla basca.<\/strong><\/p>\n<p style=\"text-align: justify;\">Come contorno il pi\u00c3\u00b9 importante \u00c3\u00a8 il <strong>pisto manchego<\/strong>, fatto con pomodori, cipolla, melanzane e zucchine tagliati a pezzi e cucinati in padella con olio per circa 30 minuti. Un altro contorno \u00c3\u00a8 la <strong>gachamiga<\/strong>, a base di farina.<br \/>\nUn piatto tipico spagnolo \u00c3\u00a8 &#8220;l&#8217;Arr\u00c3\u00b2s negre&#8221; tradotto &#8220;il riso nero&#8221;.<\/p>\n<p>Disfrute de su comida<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Spagna, ufficialmente Regno di Spagna (in spagnolo e galiziano: Reino de Espa\u00c3\u00b1a, in basco: Espainiako Erresuma, in dialetto aranese: Regne d&#8217;Espanha, in catalano e valenciano: Regne d&#8217;Espanya), \u00c3\u00a8 uno Stato membro dell&#8217;Unione europea (dal 1\u00c2\u00ba gennaio 1986) e della NATO (dal 1982).<\/p>\n","protected":false},"author":2,"featured_media":29607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,145,168,22,90],"tags":[176,243,116],"class_list":["post-29604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dessert","category-dolci","category-europa","category-food","category-lievitati","tag-176","tag-europa_sud","tag-ldb"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=29604"}],"version-history":[{"count":14,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29604\/revisions"}],"predecessor-version":[{"id":31149,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29604\/revisions\/31149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/29607"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=29604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=29604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=29604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}