{"id":29375,"date":"2021-04-13T14:43:29","date_gmt":"2021-04-13T12:43:29","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=29375"},"modified":"2022-01-22T16:54:17","modified_gmt":"2022-01-22T15:54:17","slug":"giordania_maftoul","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/04\/13\/giordania_maftoul\/","title":{"rendered":"# 155 &#8211; Regno Hascemita di Giordania. Maftoul \/ Couscous Giordano"},"content":{"rendered":"<p style=\"text-align: justify;\">La <strong>Giordania<\/strong> ([\u00ca\u00a4or\u00cb\u02c6danja]) o <strong>Regno Hascemita di Giordania<\/strong> (in arabo: \u00d8\u00a7\u00d9\u201e\u00d9\u2026\u00d9\u2026\u00d9\u201e\u00d9\u0192\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d8\u00a3\u00d8\u00b1\u00d8\u00af\u00d9\u2020\u00d9\u0160\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d9\u2021\u00d8\u00a7\u00d8\u00b4\u00d9\u2026\u00d9\u0160\u00d8\u00a9\u00e2\u20ac\u017d, al-Mamlaka al-Urduniyya al-H\u00c4\u0081shimiyya) \u00c3\u00a8 uno Stato del Vicino Oriente (Asia).<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nConfina a nord con la Siria, a nord-est con l&#8217;Iraq, a sud-est e a sud con l&#8217;Arabia Saudita, a sud-ovest \u00c3\u00a8 bagnata dal Mar Rosso, a ovest con il territorio palestinese della Cisgiordania, Israele e il mar Morto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30807\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/06\/asia_occidentale-1024x881.jpg\" alt=\"\" width=\"525\" height=\"452\" \/><\/p>\n<p style=\"text-align: justify;\">\u00c3\u02c6 indipendente dal 1946 e la sua forma di governo \u00c3\u00a8 la monarchia costituzionale con capitale <em>Amman<\/em>.<\/p>\n<p style=\"text-align: justify;\">La lingua ufficiale del Regno \u00c3\u00a8 l&#8217;arabo, ma l&#8217;uso dell&#8217;inglese \u00c3\u00a8 molto diffuso in ambito governativo, culturale e sociale. Entrambe le lingue sono obbligatorie nelle scuole pubbliche e private. Il francese \u00c3\u00a8 insegnato in alcune scuole (sia pubbliche che private), ma non \u00c3\u00a8 obbligatorio. L&#8217;armeno e le lingue caucasiche sono diffuse tra i membri delle minoranze sopra citate.<\/p>\n<p><strong>Ingredienti<\/strong> &#8211; <a href=\"https:\/\/www.196flavors.com\/jordan-maftoul\/\"><strong><em>Maftoul\u00c2\u00a0 Giordano <\/em><\/strong><\/a>&#8211; 3 persone<\/p>\n<pre><strong>Per il maftoul<\/strong>\r\n150gr maftoul\r\nmezzo cucchiai di burro chiarificato\r\nmezza cipolla, tritata finemente\r\nmezzo cucchiaino di curcuma\r\nmezzo cucchiaio di cumino\r\n100gr di ceci, ammollati, cotti e scolati\r\n\r\n<strong>Per il brodo<\/strong>\r\n1,13 l  di acqua\r\n1,5 cubetti di brodo di pollo\r\n\r\n<strong>Per il pollo<\/strong>\r\n3 cosce di pollo\r\nmezzo cucchiai di burro chiarificato\r\nmezza cipolla, tritata\r\n75 g di ceci, ammollati, cotti e scolati\r\nmezzo cucchiaino di curcuma\r\nmezzo cucchiaio di cumino\r\nprezzemolo (foglia liscia) tritato finemente<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<br \/>\n<\/strong><br \/>\n<strong>Brodo<\/strong><br \/>\nPreparate un brodo portando l&#8217;acqua a ebollizione in una pentola e aggiungendo i cubetti di dado per brodo.<br \/>\nMescolate per sciogliere bene i cubetti e tenete in caldo.<\/p>\n<p style=\"text-align: justify;\"><strong>Pollo<\/strong><br \/>\nIn un forno olandese in ghisa (dutch oven), sciogliete il burro chiarificato.<br \/>\nRosolate il pollo a fuoco vivo fino a dorarlo su tutti i lati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30225\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963112-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963112-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963112-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963112-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963112-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30223\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963096-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963096-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963096-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963096-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963096-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la cipolla tritata insieme alla curcuma, al cumino e ai ceci.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30221\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963066-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963066-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963066-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963066-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963066-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nCoprite con met\u00c3\u00a0 del brodo.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30218\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963017-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963017-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963017-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963017-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963017-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nCuocete a fuoco lento, scoperto, per 20 minuti o fino a quando il pollo \u00c3\u00a8 cotto e la salsa si \u00c3\u00a8 addensata.<\/p>\n<p style=\"text-align: justify;\"><strong>Maftoul<\/strong><br \/>\nIn un forno olandese (dutch oven), scaldate il burro chiarificato a fuoco basso.<br \/>\nAggiungete la cipolla e fatela appassire senza colorarla.<br \/>\nAggiungete il maftoul e fatelo rosolare per qualche minuto, mescolando regolarmente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30224\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962999-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962999-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962999-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962999-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962999-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30217\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962958-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962958-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962958-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962958-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962958-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAggiungete la curcuma, il cumino ed i ceci e irrorate con l&#8217;altra met\u00c3\u00a0 del brodo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30226\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963128-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963128-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963128-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963128-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318963128-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30220\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962935-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962935-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962935-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962935-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962935-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAbbassate la fiamma al minimo e lasciate riposare il maftoul coperto per 15 minuti prima di servire.<\/p>\n<figure id=\"attachment_30219\" aria-describedby=\"caption-attachment-30219\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30219 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962806-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962806-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962806-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962806-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962806-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-30219\" class=\"wp-caption-text\">Giordania. Maftoul<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Assemblaggio<\/strong><br \/>\nVersate una porzione di maftoul su un piatto e adagiatevi sopra il pollo.<br \/>\nCospargete con un po&#8217; di prezzemolo.<\/p>\n<figure id=\"attachment_30222\" aria-describedby=\"caption-attachment-30222\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30222\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962773-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962773-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962773-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962773-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/ok_1618318962773-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-30222\" class=\"wp-caption-text\">Giordania. Maftoul con pollo<\/figcaption><\/figure>\n<p><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Prima di cuocere il pollo, ho rimosso la pelle<\/li>\n<li style=\"text-align: justify;\">Non ho utilizzato burro chiarificato, ma quello normale<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La cucina Giordana \u00c3\u00a8 costituita da piatti saporiti, per lo pi\u00c3\u00b9 a base di carne e legumi, spesso accompagnati da riso e verdure, che possono ricordare varianti di piatti israeliani, egiziani, siriani e curdi.<\/p>\n<p style=\"text-align: justify;\">Il cibo \u00c3\u00a8 utilizzato come strumanto di condivisione, cosi&#8217; che gli antipasti in Giordania (ed in tutti i Paesi arabi) assumono un\u00e2\u20ac\u2122importanza particolare: il fatto di mangiare con le mani, simboleggia il grande valore che il cibo e lo stare a tavola rappresenta per questo popolo, oppure si raccoglie il cibo con il &#8220;pane taboon&#8221; (simile alla pita).<br \/>\nAnche nella cucina della Giordana troviamo l&#8217;unione di riso e carne.<br \/>\nLe carni di agnello e montone sono le pi\u00c3\u00b9 diffuse, seguite da pollo e manzo, ma non mancano verdure e legumi, e naturalmente tante spezie ed erbe aromatiche, tra cui il coriandolo, il cumino, la curcuma, la menta, i chiodi di garofano, il prezzemolo e il timo.<br \/>\nIl sesamo \u00c3\u00a8 un altro ingrediente popolare e base della tahina, pasta di sesamo usata in tante ricette.<br \/>\nFrutta secca, yogurt e noci sono molto usati sia in piatti salati che, soprattutto, nei dolci.<\/p>\n<p style=\"text-align: justify;\">Tra i piatti piu&#8217; tipici possiamo ricordare<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Mansaf<\/strong> (\u00d9\u2026\u00d9\u2020\u00d8\u00b3\u00d9\u0081) &#8211; Considerato il piatto nazionale giordano, preparato durante le feste e le cerimonie.<br \/>\nSi tratta di una preparazione a base di riso, agnello e yogurt (lo jameed, leggemente pi\u00c3\u00b9 solido dello yogurt normale) e le sue origini sono chiaramente beduine, dove affonda le sue radici, essendo tra l\u00e2\u20ac\u2122altro il mansaf considerato anche il piatto conviviale per eccellenza e l\u00e2\u20ac\u2122emblema dell\u00e2\u20ac\u2122ospitalit\u00c3\u00a0.<br \/>\nLa particolarit\u00c3\u00a0 del mansaf \u00c3\u00a8 la sua preparazione elaborata che prevede la cottura della carne in brodo per poi essere passata in una salsa fatta con lo yogurt. La ricetta tradizionale prevede anche l\u00e2\u20ac\u2122aggiunta di pinoli e mandorle tostate e un mix di spezie Baharat (pimento, pepe nero, chiodi di garofano, cannella, cardamomo, coriandolo, carvi, noce moscata, paprika e in alcuni casi petali di rosa).<br \/>\nE\u00e2\u20ac\u2122 anche il piatto tipico dei beduini del deserto che viene servito se si dorme nei campi tendati o se si sosta per il pranzo.<br \/>\nI beduini mangiano il mansaf con la mano destra, possibilmente in piedi. Questo perche&#8217; per tradizione il piatto, o vassoio, viene collocato su una tavola elevata e i commensali si dispongono in piedi, attorno a essa, tenendo la mano sinistra dietro le spalle e raccogliendo il riso e la carne con la mano destra, messa a conca, per formare delle palline.<\/li>\n<li style=\"text-align: justify;\"><strong>Maqluba<\/strong> &#8211; Riso cotto in una pentola simile al tajine, insieme alla carne e alle verdure grigliate, e viene rovesciato una volta pronto. Lo si pu\u00c3\u00b2 condire con mandorle e yogurt.<\/li>\n<li style=\"text-align: justify;\"><strong>Hummus<\/strong> &#8211; La crema di ceci,\u00c2\u00a0 salsa a base di pasta di sesamo e pasta di ceci, aromatizzata con olio di oliva, aglio, paprika, prezzemolo, succo di limone e semi di cumino in polvere. Viene servita come accompagnamento a pietanze di carne\u00c2\u00a0 oppure semplicemente con il pane.<\/li>\n<li style=\"text-align: justify;\"><strong>Falafel<\/strong> &#8211; Polpette di ceci tritati, prezzemolo, aglio, coriandolo e cipolla fritte nell\u00e2\u20ac\u2122olio. Vengono accompagnate con pane o salse.<\/li>\n<li style=\"text-align: justify;\"><strong>Mutabbal (o Baba Ganush)<\/strong> &#8211; crema di melanzane al forno mischiata alla salsa tahina a base di sesamo e arricchita di limone, aglio e olio d\u00e2\u20ac\u2122oliva.<\/li>\n<li style=\"text-align: justify;\"><strong>Msakhan<\/strong> &#8211; Pollo e riso con aggiunta di pinoli.<\/li>\n<li style=\"text-align: justify;\"><strong>Labneh<\/strong> &#8211; Formaggio spalmabile.<\/li>\n<li style=\"text-align: justify;\"><strong>Zarb (o Zaarb)<\/strong> &#8211; Terrina di carne e verdure cotta sotto la sabbia.<\/li>\n<li style=\"text-align: justify;\"><strong>Knafeh<\/strong> &#8211; Strati di pasta fillo farciti con un mix di formaggi freschi e cotti in un mix di burro.<\/li>\n<li style=\"text-align: justify;\"><strong>Basbousa<\/strong> &#8211; Semolino, miele, yogurt e mandorle.<\/li>\n<li style=\"text-align: justify;\"><strong>Pita<\/strong>. Pane piatto lievitato ottenuto dalla farina di grano, conosciuto anche come pane arabo.<\/li>\n<li style=\"text-align: justify;\"><strong>Tabbouleh<\/strong> &#8211; Pietanza diffusa nel Vicino Oriente, il cui nome significa &#8220;leggermente speziato&#8221; in arabo levantino. Si tratta di un&#8217;insalata a base di bulgur (o grano spezzato), prezzemolo, cipollotti, menta tritata finemente, pomodoro e cetrioli, il tutto condito con succo di limone e olio d&#8217;oliva.<\/li>\n<li style=\"text-align: justify;\"><strong>Kufta<\/strong> &#8211; Polpettine di carne (di agnello e montone ), tritate e mescolate con erbe varie e cipolle e, successivamente, fritte oppure cotte alla brace.<\/li>\n<li style=\"text-align: justify;\"><strong>Fattush<\/strong> &#8211; Insalata mista composta da diversi ingredienti: pomodori, rapanelli, lattuga, insalata, cetrioli, menta, cipollotti e\u00c2\u00a0 pezzi di pita tostati e resi croccanti.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Tra i dolci abbiamo :<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Kunafa<\/strong> &#8211; Crema di latte o formaggio di capra dolce, racchiuso in una tela croccante di capelli d&#8217;angelo dorati.<\/li>\n<li style=\"text-align: justify;\"><strong>Muhallabia<\/strong> &#8211; Budino di riso e zucchero a cui viene aggiunto un aroma rinfrescante all&#8217;arancia.Gli alcolici sono poco diffusi, dato che la stragrande maggioranza della popolazione \u00c3\u00a8 di religione musulmana.<strong>Caffe&#8217; alla beduina<\/strong> &#8211; Caff\u00c3\u00a8 molto ristretto, ma senza fondi.<br \/>\n<strong>Caffe&#8217; turco<\/strong> &#8211; lungo, corposo, dal gusto deciso e aromatizzato.<\/li>\n<\/ul>\n<p>\u00d8\u00a3\u00d8\u00aa\u00d9\u2026\u00d9\u2020\u00d9\u2030 \u00d9\u201e\u00d9\u0192 \u00d9\u02c6\u00d8\u00ac\u00d8\u00a8\u00d8\u00a9 \u00d8\u00b4\u00d9\u2021\u00d9\u0160\u00d8\u00a9<br \/>\n&#8216;atamanaa lak wajabat shahia<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Giordania ([\u00ca\u00a4or\u00cb\u02c6danja]) o Regno Hascemita di Giordania (in arabo: \u00d8\u00a7\u00d9\u201e\u00d9\u2026\u00d9\u2026\u00d9\u201e\u00d9\u0192\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d8\u00a3\u00d8\u00b1\u00d8\u00af\u00d9\u2020\u00d9\u0160\u00d8\u00a9 \u00d8\u00a7\u00d9\u201e\u00d9\u2021\u00d8\u00a7\u00d8\u00b4\u00d9\u2026\u00d9\u0160\u00d8\u00a9\u00e2\u20ac\u017d, al-Mamlaka al-Urduniyya al-H\u00c4\u0081shimiyya) \u00c3\u00a8 uno Stato del Vicino Oriente (Asia).<\/p>\n","protected":false},"author":2,"featured_media":29640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,64,22,138,51,60],"tags":[176,234,54,249,55],"class_list":["post-29375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-carne","category-food","category-piatti_unici","category-primi_piatti","category-secondi_piatti","tag-176","tag-asia_occidentale","tag-cereali","tag-dutch_oven","tag-legumi"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=29375"}],"version-history":[{"count":20,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29375\/revisions"}],"predecessor-version":[{"id":31647,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29375\/revisions\/31647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/29640"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=29375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=29375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=29375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}