{"id":29236,"date":"2021-07-14T14:56:08","date_gmt":"2021-07-14T12:56:08","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=29236"},"modified":"2021-05-12T20:41:30","modified_gmt":"2021-05-12T18:41:30","slug":"lindt-pistacchio-mandorle","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/07\/14\/lindt-pistacchio-mandorle\/","title":{"rendered":"Lindt: Pistacchio con mandorle a pezzetti"},"content":{"rendered":"<p style=\"text-align: justify;\">Ed eccoci qui, nuovamente con una nuova irresistibile scioglievolezza data da questa nuova tavoletta di cioccolato della<strong> Lindt, <\/strong>al gusto di <strong>Pistacchio con mandorle a pezzetti<\/strong>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Questa volta la tavoletta di cioccolato che abbiamo provato fa parte della serie &#8220;Creation&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il gusto della copertura esterna di cioccolato e&#8217; deciso, non proprio al latte, ma le note di cacao sono presenti e si sentono.<br \/>\nLa crema interna, di pistacchio, sembra quasi velluto ma alla sofficita&#8217; viene contrapposto il croccante dei piccoli pezzetti di mandorla che sono presenti.<\/p>\n<figure id=\"attachment_29237\" aria-describedby=\"caption-attachment-29237\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-29237\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102719-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102719-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102719-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102719-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102719-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-29237\" class=\"wp-caption-text\">Lindt: Pistacchio con mandorle a pezzetti<\/figcaption><\/figure>\n<p>Noi lo abbiamo provato dopo il nostro pranzo, durante il caffe&#8217;.<\/p>\n<figure id=\"attachment_29237\" aria-describedby=\"caption-attachment-29237\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-29238\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102737-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102737-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102737-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102737-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/03\/1614776102737-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-29237\" class=\"wp-caption-text\">Lindt: Pistacchio con mandorle a pezzetti<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Devo dire che l&#8217;insieme dei gusti e delle consistenze si armonizzano bene tra loro.<br \/>\nMa, a mio parere, manca quel tocco di originalita&#8217; al prodotto.<\/p>\n<p>No, non si tratta di una tavoletta di cioccolato banale, ma sicuramente non particolare, come quella che avevamo precedentemente provato al <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/02\/28\/lindt-salz-lakritz-sale-liquirizia\/\">sale e liquerizia<\/a><\/strong><\/em>.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ed eccoci qui, nuovamente con una nuova irresistibile scioglievolezza data da questa nuova tavoletta di cioccolato della Lindt, al gusto di Pistacchio con mandorle a pezzetti.<\/p>\n","protected":false},"author":2,"featured_media":29237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[84,88],"class_list":["post-29236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","tag-cioccolato","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=29236"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29236\/revisions"}],"predecessor-version":[{"id":29241,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/29236\/revisions\/29241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/29237"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=29236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=29236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=29236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}