{"id":28223,"date":"2021-01-25T14:41:23","date_gmt":"2021-01-25T13:41:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=28223"},"modified":"2022-01-24T17:16:39","modified_gmt":"2022-01-24T16:16:39","slug":"ecuador_empanada-forno","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/01\/25\/ecuador_empanada-forno\/","title":{"rendered":"# 18 \u00e2\u20ac\u201c Repubblica dell\u00e2\u20ac\u2122Ecuador. Empanada al forno"},"content":{"rendered":"<p style=\"text-align: justify;\">Rieccomi nuovamente con un inverso salto temporale, ancora una volta sono qui in <strong>Ecuador<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Diciamo che in famiglia non e&#8217; stata ben presa la mia preparazione per l&#8217;Ecuador, in quanto avevo tagliato solamente delle patate invece di dover cucinare qualche cosa.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ripresento questa nazione con le <strong>Empanadas<\/strong>.<br \/>\nDovrebbero essere fritte, come quelle di Carmen, ma proprio non riesco (e non mi piace proprio friggere, anche se il cibo ottenuto in questo modo lo divorerei), cosi&#8217; mi appresto a cuocerle al forno.<\/p>\n<p style=\"text-align: justify;\">Le empanadas non sono altro che dei fagottini di pasta ripieni di verdure e\/o carne, tipici dell&#8217;Argentina e del Cile, delle Filippine e dell&#8217;America Latina.<br \/>\nTradizionalmente venivano servite alle jaranas criollas, ovvero alle feste creole, agli incontri musicali in accompagnamento alla tradizionale grigliata di carne, l&#8217;asado.<\/p>\n<p style=\"text-align: justify;\">Si ritiene che la ricetta provenga dagli spagnoli che, a loro volta, l&#8217;appresero dai popoli arabi del bacino del Mediterraneo, dove l&#8217;abitudine di presentare carne finemente tagliata dentro un fagotto di pane \u00c3\u00a8 diffusissima e d\u00c3\u00a0 luogo a ricette quali il kebab o il gyros pita.<\/p>\n<p style=\"text-align: justify;\">Le empanadas nella loro versione pi\u00c3\u00b9 nota sono di carne di manzo, ma esistono anche molte varianti con carne di gallina, di pollo, di maiale, lepre o gamberi, come in Patagonia.<br \/>\nQueste varianti si cucinano in diverse nazioni e in paesi come il Venezuela, l&#8217;Ecuador, il Per\u00c3\u00b9 e la Colombia vengono considerate piatto nazionale.<\/p>\n<p style=\"text-align: justify;\">In rete si possono trovate molte ricette per l&#8217;impasto delle empanades, con o senza uova, ne ho trovato uno anche con la vodka, con o senza lievito di birra e\/o normale per torte.<br \/>\nInsomma, non si sa bene quale utilizzare.<\/p>\n<p style=\"text-align: justify;\">Alla fine, per la preparazione dell&#8217;involucro, ho deciso di seguire la versione piu&#8217; semplice almeno per me, con meno ingredienti e meno complicata.<\/p>\n<p><strong>Ingredienti<\/strong> &#8211; 10\/15 <strong>empanadas <\/strong>(dipende molto dalla dimensione che diamo!)<strong><br \/>\n<\/strong><\/p>\n<pre>250 g. farina\r\n125 ml. acqua tiepida\r\n20 g. strutto\/burro\r\n5 g. sale\r\n\r\n1 uovo per spennellare<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">In una ciotola capiente versate la farina con lo strutto\/burro e aggiungete l\u00e2\u20ac\u2122acqua, dove in precedenza avete sciolto il sale.<br \/>\nImpastate a mano (o con un food processor) per circa dieci minuti, fino ad ottenere un impasto omogeneo e lisco.<br \/>\nCopritelo con la pellicola per alimenti e lasciatelo risposare in frigorifero per circa 30 minuti.<\/p>\n<p style=\"text-align: justify;\">Prendete il panetto e stendete la pasta in una sfoglia sottile di circa 2 mm.<br \/>\nCon un coppa pasta del diametro di 12 cm. tagliate la sfoglia in 12 dischetti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28326\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818923-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818923-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818923-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818923-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818923-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Per farcire, vi consiglio di mettete nella mano sinistra un dischetto formando una coppetta e inumidite i bordi, con un goccio di acqua, per poter chiudere bene, sigillando al termine le empanadas.<\/p>\n<p style=\"text-align: justify;\">(A casa ho trovato l&#8217;aggeggino per fare i ravioli ripieni, ed ho cosi&#8217; provato ad usarlo. Ho inoltre provato a chiudere con i rebbi della forchetta o tentare un cordoncino.)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28327\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818917-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818917-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818917-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818917-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818917-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Riempite ogni dischetto con un cucchiaio di ripieno, e chiudete l\u00e2\u20ac\u2122empanadas sigillando bene il bordo intorno al ripieno, (non deve restare aria), formando un cordoncino (il repulgue), oppure semplicemente con i rebbi della forchetta.<\/p>\n<figure id=\"attachment_28328\" aria-describedby=\"caption-attachment-28328\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28328\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818911-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818911-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818911-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818911-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818911-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28328\" class=\"wp-caption-text\">Ecuador. Empanada al forno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Spennellate la superficie con l\u00e2\u20ac\u2122uovo preventivamente sbattuto leggermente e cuocete in forno a 180\u00c2\u00b0 statico per circa 15\/20 minuti.<\/p>\n<figure id=\"attachment_28329\" aria-describedby=\"caption-attachment-28329\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28329\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818905-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818905-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818905-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818905-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818905-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28329\" class=\"wp-caption-text\">Ecuador. Empanada al forno<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Sfornate e servite calde.<\/p>\n<figure id=\"attachment_28330\" aria-describedby=\"caption-attachment-28330\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28330\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818899-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818899-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818899-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818899-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818899-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28330\" class=\"wp-caption-text\">Ecuador. Empanada al forno<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Non avendo strutto in casa, l&#8217;ho sostituito con la stessa quantita&#8217; di burro.<\/li>\n<li style=\"text-align: justify;\">Se non avete il coppapasta di quella dimensione, potete utilizzate un bicchiere grande oppure una ciotola capovolta<\/li>\n<li style=\"text-align: justify;\">Cercate di non inserire un ripieno troppo liquido, potrebbe sgocciolare fuori all&#8217;empanada<\/li>\n<li style=\"text-align: justify;\">Non ho sbattuto l&#8217;uovo per la spennallatura, ma ho passato leggermente con olio. Forse e&#8217; per questo motivo che sono risultate un po&#8217; &#8220;anemiche&#8221;.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">A casa le abbiamo preparate con la <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/01\/24\/messico_carnitas\/\">carnitas<\/a><\/strong><\/em>\/pulled pork\u00c2\u00a0 <del>avanzata<\/del> nascosta ieri, nel nostro pranzo messicano.<br \/>\nHo aggiunto una cipolla tagliuzzata e stufata in qualche cucchiaio di sugo avanzato, cosi&#8217; da ammorbidirla ed insaporire ulteriormente la carne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28323\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818941-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818941-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818941-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818941-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818941-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28324\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818935-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818935-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818935-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818935-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818935-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28325\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818929-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818929-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818929-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818929-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611579818929-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Naturalmente le potete riempire come meglio preferite, con formaggio, pesce o quello che piu&#8217; vi aggrada.<\/p>\n<p>Disfruta tu comida<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rieccomi nuovamente con un inverso salto temporale, ancora una volta sono qui in Ecuador.<\/p>\n","protected":false},"author":2,"featured_media":28224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,138,226],"tags":[176,178,160],"class_list":["post-28223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-piatti_unici","category-stati-americhe","tag-176","tag-streetfood","tag-sud_america"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=28223"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28223\/revisions"}],"predecessor-version":[{"id":35552,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28223\/revisions\/35552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/28224"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=28223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=28223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=28223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}