{"id":28221,"date":"2021-01-24T15:02:47","date_gmt":"2021-01-24T14:02:47","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=28221"},"modified":"2022-01-22T18:10:18","modified_gmt":"2022-01-22T17:10:18","slug":"messico_frijoles_refritos","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/01\/24\/messico_frijoles_refritos\/","title":{"rendered":"# 128 \u00e2\u20ac\u201c Stati Uniti Messicani. Frijoles Refritos (Crema di Fagioli)"},"content":{"rendered":"<p style=\"text-align: justify;\">Per accompagnare il mio pasto messicano, a base di tortillas e burritos, non poteva mancare una crema di fagioli (<strong>Frijoles Refritos<\/strong> ).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">I Frijoles Refritos si potrebbero tradurre in italiano con il nome di \u00e2\u20ac\u0153fagioli ripassati in padella\u00e2\u20ac\u009d e si tratta di una ricetta che accompagna diversi piatti Latino-Americani (Messico, Venezuela, Per\u00c3\u00b9, tra i tanti paesi dove si preparano).<br \/>\nSono anche questi alla base della gastronomia messicana e Latino-americana in genere.<\/p>\n<p style=\"text-align: justify;\">Anche in questo casono non abbiamo una singola ricetta codificata, ma varia da Nazione a Nazione, per non dire da famiglia a famiglia!<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong> &#8211; <em><strong><a href=\"http:\/\/banchettodei.com\/frijoles-refritos-crema-di-fagioli\">Frijoles Refritos<\/a><\/strong><\/em> (Crema di Fagioli)<\/p>\n<pre>400 gr. di fagioli borlotti (o fagioli neri) precotti*\r\n1 cipolla\r\n1 spicchio d\u00e2\u20ac\u2122aglio\r\n\u00c2\u00bd cucchiaino di cumino\r\nsale q.b.\r\nolio di semi q.b.<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tritate la cipolla e l\u00e2\u20ac\u2122aglio e fateli dorare in padella con un poco d\u00e2\u20ac\u2122olio (circa 2-3 cucchiai).<br \/>\nAggiungete i fagioli, il cumino e il sale e cuocete per qualche minuto a fuoco medio, se il composto dovesse restare troppo asciutto aggiungete un bicchierino d\u00e2\u20ac\u2122acqua.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28284\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324153-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324153-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324153-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324153-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324153-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quando il liquido di cottura comincia a restringersi, schiacciate con una paletta di legno qualche fagiolo (non tutti!!) in maniera da formare una cremina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28285\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324147-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324147-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324147-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324147-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324147-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Quando la cremina avr\u00c3\u00a0 raggiunto la consistenza giusta (abbastanza densa e non liquida), togliete dal fuoco e servite.<\/p>\n<figure id=\"attachment_28286\" aria-describedby=\"caption-attachment-28286\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28286\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324141-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324141-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324141-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324141-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324141-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28286\" class=\"wp-caption-text\">Messico: frijoles refritos<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con questa cremina di fagioli potete servire dei nachos, oppure potete usarla per farcire Enchiladas, Burritos, etc\u00e2\u20ac\u00a6<br \/>\nPotete anche usarla come accompagnamento di piatti a base di carne e\/o riso.<\/p>\n<figure id=\"attachment_28280\" aria-describedby=\"caption-attachment-28280\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28280\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28280\" class=\"wp-caption-text\">Messico. Guacamole, carnita, frijoles refritos<\/figcaption><\/figure>\n<p><strong>Note Varie e Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">* logicamente e&#8217; possibile partire direttamente dai fagioli secchi che per\u00c3\u00b2 prima dovranno stare in ammollo per almeno 12 ore e successivamente essere cotti in acqua.<\/li>\n<li style=\"text-align: justify;\">i Frijoles Refritos si possono conservare in frigo per qualche giorno, in un contenitore chiuso. Quando volete mangiarli potete scaldarli in padella aggiungendo un p\u00c3\u00b2 d\u00e2\u20ac\u2122acqua per far ammorbidire la cremina rappresa.<\/li>\n<li style=\"text-align: justify;\">i Frijoles Refritos spesso vengono mischiati con del Chorizo oppure con del formaggio fresco.<\/li>\n<\/ul>\n<p>Disfruta tu comida<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per accompagnare il mio pasto messicano, a base di tortillas e burritos, non poteva mancare una crema di fagioli (Frijoles Refritos ).<\/p>\n","protected":false},"author":2,"featured_media":28174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152,22,226],"tags":[176,55,225],"class_list":["post-28221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-confetture","category-food","category-stati-americhe","tag-176","tag-legumi","tag-nord_america"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=28221"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28221\/revisions"}],"predecessor-version":[{"id":30612,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28221\/revisions\/30612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/28174"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=28221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=28221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=28221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}