{"id":28173,"date":"2021-01-24T15:00:25","date_gmt":"2021-01-24T14:00:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=28173"},"modified":"2023-07-02T14:29:28","modified_gmt":"2023-07-02T12:29:28","slug":"messico_carnitas","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/01\/24\/messico_carnitas\/","title":{"rendered":"# 128 &#8211; Stati Uniti Messicani. Carnitas"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>Messico<\/strong> (spagnolo: M\u00c3\u00a9xico; nahuatl: M\u00c4\u201cxihco), ufficialmente gli <strong>Stati Uniti Messicani<\/strong> (spagnolo: Estados Unidos Mexicanos; nahuatl: M\u00c4\u201cxihcatl Tlacetil\u00c4\u00ablli Tlahtohc\u00c4\u0081y\u00c5\u008dtl), \u00c3\u00a8 una democrazia rappresentativa composta da trentuno Stati.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Secondo la Costituzione messicana la sede dei poteri della federazione e capitale dello Stato \u00c3\u00a8 <em>Citt\u00c3\u00a0 del Messico.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30606\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/stati_nord_america-1024x943.jpg\" alt=\"\" width=\"525\" height=\"483\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;insediamento umano in questo territorio risale a circa undicimila anni fa e da allora si succedettero svariati popoli, sia agricoltori della Mesoamerica sia nomadi.<br \/>\nIn Messico, a livello costituzionale, de iure non esiste una lingua che venga designata come lingua ufficiale. Tuttavia, la Ley General de los Derechos Ling\u00c3\u00bc\u00c3\u00adsticos riconosce lo status di lingua nazionale allo spagnolo e alle lingue indigene native del territorio, cos\u00c3\u00ac come a quelle di altri popoli indios che si sono stabiliti nel loro territorio.<\/p>\n<p style=\"text-align: justify;\">Per la preparazione odierna ho pensato alla &#8220;<strong>carnitas<\/strong>&#8220;, cosi&#8217; da poterla utilizzare in modi differenti, per riempire tacos, burritos o enchiladas.<\/p>\n<p style=\"text-align: justify;\">&#8220;Carnitas&#8221; significa in spagnolo &#8220;piccole carni&#8221;.<br \/>\nSi tratta di un taglio di maiale poco costoso e molto marmorizzato (come la spalla di maiale), brasato o cotto a fuoco lento per diverse ore utilizzando condimenti diversi e strutto, affinch\u00c3\u00a9 non risulta tenero da poter essere sminuzzato.<br \/>\nA fine cottura la carne viene arrostita per renderla croccante.<\/p>\n<p style=\"text-align: justify;\">La ricetta l&#8217;ho trovata<em><strong> {\u00c2\u00a0https :\/\/ carnitas.info\/receta\/ } <\/strong><\/em>e&#8217; veramente semplice e basica da preparare, giusto pochi ingredienti: carne (con o senza cotenna), olio\/burro\/strutto, sale acqua.<\/p>\n<p style=\"text-align: justify;\">Ma volendomi fare del male, ho pensato di aggiungere qualche sapore in piu&#8217; e di cuocerla nella pentola a pressione, seguendo la ricetta che avevo preparato precedendemente per il <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/08\/02\/pulled-pork-pap\/\">pulled pork<\/a><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">La carnita non e&#8217; poi cosi&#8217; tanto diversa dal pulled pork.<br \/>\nSia le carnitas che il pulled pork vengono cotti lentamente per diverse ore e sono ottimi da preparare nella pentola a cottura lenta o in pentola a pressione.<br \/>\nA differenza del pulled pork, tuttavia, le carnitas vengono terminate arrostendo la carne in forno fino a doratura e croccantezza.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti &#8211; Carnita (a modo mio)<\/strong><\/p>\n<pre>olio q.b.\r\n1.3 kg spalla di maiale disossata, senza cotenna\r\npeperoncino (o peperoni)\r\n1 cipolla grande, tritata grossolanamente\r\n2 spicchi d'aglio, schiacciati\r\n3 pimento\r\ncumino macinato\r\nworcester souce\r\nketchup\r\n\r\n<strong>Opzionale<\/strong>:\r\nsale\r\npepe nero\r\norigano\r\nsucco di lime (facoltativo)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Ecco gli ingredienti inseriti, oltre alla carne<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28260\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043884-1024x813.jpg\" alt=\"\" width=\"525\" height=\"417\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043884-1024x813.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043884-150x119.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043884-300x238.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043884-768x610.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Iniziate a scaldare la pentola a pressione a fuoco medio-alto inserendo dell&#8217;olio.<\/p>\n<figure id=\"attachment_28261\" aria-describedby=\"caption-attachment-28261\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28261\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043876-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043876-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043876-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043876-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043876-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28261\" class=\"wp-caption-text\">pulled pork &#8211; (Messico) carnitas<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Rosolate la spalla\u00c2\u00a0 di maiale (o altro pezzo di carne prescelto) su tutti i lati nell&#8217;olio caldo.<\/p>\n<figure id=\"attachment_28262\" aria-describedby=\"caption-attachment-28262\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28262\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043867-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043867-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043867-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043867-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043867-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28262\" class=\"wp-caption-text\">pulled pork &#8211; (Messico) carnitas<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Incorporate i restanti ingredienti (il peperoncino, cipolla, aglio, coriandolo, cumino, pimento, worcester souce, ketchup), compresi gli opzionali e\/o facoltativi<\/p>\n<figure id=\"attachment_28263\" aria-describedby=\"caption-attachment-28263\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28263\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043856-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043856-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043856-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043856-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043856-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28263\" class=\"wp-caption-text\">pulled pork &#8211; (Messico) carnitas<\/figcaption><\/figure>\n<figure id=\"attachment_28264\" aria-describedby=\"caption-attachment-28264\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28264\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043840-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043840-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043840-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043840-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611401043840-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28264\" class=\"wp-caption-text\">pulled pork &#8211; (Messico) carnitas<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Chiudete e bloccate il coperchio della pentola a pressione, portate a pressione e abbassate la fiamma per mantenere la pressione interna costante.<\/p>\n<p style=\"text-align: justify;\">Cuocete a pressione media costante per 1:30 ora, togliete la pentola dal fuoco e fate sfiatare.<\/p>\n<p style=\"text-align: justify;\">Rimuovete con cautela il coperchio e la carne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28278\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324164-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324164-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324164-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324164-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324164-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Stracciate la carne, mettetela in un contenitore e passatela sotto la griglia del forno per farla arrostire, rendendola croccante.<\/p>\n<figure id=\"attachment_28279\" aria-describedby=\"caption-attachment-28279\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28279\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324159-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324159-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324159-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324159-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324159-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28279\" class=\"wp-caption-text\">Messico: carnitas<\/figcaption><\/figure>\n<figure id=\"attachment_28280\" aria-describedby=\"caption-attachment-28280\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-28280\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324102-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-28280\" class=\"wp-caption-text\">Messico. Guacamole, carnitas, frijoles refritos<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">E&#8217; possibile tagliare a cubetti la carne, invece di inserirla intera. Una volta cotta sara&#8217; piu&#8217; semplice\u00c2\u00a0 stracciarla manualmente (il tempo di cottura diminuisce, essendo piu&#8217; veloce a cuocere)<\/li>\n<li style=\"text-align: justify;\">Personalmente non amo i peperoncini, per questo motivo non ne ho fatto un grosso uso,<br \/>\nSe volete aggiungerne di piu&#8217;, o di diversa qualita&#8217;, fate pure.<br \/>\nAttenzione, pero&#8217;, a quando maneggiate tutti quei peperoncini! Forse sarebbe piu&#8217; conveniente utilizzare dei guanti di lattice \ud83d\ude09<\/li>\n<li style=\"text-align: justify;\">Le indicazioni inserite tra gli ingredienti sono un po&#8217; spannometriche, lo so. Ma molto va a gusto personale.<br \/>\nLa mia carne era comunque poco piu&#8217; di 1kg di spalla di maiale (1.3kg per la precisione), senza cotenna.<\/li>\n<li style=\"text-align: justify;\">La volta precedente avevo inserito della salsa. Questa volta ho terminato il ketchup (che era aperto da Natale e che nessuno in casa utilizza). Cosi&#8217; facendo non ho aggiunto brodo e\/o acqua abbondante.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-28281\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324119-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324119-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324119-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324119-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1611491324119-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">La <strong>cucina messicana<\/strong> (gastronom\u00c3\u00ada mexicana\/M\u00c4\u201cxihco itlacualiz) \u00c3\u00a8 l&#8217;espressione dell&#8217;arte culinaria sviluppata in Messico ed \u00c3\u00a8 caratterizzata da sapori intensi e vari, per via della gran variet\u00c3\u00a0 di spezie utilizzate.<br \/>\nDal 2010 \u00c3\u00a8 diventata patrimonio dell&#8217;umanit\u00c3\u00a0 UNESCO.<\/p>\n<p style=\"text-align: justify;\">Quando i conquistadores spagnoli raggiunsero la capitale azteca Tenochtitl\u00c3\u00a1n (l&#8217;antica citt\u00c3\u00a0 su cui sorge ora Citt\u00c3\u00a0 del Messico), scoprirono che la dieta indigena consisteva principalmente di piatti basati su mais, conditi con peperoncini ed erbe e in genere accompagnati da fagioli e zucca.<br \/>\nNel tempo i conquistadores combinarono la propria dieta composta da riso, manzo, maiale, pollo, vino, aglio e cipolle con il cibo indigeno del Messico pre-Colombiano (che includeva cacao, pannocchie, pomodori, vaniglia, avocado, papaia, ananas, peperoncino, fagioli, zucca, patate dolci, arachidi e tacchino).<br \/>\nIl <strong>totopo<\/strong> (una &#8220;tortilla&#8221; di mais salata cotta in forno a legna) potrebbe essere un risultato di questo connubio.<\/p>\n<p style=\"text-align: justify;\">Gran parte del cibo messicano odierno \u00c3\u00a8 basato su tradizioni pre-ispaniche, comprese quelle azteche e maya, combinate con lo stile culinario introdotto dai coloni spagnoli.<br \/>\nLe <strong>quesadillas<\/strong> sono &#8220;tortilla&#8221; di farina o mais con formaggio (tipicamente queso blanco), manzo, pollo, maiale e peperoncino (chili).<br \/>\nI piatti sono tipicamente molto colorati grazie alla ricca variet\u00c3\u00a0 di verdure rosse e verdi presenti e di carni.<br \/>\nAnche la cucina caraibica ha influenzato alcuni piatti Messicani, in particolar modo alcuni piatti regionali di Veracruz e dello Yucat\u00c3\u00a1n. Infine l&#8217;occupazione francese ha a sua volta contribuito in qualche misura a formare la cucina attuale messicana.<\/p>\n<p style=\"text-align: justify;\">I cibi messicani cambiano da regione a regione a causa delle differenze climatiche, geografiche, etniche e a seconda della maggiore o minore influenza ispanica.<br \/>\nI piatti principali e pi\u00c3\u00b9 famosi sono i tacos, i sopes, barbacoa, la salsa guacamole, le tortilla e le zuppe (sopas).<br \/>\nLa bevanda pi\u00c3\u00b9 famosa \u00c3\u00a8 la tequila, derivata dalla pianta dell&#8217;Agave come l&#8217;aguardiente, mescal, ecc.<br \/>\nUn&#8217;altra bevanda molto popolare \u00c3\u00a8 la michelada; birra preparata con sale e limone verde, che pu\u00c3\u00b2 anche includere salsa piccante e salsa soia.<\/p>\n<p style=\"text-align: justify;\">Molte pietanze messicane vanno mangiate per strada (street food).<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Chilaquiles<\/strong> &#8211; piatto composto da pezzi di tortilla di mais fritti conditi con una salsa verde piccante ed accompagnati da cipolle crude, pezzi di pollo, carne macinata, uova, formaggio, panna acida e fagioli. Generalmente viene consumato a colazione.<\/li>\n<li style=\"text-align: justify;\"><strong>Tamales<\/strong> &#8211; piatto pi\u00c3\u00b9 antico della tradizione culinaria messicana. Composto da un impasto di mais cotto a vapore all\u00e2\u20ac\u2122interno di foglie di banana. Si pu\u00c3\u00b2 abbinare a carne e verdure. Esistono anche alcune versioni dolci.<\/li>\n<li style=\"text-align: justify;\"><strong>Champurrado<\/strong> &#8211; bevanda con cacao<\/li>\n<li style=\"text-align: justify;\"><strong>Mole<\/strong> -Salsa dalle numerose varianti. Viene utilizzata per accompagnare la carne ed ha l\u00e2\u20ac\u2122aspetto ed il sapore della cioccolata.<\/li>\n<li style=\"text-align: justify;\"><strong>Pozole<\/strong> &#8211; Uno dei pi\u00c3\u00b9 antichi piatti messicani. \u00c3\u02c6 uno stufato a base di mais cotto servito con carne, cavolo affettato, peperoncino, cipolla, aglio e altri aromi e spezie.<\/li>\n<li style=\"text-align: justify;\"><strong>Enchiladas<\/strong> &#8211; Sono realizzate utilizzando la farina di mais, leggere sfoglie ripiene di diversi ingredienti, dalla carne alle verdure, e ricoperte da salsa piccante.<\/li>\n<li style=\"text-align: justify;\"><strong>Nopales<\/strong> &#8211; foglie di cactus consumate crude o cotte alla griglia, molto utilizzate soprattutto per le loro propriet\u00c3\u00a0 benefiche.<\/li>\n<li style=\"text-align: justify;\"><strong>Esquites<\/strong> &#8211; Chicchi di mais cotti alla piastra e conditi con cipolla, formaggio, peperoncino in polvere con l\u00e2\u20ac\u2122aggiunta di maionese.<\/li>\n<li style=\"text-align: justify;\"><strong>Chapulines<\/strong> &#8211; cavallette tostate alla piastra e condite con aglio, succo di lime e sale.<\/li>\n<li style=\"text-align: justify;\"><strong>Frutta con peperoncino e sale<\/strong> &#8211; Originale ma saporita.<\/li>\n<li style=\"text-align: justify;\"><strong>Gorditas<\/strong> &#8211; pagnotte di farina di mais farcite con carne e formaggio.<\/li>\n<\/ul>\n<p>Disfruta tu comida<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Messico (spagnolo: M\u00c3\u00a9xico; nahuatl: M\u00c4\u201cxihco), ufficialmente gli Stati Uniti Messicani (spagnolo: Estados Unidos Mexicanos; nahuatl: M\u00c4\u201cxihcatl Tlacetil\u00c4\u00ablli Tlahtohc\u00c4\u0081y\u00c5\u008dtl), \u00c3\u00a8 una democrazia rappresentativa composta da trentuno Stati.<\/p>\n","protected":false},"author":2,"featured_media":28174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60,226],"tags":[176,225,53],"class_list":["post-28173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","category-stati-americhe","tag-176","tag-nord_america","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=28173"}],"version-history":[{"count":20,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28173\/revisions"}],"predecessor-version":[{"id":42346,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/28173\/revisions\/42346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/28174"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=28173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=28173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=28173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}