{"id":27801,"date":"2021-01-01T15:28:12","date_gmt":"2021-01-01T14:28:12","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=27801"},"modified":"2021-01-01T15:28:12","modified_gmt":"2021-01-01T14:28:12","slug":"buon-anno_2021","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/01\/01\/buon-anno_2021\/","title":{"rendered":"Buon Anno."},"content":{"rendered":"<p style=\"text-align: justify;\">Che questo 2021 possa essere un anno migliore per tutti.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Che possa portare felicita&#8217;, soldi, amore, fortuna e, soprattutto, salute a tutti quanti.<\/p>\n<p style=\"text-align: justify;\">Speriamo di poterci finalmente riabbracciare e proseguire il nostro cammino coltivando le nostre amicizie, sopravvissute a questa catastrofe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27802\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1609509790456-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1609509790456-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1609509790456-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1609509790456-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/01\/1609509790456-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Sorridendo guardiamo al futuro, che possa essere grandioso, senza farci abbattere.<\/p>\n<p style=\"text-align: justify;\">Ed anche quest&#8217;anno ho espresso i miei buoni propositi.<br \/>\nNon si discostano molto da quelli degli anni trascorsi, confido solamente nella mia <del>mancata<\/del> tenacia per portarli avanti.<br \/>\nUno tra questi, e&#8217; quello di cercare di bere ed idratarmi maggiormente.<\/p>\n<p style=\"text-align: justify;\">E voi?<br \/>\nChe cosa vi siete ripromessi per il nuovo anno?<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che questo 2021 possa essere un anno migliore per tutti.<\/p>\n","protected":false},"author":2,"featured_media":27803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-27801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=27801"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27801\/revisions"}],"predecessor-version":[{"id":27805,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27801\/revisions\/27805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/27803"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=27801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=27801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=27801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}