{"id":27621,"date":"2021-02-06T14:30:57","date_gmt":"2021-02-06T13:30:57","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=27621"},"modified":"2023-02-24T15:18:50","modified_gmt":"2023-02-24T14:18:50","slug":"ragu-senza-latte-pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/02\/06\/ragu-senza-latte-pap\/","title":{"rendered":"Ragu di carne, senza latte &#8211; in Pentola a Pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Come ben sapete, non esiste una sola ricetta per ogni preparazione culinaria.<br \/>\nOgni famiglia ha il suo segreto, ogni piccolo dettaglio fa la differenza del risultato, le varianti in gioco sono diverse e tra le piu disparate.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Molto spesso si acquistano tutti gli ingredienti indicati nella ricetta, seguendo pedissequamente la singola grammatura, altre volte si utilizzano gli ingredienti che si hanno in casa.<br \/>\nE se dovesse mancare qualche cosa? Semplice, si cambia improvvisando.<\/p>\n<p style=\"text-align: justify;\">Questa e&#8217; stata la mia ennesima ricetta per la preparazione del ragu&#8217;, preparato in pentola a pressione, evitando di sfumare la carne con il vino e sostituendo l&#8217;aggiunta del latte con un cucchiaino di zucchero, per rendere meno acida la passata di pomodoro.<\/p>\n<p><strong>Ingredienti &#8211; Ragu di carne &#8211; senza latte<\/strong><\/p>\n<pre>1000 gr di macinato di manzo (anche un misto)\r\n690 gr di passata di pomodoro (1 bottiglia)\r\n1 cipolla\r\n2 carota\r\n1 costa di sedano\r\n1 bicchiere di brodo <i>(o acqua)<\/i>\r\nnoce moscata\r\nolio\r\nsale\r\nzucchero<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Lavate e tritate finemente le verdure, tenendo la cipolla separata dalle altre due.<\/p>\n<p style=\"text-align: justify;\">Mettete nella pentola a pressione\u00c2\u00a0l&#8217;olio e la cipolla.<\/p>\n<figure id=\"attachment_27656\" aria-describedby=\"caption-attachment-27656\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27656\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901714-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901714-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901714-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901714-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901714-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27656\" class=\"wp-caption-text\">Ragu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Fate soffriggere quest&#8217;ultima lentamente, mescolando di tanto in tanto, finch\u00c3\u00a8 si sar\u00c3\u00a0 assorbita tutta l&#8217;acqua rilasciata.<br \/>\nAggiungete ora il sedano e la carota e fateli rosolare con la cipolla.<\/p>\n<figure id=\"attachment_27657\" aria-describedby=\"caption-attachment-27657\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27657\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901709-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901709-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901709-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901709-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901709-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27657\" class=\"wp-caption-text\">Ragu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Alzate la fiamma.<br \/>\nAggiungete la carne in 3-4 volte, sgranandola e attendendo che abbia cambiato colore prima di aggiungere la successiva.<br \/>\nQuando la carne sar\u00c3\u00a0 rosolata, versate il vino in diverse riprese <i>(per non far raffreddare la carne, facendolo scorrere lungo le pareti della pentola)<\/i> e fatelo evaporare completamente.<\/p>\n<figure id=\"attachment_27658\" aria-describedby=\"caption-attachment-27658\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27658\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901703-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901703-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901703-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901703-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901703-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27658\" class=\"wp-caption-text\">Ragu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Unite una generosa grattata di noce moscata, il sale, la passata di pomodoro ed il brodo.<\/p>\n<figure id=\"attachment_27659\" aria-describedby=\"caption-attachment-27659\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27659\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901697-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901697-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901697-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901697-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901697-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27659\" class=\"wp-caption-text\">Ragu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Chiudete la pentola a pressione e calcolate almeno 40 minuti dal sibilo (considerate che la cottura del ragu&#8217;, normalmente, e&#8217; di almeno 3 ore)<\/p>\n<figure id=\"attachment_27660\" aria-describedby=\"caption-attachment-27660\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27660\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901687-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901687-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901687-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901687-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608742901687-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27660\" class=\"wp-caption-text\">Ragu<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">L&#8217;idea e&#8217; quella di utilizzare questa preparazione , in seguito, per le lasagne.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27688\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/02\/1608829279898-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/02\/1608829279898-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/02\/1608829279898-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/02\/1608829279898-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/02\/1608829279898-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nGiusto per iniziare a testare il gusto, lo abbiamo messo come condimento su un piatto di gnocchi colorati.<br \/>\nNon mi resta che augurarvi.. buon appetito!<\/p>\n<figure id=\"attachment_27655\" aria-describedby=\"caption-attachment-27655\" style=\"width: 525px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27655\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608751267936-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608751267936-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608751267936-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608751267936-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608751267936-768x432.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1608751267936.jpg 1920w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27655\" class=\"wp-caption-text\">Ragu<\/figcaption><\/figure>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come ben sapete, non esiste una sola ricetta per ogni preparazione culinaria. Ogni famiglia ha il suo segreto, ogni piccolo dettaglio fa la differenza del risultato, le varianti in gioco sono diverse e tra le piu disparate.<\/p>\n","protected":false},"author":2,"featured_media":27655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22],"tags":[53,126],"class_list":["post-27621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","tag-pentola_a_pressione","tag-salsa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=27621"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27621\/revisions"}],"predecessor-version":[{"id":40978,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27621\/revisions\/40978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/27655"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=27621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=27621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=27621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}