{"id":27191,"date":"2020-12-06T16:00:27","date_gmt":"2020-12-06T15:00:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=27191"},"modified":"2020-12-06T15:48:25","modified_gmt":"2020-12-06T14:48:25","slug":"nikolaus-2020","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/12\/06\/nikolaus-2020\/","title":{"rendered":"Nikolaus 2020"},"content":{"rendered":"<p style=\"text-align: justify;\">Oggi e&#8217; un giorno abbastanza allegro qui in Germania\/Patatolandia.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Oltre a commemorare\u00c2\u00a0 <strong>Nikolaus<\/strong>, festa molto importante e famosa soprattutto per i bambini\u00c2\u00a0 (ma che noi certamente non disdegnamo dal festeggiarla), viene celebrata anche la seconda domenica di Avvento.<\/p>\n<p style=\"text-align: justify;\">Ecco alcune immagini scattate per quanto riguarda la festa di <strong>Nikolaus<\/strong> (San Nicola).<br \/>\nQui abbiamo le nostre &#8220;scarpe&#8221; posizionate<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27291\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511143-e1607248608832-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511143-e1607248608832-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511143-e1607248608832-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511143-e1607248608832-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511143-e1607248608832-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>I regali&#8230;<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27292\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511137-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511137-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511137-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511137-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511137-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27293\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511131-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511131-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511131-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511131-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607248511131-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Il <strong>Calendario dell&#8217;Avvento<\/strong> e&#8217; stato altro punto &#8220;dolente&#8221; quest&#8217;anno.<\/p>\n<p style=\"text-align: justify;\">Nonostante tutte le giornate trascorse a casa in questo 2020 (tra il lockdown, le mancate vacanze ed altro ancora), non ho avuto molte possibilita&#8217; nel creare qualche cosa di nuovo, proprio non mi sono sentita ispirata.<br \/>\nCosi&#8217; abbiamo deciso di riutilizzare il &#8220;Calendario&#8221; che avevamo allestito in casa lo<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2019\/12\/02\/adventkalendar-2019\/\"> scorso anno<\/a><\/strong><\/em>.<br \/>\nSolo spostandolo di finestra, per non inciampare tra le piante \ud83d\ude09<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27193\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606679623040-1024x787.jpg\" alt=\"\" width=\"525\" height=\"403\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606679623040-1024x787.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606679623040-150x115.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606679623040-300x231.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606679623040-768x590.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Come potete notare dalla foto inserita in questo post, non tutte le 24 finestre (ossia le bustine dei relativi giorni del mese di dicembre fino alla Vigilia di Natale) sono presenti ed attaccate.<br \/>\nCosa posso notare&#8230; se non la pochezza di fantasia e mancanza di inventiva dei miei familiari, tanto da rattristarmi molto.<br \/>\nC&#8217;est la vie!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27192\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606820943941-e1606840319881-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606820943941-e1606840319881-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606820943941-e1606840319881-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606820943941-e1606840319881-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1606820943941-e1606840319881-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ma non demordo. A furia di incoraggiarli nel prepare qualche cosa, magari riusciro&#8217; a raggiungere un minimo risultato.<\/p>\n<p style=\"text-align: justify;\">Fortunatamente ce la caviamo con i calendari &#8220;alternativi&#8221; a base di cioccolato.<br \/>\nLa nostra &#8220;gola&#8221;, come sapete, non ha limiti!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27290\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607184037027-1024x512.jpg\" alt=\"\" width=\"525\" height=\"263\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607184037027-1024x512.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607184037027-150x75.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607184037027-300x150.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1607184037027-768x384.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">E voi, come siete messi con il Calendario?<br \/>\nQualche golosita&#8217;?<\/p>\n<p>Il Nonno, poi, ci ha spedito un simpatico link dove si possono sentire 24 canzoni natalizie, giusto per entrare nella corretta atmosfera \ud83d\ude42<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi e&#8217; un giorno abbastanza allegro qui in Germania\/Patatolandia.<\/p>\n","protected":false},"author":2,"featured_media":27290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[99,123],"class_list":["post-27191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-avvento","tag-festa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=27191"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27191\/revisions"}],"predecessor-version":[{"id":27298,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27191\/revisions\/27298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/27290"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=27191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=27191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=27191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}