{"id":27086,"date":"2021-02-25T14:14:44","date_gmt":"2021-02-25T13:14:44","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=27086"},"modified":"2021-04-17T10:02:10","modified_gmt":"2021-04-17T08:02:10","slug":"beluga-topinambur-pecorino","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/02\/25\/beluga-topinambur-pecorino\/","title":{"rendered":"Budino con lenticchie Beluga al topinambur e pecorino."},"content":{"rendered":"<p style=\"text-align: justify;\">Quest&#8217;oggi ho voluto cercare un modo diverso per preparare i <strong>topinambur<\/strong> acquistati.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non ricordo bene come, ma mi sono trovata <em><strong><a href=\"https:\/\/www.melandrigaudenzio.com\/ricetta.aspx?id=1000\">questa<\/a><\/strong><\/em> pagina e la ricetta proposta che, non lo nascondo, mi ha stuzzicato molto.<br \/>\nNon solo per l&#8217;accostamento degli ingredienti, ma anche della facilita&#8217; del loro reperimento che, stranamente, avevo tutto a casa.<\/p>\n<p style=\"text-align: justify;\">E&#8217; stata la prima volta, poi, che ho anche cotto a bagnomaria, stile di cottura che non mi si addice proprio.<\/p>\n<p><strong>Ingredienti<\/strong> &#8211; <strong>Budino Beluga al topinambur e pecorino &#8211; per 4 persone<\/strong><\/p>\n<pre>200 g di topinambur\r\n140 gr di panna fresca\r\n90 gr di albumi\r\n80 g di lenticchie nere Beluga\r\n60 gr di pecorino\r\nsale, pepe nero\r\nolio di semi di arachidi<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preparate le lenticchie come indicato sulla confezione, scolatele e tenete da parte.<\/p>\n<p>(<em>Sono stata incerta sino alla fine su come cuocerle. Alla fine ho deciso per la pentola a pressione, nonostante erano veramente poche le lenticchie beluga utilizzate: 13 minuti dal fischio)<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27090\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009170-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009170-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009170-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009170-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009170-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Nel frattempo sbucciate il topinambur, pesatene 110 grammi e tagliatelo a cubetti, lavatelo e cuocetelo in acqua bollente.<br \/>\nIl restante topinambur conservatelo all&#8217;interno di una ciotola con acqua fresca.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27092\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009159-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009159-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009159-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009159-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009159-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27093\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009154-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009154-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009154-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009154-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009154-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">In un tegamino fate scaldare la panna e fatevi sciogliere il pecorino grattugiato, fate raffreddare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27091\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009165-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009165-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009165-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009165-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009165-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Sbattete gli albumi con una forchetta, unite la panna con il pecorino ed il topinambur, regolate di sale e pepe e frullate con un mixer ad immersione fino ad ottenere una crema liscia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27094\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009148-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009148-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009148-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009148-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009148-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27095\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009143-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009143-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009143-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009143-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009143-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mettete un cucchiaio di lenticchie sul fondo di ogni stampino monoporzione e riempite per \u00c2\u00be con la crema di topinambur. Unite alla crema rimasta 4 cucchiai di lenticchie e frullate.<br \/>\nVersate il composto ottenuto negli stampini molto delicatamente fino a riempirli, fate attenzione a non mescolare i due composti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27097\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009132-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009132-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009132-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009132-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009132-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Scaldate il forno a 160\u00c2\u00b0C con all&#8217;interno una teglia piena di acqua per met\u00c3\u00a0. Mettetevi dentro gli stampini, l&#8217;acqua dovr\u00c3\u00a0 arrivare alla loro met\u00c3\u00a0.<br \/>\nCuocete 40 minuti, se la superficie dovesse iniziare a scurire coprite con un foglio di alluminio.<\/p>\n<figure id=\"attachment_27096\" aria-describedby=\"caption-attachment-27096\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27096 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009137-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009137-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009137-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009137-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009137-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27096\" class=\"wp-caption-text\">Budino Beluga al topinambur e pecorino.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Togliete dal forno e prelevate gli stampini dalla teglia.<br \/>\nFate intiepidire poi passate un coltello tra lo stampino e lo sformato in modo da facilitare la sua espulsione.<\/p>\n<figure id=\"attachment_27098\" aria-describedby=\"caption-attachment-27098\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27098 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009127-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009127-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009127-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009127-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009127-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27098\" class=\"wp-caption-text\">Budino Beluga al topinambur e pecorino.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Rovesciate ogni sformato sul piatto da portata.<br \/>\nTagliate a fette sottili il topinambur rimasto e friggetelo in olio bollente pochi minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27099\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009116-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009116-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009116-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009116-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009116-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Servite gli sformati con le chips di topinambur e le lenticchie rimaste.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27100\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009101-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009101-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009101-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009101-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606243009101-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">come dicevo precedentemente, ho preferito cuocere le lenticchie beluga in pentola a pressione. Sulla confezione era scritto di cuocerle per 30 minuti (nel caso in cui non fossero state in ammollo) mentre le ho tenute in pentola per 13 minuti dal fischio. Magari qualche minuto in meno e sarebbero state perfette.<br \/>\nPer la quantita&#8217; di acqua utilizzata&#8230; non avendo particolari problemi, non la ho misurata ma erano totalmente sommerse<\/li>\n<li style=\"text-align: justify;\">Come stampini non ho usato quelli di alluminio, ma quelli di ceramica. Ho pensato troppo tardi che impiegano piu&#8217; tempo a scaldarsi, cosi&#8217; quando ho sformato si e&#8217; distrutto un po&#8217; (tanto) il budino di lenticchie.<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quest&#8217;oggi ho voluto cercare un modo diverso per preparare i topinambur acquistati.<\/p>\n","protected":false},"author":2,"featured_media":27098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,22,61],"tags":[55,53],"class_list":["post-27086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antipasti","category-food","category-uova-formaggio","tag-legumi","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=27086"}],"version-history":[{"count":7,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27086\/revisions"}],"predecessor-version":[{"id":30725,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27086\/revisions\/30725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/27098"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=27086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=27086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=27086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}