{"id":27076,"date":"2020-11-28T14:12:22","date_gmt":"2020-11-28T13:12:22","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=27076"},"modified":"2022-01-22T15:35:34","modified_gmt":"2022-01-22T14:35:34","slug":"bulgaria_bob-chorba","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/11\/28\/bulgaria_bob-chorba\/","title":{"rendered":"# 111 &#8211; Repubblica di Bulgaria. Bob Chorba &#8211; Bulgarian monastery-style"},"content":{"rendered":"<p style=\"text-align: justify;\">La <strong>Bulgaria<\/strong>, ufficialmente<strong> Repubblica di Bulgaria<\/strong> (in bulgaro \u00d0\u2018\u00d1\u0160\u00d0\u00bb\u00d0\u00b3\u00d0\u00b0\u00d1\u20ac\u00d0\u00b8\u00d1\u008f\/B\u00c4\u0192lgarija, \/b\u00c9\u00a4l\u00cb\u02c6garij\u00c9\u2122\/; ufficialmente \u00d0\u00a0\u00d0\u00b5\u00d0\u00bf\u00d1\u0192\u00d0\u00b1\u00d0\u00bb\u00d0\u00b8\u00d0\u00ba\u00d0\u00b0 \u00d0\u2018\u00d1\u0160\u00d0\u00bb\u00d0\u00b3\u00d0\u00b0\u00d1\u20ac\u00d0\u00b8\u00d1\u008f, Republika B\u00c4\u0192lgarija, \/r\u00c9\u203a\u00cb\u02c6publi\u00cb\u0152k\u00c9\u2122 b\u00c9\u00a4l\u00cb\u02c6garij\u00c9\u2122\/), e&#8217; uno Stato membro dell&#8217;Unione europea situato nella meta&#8217; orientale della penisola balcanica.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">La sua posizione l&#8217;ha resa nel corso della storia un importante incrocio per varie civilizzazioni ed e&#8217; infatti il luogo di ritrovamento di alcuni dei piu&#8217; antichi artefatti metallurgici, religiosi e culturali al mondo.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Alcune culture preistoriche iniziarono a evolversi nelle terre bulgare durante il Neolitico. Inizialmente furono abitate dai Traci e successivamente dai Greci e dai Romani.<\/p>\n<p style=\"text-align: justify;\">Il 99,8% della popolazione bulgara parla il bulgaro, appartenente alle lingue slave. Il bulgaro u&#8217; l&#8217;unica lingua ufficiale della Bulgaria, ma al suo interno sono parlate anche altre lingue che corrispondono strettamente alle varie minoranze etniche.<\/p>\n<p style=\"text-align: justify;\">La capitale e&#8217; <em>Sofia.<\/em><\/p>\n<p style=\"text-align: justify;\">In queste serata freschine una zuppa ci sta veramente bene, soprattutto per riscaldare il corpo e, una volta tanto, evitare anche di mangiare proteine animali.<\/p>\n<p style=\"text-align: justify;\">La <strong>Bob chorba<\/strong> (&#8220;<strong>Zuppa di fagioli&#8221;<\/strong>) \u00c3\u00a8 un chorba, ossia una zuppa bulgara; e&#8217; costituita principalmente da fagioli secchi, cipolle, pomodori, chubritza o dzhodzhen (menta verde) e carote.<br \/>\nLe varianti locali possono anche escludere le carote o includere paprika, patate o anche qualche tipo di carne. Storicamente e&#8217; stata una zuppa comune e un alimento base nei monasteri bulgari, da qui il nome.<\/p>\n<p style=\"text-align: justify;\">E&#8217; uno tra i piatti nazionali della Bulgaria, e come si puo&#8217; immaginare esistono diverse versioni, ma quella vegetariana e&#8217; quella piu&#8217; apprezzata.<\/p>\n<p>La ricetta che ho seguito per la preparazione di questa &#8220;chorba&#8221; e&#8217; la seguente ( http:\/\/www.undertheandalusiansun.com\/2016\/12\/bob-chorba-bulgarian-monastery-style.html )<\/p>\n<p><strong>Ingredienti &#8211; Bob Chorba &#8211; Zuppa di fagioli in stile monastico bulgaro<\/strong> &#8211; per 6 persone<\/p>\n<pre>2 cipolle grandi\r\n3 carote di media grandezza\r\n2 spicchi d'aglio grandi, tritati\r\n1\/2 cucchiaio di paprika dolce\r\n1 cucchiaino di peperoncino in fiocchi\r\n1\/2 dl di concentrato di pomodoro\r\n1\/2 cucchiaio di zucchero\r\n1 cucchiaino di sale\r\n1 cucchiaino di pepe nero appena macinato\r\n3 barattoli (a 400 g \/ 240 g) di fagioli bianchi grandi, scolati e risciacquati\r\n1 1\/4 l di brodo vegetale o di pollo\r\n4 cucchiai di menta verde fresca (o 2 cucchiai essiccati), tritati grossolanamente\r\n1\/2 dl di olio\r\n\r\n<strong>Per servire<\/strong>: prezzemolo a foglia piatta tritato<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tagliate le carote e le cipolle a cubetti.<\/p>\n<p style=\"text-align: justify;\">Soffriggetele nell&#8217;olio in una pentola con l&#8217;aglio fino a quando la cipolla non sara&#8217; trasparente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27107\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412331-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412331-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412331-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412331-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412331-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la paprika, i fiocchi di peperoncino, il concentrato di pomodoro e lo zucchero. Condite con sale e pepe.<\/p>\n<p>Continuate a mescolare gli ingredienti per altri 5 minuti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27108\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412296-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412296-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412296-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412296-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412296-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27109\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412262-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412262-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412262-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412262-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412262-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nQuindi aggiungete i fagioli e il brodo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27110\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412227-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412227-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412227-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412227-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412227-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lasciate cuocere, coperto, a fuoco medio per un&#8217;ora (oppure in pentola a pressione come ho fatto io, diminuendone i tempi).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27111\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412186-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412186-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412186-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412186-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412186-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Rimuovete circa un mestolo di fagioli e un mestolo di brodo. Inseriteli in un robot da cucina e frullateli fino a renderli omogenei (cosi&#8217; da aiutare ad addensare la zuppa).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27112\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412160-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412160-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412160-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412160-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412160-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Reinserite il \u00e2\u20ac\u2039\u00e2\u20ac\u2039composto di fagioli frullato nella pentola. Aggiungete la menta e continuate a cuocere per altri 5 minuti.<\/p>\n<p style=\"text-align: justify;\">Controllate il gusto e aggiungete altro sale, pepe e\/o paprika se necessario.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27113\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412144-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412144-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412144-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412144-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606478412144-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Dividete in ciotole, cospargete di prezzemolo e servite.<\/p>\n<figure id=\"attachment_27115\" aria-describedby=\"caption-attachment-27115\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-27115\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606550688339-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606550688339-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606550688339-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606550688339-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1606550688339-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-27115\" class=\"wp-caption-text\">Bulgaria. Bob Chorba &#8211; Bulgarian monastery-style<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li>Al posto del concentrato di pomodoro, ho inserito della passata.<\/li>\n<li>La mia cottura e&#8217; stata effettuata in pentola a pressione, 23 minuti dal fischio e sfiato naturale.<\/li>\n<li style=\"text-align: justify;\">Stranamente e&#8217; piaciuta anche a Tobias,\u00c2\u00a0 probabilmente a causa dello zucchero inserito nel brodo, cosi&#8217; da renderla piu&#8217; dolciastra.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La <strong>cucina bulgara<\/strong> e&#8217; simile a quella degli altri popoli della penisola balcanica e mostra una forte influenza turca e greca.<br \/>\nTra i cibi piu&#8217; rinomati si possono trovare lo <strong>yoghurt<\/strong>, la <strong>lukanka<\/strong> (salame tipico), la <strong>banitsa<\/strong> (mix di uova sbattute e pezzi di s\u00c3\u00acrene ( formaggio bulgaro, simile alla feta) tra dei fogli di pasta e cotta al forno) , la <strong>\u00c5\u00a1opska salata<\/strong> (insalata di verdure tagliata a cubetti e preparata con pomodori, cetrioli, peperoni verdi, cipolle e formaggio sirene), la <strong>ljutenica<\/strong> (condimento a base di verdure) e il <strong>kozunak<\/strong> (dolce tipico del periodo di Pasqua), ma sono presenti altri piatti di origine tipicamente balcanica o medio-orientale come la musak\u00c3\u00a0, il gjuve\u00c4\u008d e la baklava.<br \/>\nIl consumo di carne e&#8217; inferiore alla media europea e si riscontra una notevole prevalenza per una gran quantita&#8217; di piatti di insalata e verdure.<br \/>\nLa rakija \u00c3\u00a8 un superalcolico tradizionale a base di frutta, che veniva consumato in Bulgaria gia&#8217; nel XIV secolo.<br \/>\nTra i vini bulgari pi\u00c3\u00b9 noti \u00c3\u00a8 possibile trovare tipi di traminer, moscati e di mavrud. Fino al 1989 la Bulgaria era il secondo esportatore di vino al mondo.<\/p>\n<p>\u00d0\u00bf\u00d1\u20ac\u00d0\u00b8\u00d1\u008f\u00d1\u201a\u00d0\u00b5\u00d0\u00bd \u00d0\u00b0\u00d0\u00bf\u00d0\u00b5\u00d1\u201a\u00d0\u00b8\u00d1\u201a<br \/>\npriyaten apetit<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bulgaria, ufficialmente Repubblica di Bulgaria (in bulgaro \u00d0\u2018\u00d1\u0160\u00d0\u00bb\u00d0\u00b3\u00d0\u00b0\u00d1\u20ac\u00d0\u00b8\u00d1\u008f\/B\u00c4\u0192lgarija, \/b\u00c9\u00a4l\u00cb\u02c6garij\u00c9\u2122\/; ufficialmente \u00d0\u00a0\u00d0\u00b5\u00d0\u00bf\u00d1\u0192\u00d0\u00b1\u00d0\u00bb\u00d0\u00b8\u00d0\u00ba\u00d0\u00b0 \u00d0\u2018\u00d1\u0160\u00d0\u00bb\u00d0\u00b3\u00d0\u00b0\u00d1\u20ac\u00d0\u00b8\u00d1\u008f, Republika B\u00c4\u0192lgarija, \/r\u00c9\u203a\u00cb\u02c6publi\u00cb\u0152k\u00c9\u2122 b\u00c9\u00a4l\u00cb\u02c6garij\u00c9\u2122\/), e&#8217; uno Stato membro dell&#8217;Unione europea situato nella meta&#8217; orientale della penisola balcanica.<\/p>\n","protected":false},"author":2,"featured_media":27077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,22,51,57],"tags":[176,244,55,53],"class_list":["post-27076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-food","category-primi_piatti","category-zuppa","tag-176","tag-europa_est","tag-legumi","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=27076"}],"version-history":[{"count":14,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27076\/revisions"}],"predecessor-version":[{"id":31498,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/27076\/revisions\/31498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/27077"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=27076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=27076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=27076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}