{"id":26853,"date":"2021-10-13T14:54:46","date_gmt":"2021-10-13T12:54:46","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=26853"},"modified":"2021-05-04T17:26:28","modified_gmt":"2021-05-04T15:26:28","slug":"come-pulire-una-padella-incrostata","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/10\/13\/come-pulire-una-padella-incrostata\/","title":{"rendered":"Come pulire una padella incrostata"},"content":{"rendered":"<p style=\"text-align: justify;\">Con tutto questo cucinare il lavaggio dei piatti viene fatto nella grande maggioranza dei casi direttamente dalla mia lavastoviglie.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non vi nascondo, pero&#8217;, che molto spesso lo faccio a mano, per diverse ragioni:<\/p>\n<ul>\n<li style=\"text-align: justify;\">ho un numero limitato di piatti\/pentole che, spesso, utilizzo piu&#8217; di una volta al giorno<\/li>\n<li style=\"text-align: justify;\">solitamente se la lavastoviglie e&#8217; ancora vuota, faccio prima a lavare le tazzine che non a caricarla direttamente<\/li>\n<li style=\"text-align: justify;\">non faccio andare la lavastoviglie tutti i giorni<\/li>\n<li style=\"text-align: justify;\">mi rilassa, mi fa pensare e mi vengono in mente brillanti idee su cosa fare (o far fare \ud83d\ude09 )<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Altre volte mi trovo spesso ad avere la padella-griglia (solitamente usata per cucinare le bistecche) piena di unto ed incrostata e che, comunque, questa tipologia di pentola non puo&#8217; essere lavata in lavastoviglie.<\/p>\n<p style=\"text-align: justify;\">Come tentare di alleviare lo sporco senza doversi dannare troppo?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26860\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173533-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173533-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173533-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173533-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173533-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Personalmente ho trovato la soluzione: il <strong>sale<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26859\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173725-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173725-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173725-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173725-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_173725-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Dopo aver bagnato la padella, la cospargo di sale grosso, poi con la paglietta ed il sapone liquido proseguo con una bella strofinata ed una sciacquata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26856\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200910_193205-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200910_193205-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200910_193205-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200910_193205-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200910_193205-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Per ora questa e&#8217; la mia soluzione al problema e, almeno per me, pare proprio funzionare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26857\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_174142-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_174142-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_174142-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_174142-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/IMG_20200721_174142-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Voi come fate?<br \/>\nQuale soluzione adottate?<\/p>\n<p>Inutile affermare che questa soluzione <strong>NON<\/strong> e&#8217; fattibile per tutte le tipologie di padelle!<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con tutto questo cucinare il lavaggio dei piatti viene fatto nella grande maggioranza dei casi direttamente dalla mia lavastoviglie.<\/p>\n","protected":false},"author":2,"featured_media":26859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,58],"tags":[],"class_list":["post-26853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-curiosita"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=26853"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26853\/revisions"}],"predecessor-version":[{"id":31032,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26853\/revisions\/31032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/26859"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=26853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=26853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=26853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}