{"id":26748,"date":"2020-12-19T14:47:54","date_gmt":"2020-12-19T13:47:54","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=26748"},"modified":"2022-12-27T15:12:17","modified_gmt":"2022-12-27T14:12:17","slug":"canederlispeck-speckknoedel","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/12\/19\/canederlispeck-speckknoedel\/","title":{"rendered":"Canederli allo speck in brodo &#8211; Speckkn\u00c3\u00b6del"},"content":{"rendered":"<p style=\"text-align: justify;\">Cosa preparare di sera per tentare di combattere queste temperature non proprio estive?<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Eccomi quindi con una preparazione, per la prima volta, bavarese\/alto atesina\/tirolese:<\/p>\n<p><strong>Canederli allo speck in brodo \/ Speckknoedel<\/strong><\/p>\n<p>Vedete voi come volete considerarla, da parte mia posso semplicemente dire che e&#8217; stata ottima e mi ha decisamente soddisfatto.<br \/>\nNon e&#8217; assolutamente difficile da preparare e la potete replicare a casa facilmente.<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Canederli allo speck in brodo \/ Speckkn\u00c3\u00b6del<\/strong> &#8211; 4 persone<\/p>\n<pre>3 panini del giorno prima (*)\r\n150gr di speck\r\n1 cipolla piccola\r\n1 mazzetto di prezzemolo\r\n25gr di burro\r\n1 uovo (M)\r\n150ml di latte\r\nsale, pepe\r\n1 cucchiaio di farina\r\n\r\n150gr di carote\r\n1 porro\r\n80gr di dado di manzo (*)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Tagliate il pane a cubetti, nel caso in cui non utilizziate del composto gia&#8217; pronto, mettendolo in una capiente ciotola.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26754\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070761-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070761-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070761-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070761-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070761-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nRimuovete l&#8217;eventuale cotenna alla pancetta e tagliatela finemente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26750\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070783-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070783-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070783-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070783-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070783-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Pelate la cipolla e tagliatela a dadini.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26751\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070777-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070777-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070777-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070777-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070777-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lavate e tritate finemente il prezzemolo, mettendone da parte un cucchiaio che verra&#8217; utilizzato per guarnire il piatto.<\/p>\n<p style=\"text-align: justify;\">Sciogliete il burro in una padella, soffriggete la pancetta e rimuovetene un cucchiaio, tenendolo da parte.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26752\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070772-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070772-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070772-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070772-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070772-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete la cipolla nella padella e soffriggetela brevemente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26753\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070767-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070767-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070767-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070767-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070767-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26755\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070756-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070756-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070756-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070756-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070756-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete il composto pancetta-cipolla al pane.<\/p>\n<p style=\"text-align: justify;\">Mischiate l&#8217;uovo al latte, poi versatelo sul pane, salate e pepate.<br \/>\nSpolverizzate il composto con il cucchiaio di farina, mescolate molto bene, aiutandovi con le mani.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26756\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070749-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070749-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070749-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070749-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070749-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lasciate riposare per circa 30 minuti, cosi&#8217; che il pane assorba il liquido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26757\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070744-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070744-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070744-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070744-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070744-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26758\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070738-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070738-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070738-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070738-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070738-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mondate, pelate e lavate le carote, tagliatele a bastoncini sottili.<br \/>\nMondate e lavate il porro, tagliatelo a striscioline lunghe circa 7cm (*).<\/p>\n<p style=\"text-align: justify;\">Impastate nuovamente bene il composto per i canederli, formando 12 gnocchi con le mani umide.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26759\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070727-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070727-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070727-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070727-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070727-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Versate in acqua bollente salata e lasciate in infusione per circa 10 minuti, a fuoco basso.<\/p>\n<p style=\"text-align: justify;\">Portate a ebollizione 1 litro di acqua, aggiungete le carote e la pasta di manzo\/dado (o cosa volete utilizzare) per la preparazione del brodo, lasciate sobbollire per 5 minuti.<br \/>\nAggiungete il porro e la pancetta (il cucchiaio lasciato a parte) e cuocete per altri 2-3 minuti.<br \/>\nAggiustate di sale e pepe a seconda del gusto personale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26760\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070722-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070722-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070722-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070722-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070722-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Scolate gli gnocchi dall&#8217;acqua, con una schiumarola, e scolateli bene.<br \/>\nDivideteli in 4 piatti profondi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26761\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070717-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070717-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070717-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070717-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070717-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<figure id=\"attachment_26762\" aria-describedby=\"caption-attachment-26762\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26762 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070711-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070711-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070711-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070711-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070711-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26762\" class=\"wp-caption-text\">Canederli allo speck in brodo &#8211; Speckkn\u00c3\u00b6del<\/figcaption><\/figure>\n<p>Versate il brodo.<\/p>\n<figure id=\"attachment_26763\" aria-describedby=\"caption-attachment-26763\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26763 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070699-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070699-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070699-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070699-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070699-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26763\" class=\"wp-caption-text\">Canederli allo speck in brodo &#8211; Speckkn\u00c3\u00b6del<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cospargete e guarnite il piatto con il prezzemolo lasciato a parte.<\/p>\n<figure id=\"attachment_26764\" aria-describedby=\"caption-attachment-26764\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26764 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070691-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070691-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070691-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070691-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/12\/1605293070691-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26764\" class=\"wp-caption-text\">Canederli allo speck in brodo &#8211; Speckkn\u00c3\u00b6del<\/figcaption><\/figure>\n<p>Servite subito!<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Non avendo voglia di tagliuzzare, avevo in casa del pane gia&#8217; adatto allo scopo. Qui viene venduto normalmente al supermercato, mentre in panetteria si trovano spesso i prezel gia&#8217; sminuzzati<\/li>\n<li style=\"text-align: justify;\">Per il brodo ho utilizzato un concentrato gia&#8217; pronto, al quale ho aggiunto un po&#8217; di acqua per allungarlo ma anche per arrivare alla quantita&#8217; necessaria<\/li>\n<li style=\"text-align: justify;\">Il mio porro era surgelato, cosi&#8217; era tagliato a rondelle<\/li>\n<\/ul>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosa preparare di sera per tentare di combattere queste temperature non proprio estive?<\/p>\n","protected":false},"author":2,"featured_media":26764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,22,91,51,57],"tags":[236],"class_list":["post-26748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-food","category-pane","category-primi_piatti","category-zuppa","tag-europa_centrale"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=26748"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26748\/revisions"}],"predecessor-version":[{"id":40148,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26748\/revisions\/40148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/26764"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=26748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=26748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=26748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}