{"id":26523,"date":"2020-11-15T15:18:16","date_gmt":"2020-11-15T14:18:16","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=26523"},"modified":"2022-01-23T14:44:47","modified_gmt":"2022-01-23T13:44:47","slug":"paesi-bassi_hutspot","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/11\/15\/paesi-bassi_hutspot\/","title":{"rendered":"# 108 &#8211; Regno dei Paesi Bassi. Hutspot."},"content":{"rendered":"<p style=\"text-align: justify;\">I <strong>Paesi Bassi<\/strong> (in lingua olandese Nederland [\u00cb\u02c6ne\u00cb\u0090d\u00c9\u2122rl\u00c9\u2018nt]), spesso impropriamente indicati anche dagli stessi abitanti come <strong>Olanda<\/strong>, sono una delle quattro nazioni costitutive del Regno dei Paesi Bassi.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Si trovano principalmente in Europa ma comprendono anche i cosiddetti Paesi Bassi caraibici (isole di Bonaire, Saba e Sint Eustatius, che hanno lo status di municipalita&#8217; speciali) in riferimento alla sua bassa elevazione e alla sua topografia piatta, con solo il 50% circa del suo territorio che supera 1 metro sopra il livello del mare e quasi il 26% che scende sotto il livello del mare.<\/p>\n<p style=\"text-align: justify;\">La sua capitale e&#8217; <em>Amsterdam<\/em>.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">I Paesi Bassi hanno avuto un vasto impero coloniale che, al momento della sua massima espansione (XVII secolo), ne fece la principale potenza del commercio mondiale e la culla del capitalismo.<\/p>\n<p style=\"text-align: justify;\">In italiano (e in numerose altre lingue) i termini Paesi Bassi e Olanda sono spesso utilizzati come sinonimi. In realta&#8217; il termine Olanda identifica soltanto due delle dodici province che formano i Paesi Bassi: l&#8217;Olanda Settentrionale e l&#8217;Olanda Meridionale<\/p>\n<p style=\"text-align: justify;\">Il termine &#8220;olandese&#8221; viene anche comunemente usato per indicare la lingua principale dei Paesi Bassi (parlata anche nelle Fiandre settentrionali, parte nederlandofona del Belgio), mentre a stretto rigore esso identifica i soli dialetti parlati nelle province dell&#8217;Olanda Settentrionale e dell&#8217;Olanda Meridionale; il termine neerlandese (o nederlandese) e&#8217; il pi\u00c3\u00b9 corretto per identificare questa lingua, ma in italiano viene usato quasi esclusivamente in ambito accademico.<\/p>\n<p style=\"text-align: justify;\">Originario del 1600, lo <strong>stamppot<\/strong> e&#8217; una delle piu&#8217; antiche ricette olandesi che rimane popolare oggi.<br \/>\nLe tradizionali ricette olandesi di stamppot utilizzano il pure&#8217; di patate come base, quindi incorporano una verdura (piu&#8217; spesso crauti, cavoli, indivia, spinaci e cime di rapa) e talvolta una carne, rendendo il piatto di comfort per eccellenza.<br \/>\nNon ci sono regole reali su cio&#8217; che va in uno stamppot, quindi la varieta&#8217; e&#8217;\u00c2\u00a0 infinita, e nasce come piatto invernale.<br \/>\nUno dei primi stamppots creati e&#8217; il <strong>hutspot<\/strong>, nato dalla &#8220;Guerra degli ottant&#8217;anni&#8221; degli olandesi con la Spagna.<br \/>\nLa storia racconta che quando i soldati spagnoli fuggirono, si lasciarono dietro dei pezzi di uno stufato che l&#8217;olandese affamato accolse e chiamo&#8217; hutspot, che significa &#8220;<strong>pentola mista<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingredienti<\/strong> per l&#8217;<em><strong><a href=\"https:\/\/www.thedutchtable.com\/search\/label\/Hutspot%20met%20klapstuk%20%28Dutch%20carrot%20mashed%20potatoes%20with%20braised%20beef%29\">Hutspot<\/a><\/strong><\/em><\/p>\n<pre>6 patate grandi, sbucciate e tagliate in quarti\r\n8 carote grandi, sbucciate e tagliate a cubetti\r\n4 cipolle grandi, sbucciate e affettate\r\n2 tazze d'acqua\r\npizzico di sale<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete le patate sbucciate e tagliate in quattro sul fondo di un forno olandese in ghisa (dutch oven).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26798\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265567-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265567-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265567-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265567-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265567-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26799\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265561-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265561-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265561-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265561-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265561-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Versate l&#8217;acqua in modo che le patate siano appena coperte. Aggiungete il pizzico di sale.<br \/>\nMettete sopra le carote e finite con le cipolle.<br \/>\nCoprite e portate a ebollizione, quindi abbassate la fiamma e fate bollire per circa 20 minuti o fino a quando le patate saranno cotte.<br \/>\nVersate l&#8217;acqua di cottura, ma conservarla.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26801\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265490-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265490-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265490-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265490-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265490-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Schiacciate le patate, le carote e le cipolle fino ad ottenere una consistenza o lasciate dei grumi piu&#8217; grandi, ma questa e&#8217; una preferenza personale e va molto a gusto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26800\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265496-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265496-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265496-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265496-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265496-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Se avete bisogno di piu&#8217; liquido per rendere l&#8217;hutspot piu&#8217; liscio, aggiungete un cucchiaio di liquido di cottura alla volta.<br \/>\nAssaggiate, aggiustate di sale e pepe.<\/p>\n<figure id=\"attachment_26802\" aria-describedby=\"caption-attachment-26802\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26802 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265479-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265479-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265479-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265479-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1605446265479-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26802\" class=\"wp-caption-text\">Paesi Bassi. Hutspot.<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Nonostante la facilita&#8217; della preparazione, ho usato la pentola a pressione per la cottura, con il relativo cestello.<\/li>\n<li style=\"text-align: justify;\">La verdura inserita e&#8217; stata tagliata a cubetti ed ho cotto circa 8 minuti dal fischio.<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">La <strong>cucina olandese<\/strong> (Nederlandse keuken) rappresenta l&#8217;insieme delle tradizioni gastronomiche e alimentari sviluppatesi negli ultimi secoli nei Paesi Bassi.<br \/>\nCaratterizzata per essere una cucina poco elaborata e ricca di calorie, deve parte del suo sviluppo anche al passato coloniale del paese, che l&#8217;ha messo in contatto con culture e quindi cucine differenti, quali quella indonesiana, surinamese e antillana.<br \/>\nGeneralmente, nei Paesi Bassi, come in molti altri paesi del nord Europa, il pasto principale e&#8217; quello serale, tra le 18 e le 19, composto di solito da un piatto unico, preceduto eventualmente da una zuppa o seguito da un dolce.<br \/>\nPer questo motivo i piatti in cui meglio si esprime la tradizione culinaria dei Paesi Bassi sono quelli unici.<br \/>\nNel periodo natalizio non puo&#8217; proprio mancare lo stamppot, tipica ricetta della tradizione olandese e re incontrastato delle feste. Questo gustoso piatto unico e&#8217; costituito da un pure&#8217; di patate con verdure, servito caldo insieme a bacon o salsiccia affumicata.<br \/>\nIl nome deriva dallo stamper, il corrispettivo olandese nel nostro schiacciapatate.<\/p>\n<p>Eet smakelijk<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Paesi Bassi (in lingua olandese Nederland [\u00cb\u02c6ne\u00cb\u0090d\u00c9\u2122rl\u00c9\u2018nt]), spesso impropriamente indicati anche dagli stessi abitanti come Olanda, sono una delle quattro nazioni costitutive del Regno dei Paesi Bassi.<\/p>\n","protected":false},"author":2,"featured_media":26524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,168,22],"tags":[176,249,241,53],"class_list":["post-26523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-europa","category-food","tag-176","tag-dutch_oven","tag-europa_ovest","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=26523"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26523\/revisions"}],"predecessor-version":[{"id":31650,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26523\/revisions\/31650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/26524"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=26523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=26523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=26523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}