{"id":26475,"date":"2020-11-17T14:20:15","date_gmt":"2020-11-17T13:20:15","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=26475"},"modified":"2021-04-17T10:15:34","modified_gmt":"2021-04-17T08:15:34","slug":"coniglio-panna-rosmarino-pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/11\/17\/coniglio-panna-rosmarino-pap\/","title":{"rendered":"Coniglio alla panna e rosmarino &#8211; in Pentola a Pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Quando ero piccola, la mia mamma cucinava qualche volta il &#8220;<strong>coniglio alla panna<\/strong>&#8221; e, ricordo, aveva un sapore sorprendentemente buono.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Da quando lei non c&#8217;e&#8217; piu&#8217;, ed io abito qui a Patatolandia, non l&#8217;ho preparato solamente una volta ma non vedo perche&#8217; devo sempre cucinare cio&#8217; che piace a loro, per lo meno i loro ingredienti \ud83d\ude09 , e mai qualche cosa per me.<\/p>\n<p style=\"text-align: justify;\">Proseguendo il nostro giro del mondo, ed oltrepassando le 100 Nazioni, sono riuscita ad evitare la besciamella, il formaggio ed ho inserito i funghi una sola volta..<\/p>\n<p style=\"text-align: justify;\">Quindi, se per una volta tanto si prepara qualche portata diversa, non ne vedo il problema.<\/p>\n<p style=\"text-align: justify;\">La ricetta che seguiva la mia mamma la potete trovare in questo Post (<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2015\/06\/09\/coniglio-alla-panna\/\">coniglio alla panna<\/a><\/strong><\/em>).<br \/>\nPer l&#8217;occasione ne ho trovata una leggermente diversa<\/p>\n<p><strong>Ingredienti<\/strong> &#8211; <strong>Coniglio alla panna e rosmarino<\/strong><\/p>\n<pre>1 kg di coniglio tagliato a pezzi\r\n4 spicchi di aglio\r\n4 cucchiai di olio extravergine d'oliva\r\n1 dl di vino bianco secco\r\nun rametto di rosmarino\r\n2 dl di panna fresca\r\n1 bicchiere brodo vegetale (anche dado)\r\nsale\r\npepe (anche in grani - facolativo)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate lavando accuratamente i pezzi del coniglio. Asciugate\u00c2\u00a0 bene le parti tamponando con della carta assorbente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26501\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648217-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648217-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648217-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648217-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648217-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Ponete l&#8217;olio, l&#8217;aglio sbucciato, il pepe in grani nella pentola a pressione scoperchiata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26502\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648212-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648212-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648212-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648212-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648212-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete poi il coniglio.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26503\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648206-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648206-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648206-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648206-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648206-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nRosolate il tutto a fuoco vivo per alcuni minuti, girando i pezzi di carne una volta sola<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26504\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648201-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648201-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648201-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648201-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648201-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete il vino e fate sfumare ben bene, inserite il rosmarino, salate e pepate.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26505\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648195-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648195-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648195-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648195-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648195-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Inserite un bicchiere di brodo vegetale, poi chiudete la pentola a pressione con il coperchio.<br \/>\nQuando la pentola comincer\u00c3\u00a0 a fischiare e sar\u00c3\u00a0 arrivata a pressione, abbassate il fuoco e proseguite la cottura per 20-25 minuti circa.<br \/>\nTrascorso il tempo di cottura eliminate la pressione dall\u00e2\u20ac\u2122interno della pentola, aprite e verificate la cottura. Se necessario proseguite la cottura per qualche minuto, ponendo nuovamente la pentola sul fuoco.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26506\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648174-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648174-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648174-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648174-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648174-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Togliete i pezzi di coniglio dalla casseruola, unite la panna e mescolate.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26507\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648163-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648163-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648163-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648163-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648163-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Lasciate sobbollire il tutto per qualche minuto, continuando a mescolare.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26508\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648157-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648157-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648157-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648157-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604235648157-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Versate la salsina sul coniglio e servite.<\/p>\n<figure id=\"attachment_26511\" aria-describedby=\"caption-attachment-26511\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-26511\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604333890128-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604333890128-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604333890128-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604333890128-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/11\/1604333890128-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26511\" class=\"wp-caption-text\">Coniglio alla panna &#8211; PaP<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con cosa si potrebbe accompagnare?<br \/>\nSicuramente con dell&#8217;ottimo riso bianco, bulghur, couscous, pasta, patate lesse e, naturalmente, con una fresca insalatina come contorno.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando ero piccola, la mia mamma cucinava qualche volta il &#8220;coniglio alla panna&#8221; e, ricordo, aveva un sapore sorprendentemente buono.<\/p>\n","protected":false},"author":2,"featured_media":26511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,22,60],"tags":[53],"class_list":["post-26475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carne","category-food","category-secondi_piatti","tag-pentola_a_pressione"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=26475"}],"version-history":[{"count":8,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26475\/revisions"}],"predecessor-version":[{"id":30737,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26475\/revisions\/30737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/26511"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=26475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=26475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=26475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}