{"id":26453,"date":"2021-02-20T14:30:30","date_gmt":"2021-02-20T13:30:30","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=26453"},"modified":"2024-11-08T11:42:31","modified_gmt":"2024-11-08T10:42:31","slug":"crema-pastinaca-scalogno","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2021\/02\/20\/crema-pastinaca-scalogno\/","title":{"rendered":"Crema di pastinaca con scalogno caramellato"},"content":{"rendered":"<p style=\"text-align: justify;\">Al supermercato ho acquistato della <strong>pastinaca<\/strong>, vegetale molto comune qui a Patatolandia.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">In un primo momento avevo pensato di cuocere la pastinaca al forno, insieme a delle carote.<br \/>\nIn questo modo, putroppo, l&#8217;avrei mangiata solamente io e questo non era il mio scopo.<\/p>\n<p style=\"text-align: justify;\">Cosi&#8217; ho pensato di prepararne una crema.<br \/>\nCercando tra le ricette inserite in questo Blog che avevo preparato precedentemente,\u00c2\u00a0 ho trovato la <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/10\/09\/crema-di-pastinaca\/\">seguente<\/a><\/strong><\/em>: questa volta ho mantenuto gli ingredienti, anche se le quantita&#8217; si sono aggiornate, ma la preparazione di questa crema di pastinaca e&#8217; cambiata \ud83d\ude42<\/p>\n<p><strong>Ingredienti per 3 &#8211; crema di pastinaca con scalogno glassato<br \/>\n<\/strong><\/p>\n<pre>3 pastinache\r\n3 scalogni\r\nun goccio di olio\r\nvino bianco secco\r\n700ml litro di brodo vegetale\r\n150ml di panna liquida\r\n1 cucchiaio zucchero di canna\r\ntimo\r\nsale, pepe<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbucciate le pastinache, tagliatele a pezzetti.<br \/>\nSpellatelo scalogno e tagliatelo in fettine sottili.<\/p>\n<figure id=\"attachment_26458\" aria-describedby=\"caption-attachment-26458\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-26458\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487103-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487103-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487103-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487103-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487103-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26458\" class=\"wp-caption-text\">Pastinaca<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26459\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487097-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487097-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487097-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487097-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487097-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Preparate il brodo, tenendolo al caldo.<br \/>\nPulite il timo con carta da cucina inumidita.<\/p>\n<p style=\"text-align: justify;\">Mettete l&#8217;olio in una casseruola, fatevi rosolare lo scalogno per circa 5 minuti, spolverizzandolo con lo zucchero.<br \/>\nFate caramellare lo scalogno, cuocendolo per circa 10 minuti a fuoco dolce.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26460\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487092-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487092-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487092-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487092-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487092-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Rimuovete circa\u00c2\u00a0 1\/3 dello scalogno caramellizzato e tenetelo da parte, per utilizzarlo in seguito per decorare i piatti.<\/p>\n<p style=\"text-align: justify;\">Inserite le pastinache a pezzetti nella casseruola, e fatele cuocere per un poco.<br \/>\nBagnate poi con un goccio di vino bianco e sfumate.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26461\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487086-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487086-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487086-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487086-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487086-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Aggiungete il brodo caldo, portate a bollore, coprite e abbassate il fuoco, facendo cuorere dolcemente il tutto per una ventina di minuti, o fino a quando la pastinaca si sara&#8217; ammorbidita.<\/p>\n<p style=\"text-align: justify;\">Frullate il composto, sino ad ottenere una crema liscia e corposa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26462\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487081-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487081-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487081-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487081-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487081-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Aggiungete la panna, mescolate 1 minuto a fuoco basso.<br \/>\nInsaporite con sale e pepe ed il timo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26463\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487068-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487068-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487068-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487068-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487068-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Dividete la crema,\u00c2\u00a0 e decorate con lo scalogno caramellato.<\/p>\n<figure id=\"attachment_26464\" aria-describedby=\"caption-attachment-26464\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26464 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487061-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487061-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487061-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487061-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/10\/1603910487061-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-26464\" class=\"wp-caption-text\">Crema di pastinaca con scalogno caramellato<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Devo confermare che questa crema e&#8217; veramente ottima.<br \/>\nUna piccola coccola (anche se calorica, come in questo caso) non guasta mai.<\/p>\n<p style=\"text-align: justify;\">Eventualmente, per arginare un attimo alle calorie, e&#8217; possibile sostituire la panna con del latte e, magari, aggiungere un mezzo cucchiaino di farina per addensare un poco (facoltativo).<\/p>\n<p style=\"text-align: justify;\">Accompagnata a dei crostini, poi, e&#8217; veramente l&#8217;ideale per combattere la stagione invernale.<\/p>\n<p style=\"text-align: justify;\">Buon appetito!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al supermercato ho acquistato della pastinaca, vegetale molto comune qui a Patatolandia.<\/p>\n","protected":false},"author":2,"featured_media":26458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,51,57],"tags":[],"class_list":["post-26453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-primi_piatti","category-zuppa"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=26453"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26453\/revisions"}],"predecessor-version":[{"id":46765,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/26453\/revisions\/46765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/26458"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=26453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=26453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=26453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}