{"id":25004,"date":"2020-09-02T15:14:05","date_gmt":"2020-09-02T14:14:05","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=25004"},"modified":"2021-03-05T18:57:13","modified_gmt":"2021-03-05T17:57:13","slug":"filetti-pesce-mandorle-salvia","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/09\/02\/filetti-pesce-mandorle-salvia\/","title":{"rendered":"Filetti di pesce mandorle e salvia"},"content":{"rendered":"<p style=\"text-align: justify;\">Ecco un&#8217;idea simpatica e saporita su come cucinare degli &#8220;insignificanti&#8221; filetti di pesce.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il preparare ogni giorno le stesse portate mi stanca, quindi diamo ogni tanto un &#8220;tocco&#8221; diverso alle &#8220;solite preparazioni casalinghe&#8221;<\/p>\n<p><strong>Ingredienti per i Filetti di pesce mandorle e salvia<\/strong> &#8211; 2 porzioni<\/p>\n<pre>2 filetti di pesce\r\n40 g di mandorle pelate\r\n60 g di pangrattato\r\nfoglie di salvia, a piacere\r\nsale\r\nlimone e olio<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Iniziate a frullare nel mixer le mandorle insieme ad una manciata di foglie di salvia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-25012\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_190059-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_190059-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_190059-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_190059-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_190059-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mischiate quanto ottenete con del pangrattato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-25001\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200814_160911-e1597500276685-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200814_160911-e1597500276685-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200814_160911-e1597500276685-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200814_160911-e1597500276685-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200814_160911-e1597500276685-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200814_160911-e1597500276685-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Passate i filetti di pesce nel nuovo mix di panatura, avendo cura di pigiare bene in modo che la panatura aderisca perfettamente.<br \/>\nPersonalmente ho impanato anche la parte con la pelle del pesce, risultando poi croccante ed avendola poi mangiata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-25011\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191417-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191417-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191417-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191417-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191417-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-25010\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191436-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191436-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191436-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191436-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_191436-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Prendete una pirofila ed imburratela bene, oppure potete mettere della carta da forno sul fondo (cosi&#8217; da non dover sforare con le calorie ed essendo poi facilitati nel lavaggio), e diponete i filetti di pesce impanati e ben distesi, salandoli.<br \/>\nAggiungete un goccio di olio su ogni filetto, ed infornate a 190 gradi per 10 minuti circa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-25009\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_193339-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_193339-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_193339-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_193339-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/08\/IMG_20200819_193339-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Decorate con una fettina di limone e servite subito.<\/p>\n<p style=\"text-align: justify;\">Inutile dire che potete usare la stessa ricetta per impanare anche filetti di pesci diversi, come trota, merluzzo, sogliola, etc..<br \/>\nNoi li abbiamo provati con dei filetti di orata, gia&#8217; sfilettati, e surgelati, ma nulla toglie al gusto del pesce fresco (sempre che sappiate sfilettare&#8230; io no).<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco un&#8217;idea simpatica e saporita su come cucinare degli &#8220;insignificanti&#8221; filetti di pesce.<\/p>\n","protected":false},"author":2,"featured_media":25008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,77,60],"tags":[88],"class_list":["post-25004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","category-pesce","category-secondi_piatti","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/25004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=25004"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/25004\/revisions"}],"predecessor-version":[{"id":25013,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/25004\/revisions\/25013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/25008"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=25004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=25004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=25004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}