{"id":24638,"date":"2020-07-30T21:15:22","date_gmt":"2020-07-30T19:15:22","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=24638"},"modified":"2023-11-01T19:03:18","modified_gmt":"2023-11-01T18:03:18","slug":"dem-congo_riz-jaune","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/07\/30\/dem-congo_riz-jaune\/","title":{"rendered":"# 87 &#8211; Repubblica Democratica del Congo. Riz jaune \/ riso giallo"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/07\/30\/dem-congo_pollo-salsa-cumino\/\">pollo in salsa di cumino<\/a><\/strong><\/em> e&#8217; stato e&#8217; stato accompagnato da questo &#8220;<strong>riz jaune<\/strong>&#8220;, la cui ricetta l&#8217;ho trovata dal seguente sito\u00c2\u00a0 <em><strong>recette-africaine<\/strong><\/em> (  ).<\/p>\n<p><!--more--><\/p>\n<p><strong>Ingredienti -\u00c2\u00a0 Riz jaune<\/strong> \/ riso giallo &#8211; per 4 persone<\/p>\n<pre>500gr di riso\r\n1l di acqua\r\n1 cucchiaino di curcuma\r\n1 tazza di uvetta senza semi, facoltativa\r\n1 stecca di cannella\r\n1 cucchiaio di burro o olio\r\n1 cucchiaino di zucchero\r\n1 cucchiaio di sale\r\nsucco di un limone (facoltativo)<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Per prima cosa, immergete il riso in acqua per 10 minuti prima della cottura, quindi lavate il riso pi\u00c3\u00b9 volte e mettete da parte.<\/p>\n<figure id=\"attachment_24689\" aria-describedby=\"caption-attachment-24689\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24689\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_183832-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_183832-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_183832-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_183832-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_183832-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24689\" class=\"wp-caption-text\">Repubblica Democratica del Congo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Portate l&#8217;acqua a ebollizione, quindi aggiungete tutti gli ingredienti all&#8217;acqua bollente ad eccezione del riso.<br \/>\nAggiungete il burro o l&#8217;olio, lo zucchero, il sale, la curcuma, la stecca di cannella, l&#8217;uvetta (facoltativa) e il succo di limone (facoltativo).<br \/>\nMescolate fino l&#8217;insieme non sara&#8217; ben miscelato e fate bollire per 5 minuti.<\/p>\n<p style=\"text-align: justify;\">Aggiungete il riso &#8211; precedentemente lavato &#8211; nel brodo.<br \/>\nCoprite e cuocete a fuoco molto basso per 20-25 minuti.<br \/>\nMescolate il riso ogni tanto, per evitare che bruci.<\/p>\n<figure id=\"attachment_24695\" aria-describedby=\"caption-attachment-24695\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24695\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_194500-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_194500-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_194500-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_194500-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_194500-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24695\" class=\"wp-caption-text\">Repubblica Democratica del Congo. Riz jaune<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Quando il riso ha assorbito tutto il liquido e sara&#8217; cotto, rimuovete il bastoncino di cannella.<\/p>\n<figure id=\"attachment_24697\" aria-describedby=\"caption-attachment-24697\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24697\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_195436-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_195436-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_195436-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_195436-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200730_195436-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24697\" class=\"wp-caption-text\">Repubblica Democratica del Congo. Riz jaune\u00c2\u00a0 con\u00c2\u00a0 Pollo in salsa di cumino<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Servite il riso giallo con un buon stufato o qualunque cosa piaccia.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Come da ricetta ho utilizzato del riso Jasmin.<br \/>\nLa cottura del riso, comunque, non e&#8217; stata di\u00c2\u00a0 20-25 minuti (come richiesto) ma mi sono bastati una decina di minuti, lo stesso tempo indicato sulla confezione del riso.<\/li>\n<\/ul>\n<p>Furahia mlo wako<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il pollo in salsa di cumino e&#8217; stato e&#8217; stato accompagnato da questo &#8220;riz jaune&#8220;, la cui ricetta l&#8217;ho trovata dal seguente sito\u00c2\u00a0 recette-africaine ( ).<\/p>\n","protected":false},"author":2,"featured_media":24588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173,22,51,67],"tags":[176,220,88],"class_list":["post-24638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-food","category-primi_piatti","category-riso_risotti","tag-176","tag-africa_centrale","tag-frutta_secca"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/24638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=24638"}],"version-history":[{"count":13,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/24638\/revisions"}],"predecessor-version":[{"id":43298,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/24638\/revisions\/43298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/24588"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=24638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=24638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=24638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}