{"id":24467,"date":"2020-07-23T21:08:52","date_gmt":"2020-07-23T19:08:52","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=24467"},"modified":"2023-03-31T17:15:15","modified_gmt":"2023-03-31T15:15:15","slug":"haiti_pikliz","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/07\/23\/haiti_pikliz\/","title":{"rendered":"# 85 &#8211; Repubblica di Haiti. Pikliz (Picklese)"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Pikliz<\/strong> \u00c3\u00a8 un condimento nella cucina <strong>haitiana<\/strong> di cavolo sott&#8217;aceto, carote, peperoni e peperoni scozzesi.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Viene spesso condito con aglio e cipolla e sottaceto in aceto bianco.<\/p>\n<p style=\"text-align: justify;\">Il piatto speziato \u00c3\u00a8 molto comunemente servito sul tavolo insieme ad altri piatti per esaltarne il sapore.<\/p>\n<p style=\"text-align: justify;\">I Caraibi sono inondati di salse al pepe e condimenti di ogni tipo in quanto fanno semplicemente parte della nostra cultura culinaria.<br \/>\nLe trame, il livello di calore, gli ingredienti, i modi di preservarli e la vivacit\u00c3\u00a0 generale di tutti sono unici per il creatore e la singola isola.<br \/>\nA Trinidad e Tobago si trovano molti chutney e amchars, mentre alle Barbados si usa la salsa di peperoni.<br \/>\nAd Haiti troviamo dunque il Pikliz come condimento piccante.<\/p>\n<p style=\"text-align: justify;\">Queste salse sono utili per eliminare l&#8217;oleosit\u00c3\u00a0 di cibi fritti e ad Haiti, appunto, e&#8217; utile per quando si mangiano cibi come il griot (maiale fritto), il tassot (manzo fritto) o il banan peze (banane fritte) e per migliorare il riso e fagioli.<\/p>\n<p style=\"text-align: justify;\">Il nome stesso del piatto pu\u00c3\u00b2 essere basato sulla parola francese piquer che significa pungere.<\/p>\n<p><strong>Ingredienti &#8211; Pikliz (Picklese)<br \/>\n<\/strong><\/p>\n<pre>4 chiodi di garofano interi\r\n8 a 10 grani di pepe\r\n6 peperoni Scotch Bonnet o haba\u00c3\u00b1ero con semi, steli e quarti\r\n2 tazze di cavolo a fette sottili o tritate\r\n\u00c2\u00bd tazza di carote grattugiate\r\n\u00c2\u00bc tazza di piselli surgelati\r\n1 cucchiaino di sale\r\n2-3 tazze di aceto bianco e altro ancora per finire<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite i chiodi di garofano ed i grani di pepe in un barattolo di vetro di grandi dimensioni (da un litro).<\/p>\n<figure id=\"attachment_24494\" aria-describedby=\"caption-attachment-24494\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24494\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153107-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153107-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153107-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153107-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153107-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153107-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24494\" class=\"wp-caption-text\">Haiti<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Stratificate le verdure alternandole nel barattolo, usando \u00e2\u2026\u201c di ciascuna verdura alla volta, l&#8217;ordine di inserimento non ha importanza.<br \/>\nRipetete due volte l&#8217;operazione fino a quando tutte le verdure sono inserite nel barattolo, spingendo il contenuto verso il basso, per comprimere.<\/p>\n<figure id=\"attachment_24495\" aria-describedby=\"caption-attachment-24495\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24495\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153218-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153218-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153218-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153218-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153218-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24495\" class=\"wp-caption-text\">Haiti<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In una ciotola media, sciogliete il sale in 2 tazze di aceto mescolando (o usando il frullatore ad immersione).<br \/>\nAggiungete aceto e soluzione salina al barattolo.<br \/>\nCompletate il barattolo con l&#8217;aceto rimasto.<br \/>\nAvvitate saldamente il coperchio sul barattolo e lasciate riposare per 24-48 ore in frigorifero o a temperatura ambiente.<\/p>\n<figure id=\"attachment_24496\" aria-describedby=\"caption-attachment-24496\" style=\"width: 525px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24496 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153739-e1595340105597-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153739-e1595340105597-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153739-e1595340105597-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153739-e1595340105597-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153739-e1595340105597-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24496\" class=\"wp-caption-text\">Repubblica di Haiti. Pikliz (Picklese)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dopo l&#8217;apertura, aggiungete come refrigerante dell&#8217;aceto per coprire le verdure,\u00c2\u00a0 mentre si consuma il pikliz per varie ricette (come ad esempio il &#8220;<em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/07\/23\/haiti_manman-poul-ak-nwa\/\">Manman poul ak nwa<\/a><\/strong><\/em>&#8220;), oppure come contorno.<\/p>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">Nonostante abito a Patatolandia, Nazione di patate e cavoli, non ne ho trovati di freschi.<br \/>\nHo acquistato una confezione di &#8220;krautsalat&#8221; che, alla fin fine, sono sempre cavoli ma &#8220;processati&#8221; in maniera diversa<\/li>\n<\/ul>\n<figure id=\"attachment_24498\" aria-describedby=\"caption-attachment-24498\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24498\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153807-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153807-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153807-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153807-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153807-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24498\" class=\"wp-caption-text\">Repubblica di Haiti. Pikliz (Picklese)<\/figcaption><\/figure>\n<ul>\n<li style=\"text-align: justify;\">Pensavo inoltre di avere a casa anche dei piselli surgelati&#8230; niente da fare, aggiungendo quindi un preparato per &#8220;minestrone&#8221;, ossia un mix di carote, piselli, cavolfiore e patate gia&#8217; pronto a dadini<\/li>\n<li style=\"text-align: justify;\">Per quanto riguarda i peperoncini, come sapete non sono proprio l&#8217;amante di questi. Per mettere qualche cosa di &#8220;piccante&#8221; ho aggiunto dei &#8220;bratpaprika&#8221;, molto simili a dei &#8220;<em>friggitelli<\/em>&#8220;.<\/li>\n<\/ul>\n<p><figure id=\"attachment_24497\" aria-describedby=\"caption-attachment-24497\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24497\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153757-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153757-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153757-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153757-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/07\/IMG_20200721_153757-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-24497\" class=\"wp-caption-text\">Haiti<\/figcaption><\/figure><\/li>\n<li style=\"text-align: justify;\">Anche la &#8220;marinatura&#8221; finale e&#8217; stata diversa, in quanto ho usato direttamente il composto rimasto della &#8220;krautsalat&#8221; che, leggendo gli ingredienti, e&#8217; molto simile alla mia preparazione.<\/li>\n<li style=\"list-style-type: none;\">Bon apeti\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pikliz \u00c3\u00a8 un condimento nella cucina haitiana di cavolo sott&#8217;aceto, carote, peperoni e peperoni scozzesi.<\/p>\n","protected":false},"author":2,"featured_media":24473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,22,226],"tags":[176,228],"class_list":["post-24467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contorni","category-food","category-stati-americhe","tag-176","tag-antille_america"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/24467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=24467"}],"version-history":[{"count":14,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/24467\/revisions"}],"predecessor-version":[{"id":41392,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/24467\/revisions\/41392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/24473"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=24467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=24467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=24467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}