{"id":2363,"date":"2006-09-15T18:40:28","date_gmt":"2006-09-15T17:40:28","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/cena-in-villa\/"},"modified":"2019-07-26T16:30:02","modified_gmt":"2019-07-26T15:30:02","slug":"cena-in-villa","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/09\/15\/cena-in-villa\/","title":{"rendered":"Arese: Cena in Villa"},"content":{"rendered":"<p style=\"text-align: justify;\">Con settembre e l&#8217;inizio della scuola, anche i corsi di cucina iniziano.<!--more--><br \/>\nQuest&#8217;anno e&#8217; stata organizzata una cena presso la <a href=\"http:\/\/www.lavalera.it\/\">Villa di Valera<\/a> e con la successiva presentazione del nuovo &#8220;anno accademico&#8221;.<\/p>\n<p style=\"text-align: justify;\">L&#8217;ambiente era abbastanza rustico (travi al soffitto e sottopiatti di cartoncino rosso), ma molto rilassante, c&#8217;erano ben 4 postazioni di rinfresco, il tutto era a buffet.<\/p>\n<p style=\"text-align: justify;\">Dopo un primo aperitivo e qualche stuzzichino per rompere il ghiaccio, ritrovare amici conosciuti nei diversi corsi e fare quattro chiacchere post-vacanza, abbiamo assistino alla presentazione della nuova organizzazione, delle attivita&#8217; e delle possibili visite di approfondimento.<\/p>\n<figure id=\"attachment_7624\" aria-describedby=\"caption-attachment-7624\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7624\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tavolo2..jpg\" alt=\"\" width=\"320\" height=\"232\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tavolo2..jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tavolo2.-150x109.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/tavolo2.-300x218.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-7624\" class=\"wp-caption-text\">Cena in Villa &#8211; Valera<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Come tante piccole cavallette colorate ci siamo poi avventate sul cibo (ho ancora la mente offuscata dal vino \ud83d\ude09 ).<\/p>\n<p style=\"text-align: justify;\">C&#8217;erano portate come<\/p>\n<ul style=\"text-align: justify;\">\n<li>mix di crudite&#8217;, crostini, mousse di pesce (non bene identificato ma delizioso)<\/li>\n<li>zuppa di farro &#8211; tagliatelle con crema di peperoni e speck (quindi leggermente affumicate)<\/li>\n<li>polenta con polipi al sugo, pomodori gratinati, melanzane, e molto altro!<\/li>\n<li>tartellette varie (mozzafiato quelle con marmellata di fichi e noci!), cantuccini (beh, la cuoca e&#8217; toscana&#8230;) ed una immensa torta con il nuovo logo della scuola<\/li>\n<li>\n<p><figure id=\"attachment_7623\" aria-describedby=\"caption-attachment-7623\" style=\"width: 193px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7623\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/DOLCI.jpg\" alt=\"\" width=\"193\" height=\"137\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/DOLCI.jpg 193w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/DOLCI-150x106.jpg 150w\" sizes=\"auto, (max-width: 193px) 100vw, 193px\" \/><figcaption id=\"caption-attachment-7623\" class=\"wp-caption-text\">Cena in Villa &#8211; Valera<\/figcaption><\/figure><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Purtroppo la mia descrizione del cibo non e&#8217; stata molto descrittiva ma grossolana, e non rende assolutamente giustizia.<\/p>\n<p style=\"text-align: justify;\">Non ho ancora imparato a descrivere ed individuare tutti gli ingredienti delle ricette, mi dovro&#8217; dedicare maggiormente.<\/p>\n<p style=\"text-align: justify;\">Che dire?<\/p>\n<p style=\"text-align: justify;\">Una immensa soddisfazione per il palato, in un luogo incredibilmente rilassato ed in una atmosfera di amicizia.<\/p>\n<p style=\"text-align: justify;\">Cosa si puo&#8217; voler di piu&#8217;?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con settembre e l&#8217;inizio della scuola, anche i corsi di cucina iniziano.<\/p>\n","protected":false},"author":2,"featured_media":7624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,25,21],"tags":[47],"class_list":["post-2363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-italia","category-travel","tag-lombardia"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2363"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2363\/revisions"}],"predecessor-version":[{"id":10229,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2363\/revisions\/10229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7624"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}