{"id":2355,"date":"2006-09-27T18:40:28","date_gmt":"2006-09-27T17:40:28","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/tentativo-budino-fiordilatte-con-te-marcopolo\/"},"modified":"2019-11-28T10:50:38","modified_gmt":"2019-11-28T09:50:38","slug":"budino-fiordilatte-marcopolo","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/09\/27\/budino-fiordilatte-marcopolo\/","title":{"rendered":"Tentativo &#8211; Budino fiordilatte con te&#8217; MarcoPolo"},"content":{"rendered":"<p style=\"text-align: justify;\">Come ho scritto diverse volte, non sono una cuoca, ma mi piace provare prodotti e sapori nuovi (soprattutto tra quelli in commercio, ma che non siano piatti pronti surgelati \ud83d\ude09 ).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Al momento non sono ancora arrivata ad azzardare cambi nelle ricette, o crearne di nuove.<br \/>\nNon demordo, prima o poi mi verra&#8217; il coraggio e ci riusciro&#8217;!<\/p>\n<p style=\"text-align: justify;\">Facendo la spesa mi sono imbattuta in questo budino alquanto \u00e2\u20ac\u0153asapore\u00e2\u20ac\u009d.<\/p>\n<p style=\"text-align: justify;\">Era la prima volta che lo vedevo, gusto &#8216;fiordilatte&#8217;, un gusto neutro e totalmente insignificante (almeno per me).<\/p>\n<p style=\"text-align: justify;\">L&#8217;ho acquistato ugualmente ed ho provato a dare un tocco personale al risultato, anche se nel suo interno c&#8217;e&#8217; un piccolo ricettario su come giocare e mescolare altri ingredienti per creare nuove ricette&#8230; con piu&#8217; gusto!<\/p>\n<p style=\"text-align: justify;\">Avevo in casa del<strong> te&#8217; MarcoPolo<\/strong>, una miscela di te&#8217; nero con fiori di fiordaliso, acquistato da <a href=\"http:\/\/www.teieraeclettica.it\/\">Barbara<\/a> alla quale ho poi chiesto consiglio sul suo utilizzo.<\/p>\n<figure id=\"attachment_6721\" aria-describedby=\"caption-attachment-6721\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6721\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/te.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/te.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/te-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/te-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-6721\" class=\"wp-caption-text\">Te Marco Polo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La mia idea era quella di lasciare parte del te nel budino, in modo da vedere i fiorellini (che si intravedono nella foto).<br \/>\nNon so esattamente la motivazione, ma me lo ha indirettamente sconsigliato.<\/p>\n<p style=\"text-align: justify;\">Ecco il procedimento, alquanto banale ma, devo ammettere, ho aumentato le dosi di te.<\/p>\n<p style=\"text-align: justify;\">Ho messo del <strong>te Marco Polo<\/strong> in infusione nel latte tiepido per 5 minuti, poi l&#8217;ho filtrato eliminando cosi&#8217; le foglie ed i fiori, ed ho continuato con la normale preparazione del budino.<\/p>\n<p style=\"text-align: justify;\">Il suggerimento era di usare 1 bel cucchiaino pieno (o due cucchiaini scarsi) per 1 lt di latte.<\/p>\n<p style=\"text-align: justify;\">Beh, ho usato lo stesso quantitativo per mezzo litro (una busta) ed il risultato non e&#8217; stato malaccio, un po&#8217; troppo delicato.<\/p>\n<p style=\"text-align: justify;\">Magari la prossima volta che ci ritento ne metto un po&#8217; di piu&#8217;.<\/p>\n<p style=\"text-align: justify;\">(Vi faro&#8217; sapere, dato che ho ancora una dose a disposizione&#8230;)<\/p>\n<p>PS: Naturalmente potete utilizzare te&#8217; di altre specie<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come ho scritto diverse volte, non sono una cuoca, ma mi piace provare prodotti e sapori nuovi (soprattutto tra quelli in commercio, ma che non siano piatti pronti surgelati \ud83d\ude09 ).<\/p>\n","protected":false},"author":2,"featured_media":6721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,69,22],"tags":[],"class_list":["post-2355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al_cucchiaio","category-dessert","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2355"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2355\/revisions"}],"predecessor-version":[{"id":19261,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2355\/revisions\/19261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6721"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}