{"id":2350,"date":"2006-10-06T18:40:27","date_gmt":"2006-10-06T17:40:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/mangiare-bere-uomo-donna-yin-shi-nan-nu\/"},"modified":"2019-11-28T10:50:09","modified_gmt":"2019-11-28T09:50:09","slug":"mangiare-bere-uomo-donna","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/10\/06\/mangiare-bere-uomo-donna\/","title":{"rendered":"Cosa vediamo? &#8220;Mangiare Bere Uomo Donna&#8221; &#8211; YIN SHI NAN NU"},"content":{"rendered":"<p style=\"text-align: justify;\">&#8220;Mangiare, bere, uomo, donna&#8221; e&#8217; una parte di un antico proverbio cinese sulle necessit\u00c3\u00a0 della vita che d\u00c3\u00a0 il titolo al film di Ang Lee (USA 1994).<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La storia tratta del conflitto generazionale tra il vecchio Chu (chef di cucina, cuoco da generazioni e vedovo) e le sue 3 figlie in una moderna TaiPei (Taiwan).<\/p>\n<figure id=\"attachment_7521\" aria-describedby=\"caption-attachment-7521\" style=\"width: 318px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7521\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mangi.jpg\" alt=\"\" width=\"318\" height=\"159\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mangi.jpg 318w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mangi-150x75.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mangi-300x150.jpg 300w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><figcaption id=\"caption-attachment-7521\" class=\"wp-caption-text\">Mangiare Bere Uomo Donna<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Tutte e tre le figlie apprezzano l\u00e2\u20ac\u2122elaborato pranzo domenicale (nonostante inizi a diventare per loro un rito abbastanza pesante) preparato dal padre con la tradizionale dedizione e meticolosa cura dei dettagli, ma ciascuna entra in conflitto con il vecchio mondo di Chu, ognuna a modo suo tentera&#8217; di scappare per vivere in una nuova dimensione e modernita&#8217; della sua esistenza.<\/p>\n<p style=\"text-align: justify;\">Si tratta di un racconto emozionalmente coinvolgente dove il cibo svolge un ruolo chiave nell\u00e2\u20ac\u2122osservare i mutamenti di una cultura cinese in via di trasformazione.<\/p>\n<p style=\"text-align: justify;\">In &#8220;Mangiare, bere, uomo, donna&#8221; ogni ingrediente viene trattato con la massima cura.<br \/>\nLa tavola apparecchiata \u00c3\u00a8 gioia per gli occhi oltre che per la bocca e stimola la riflessione.<br \/>\n\u00c3\u02c6 proprio questo considerare l&#8217;atto del mangiare un momento speciale che induce i commensali a rivelare i loro sentimenti, un momento di unione familiare e di riuscire a rivelare le proprie emozioni, divenendo un mezzo di comunicazione per eccellenza (ma non sempre efficace).<\/p>\n<p style=\"text-align: justify;\">Mangiare, bere, nutrirsi per Ang Lee non significano, semplicemente, riempirsi lo stomaco e soddisfare la fame, ma saziare lo spirito e il cuore, avvicinarsi col cibo, che \u00c3\u00a8 momento di comunione e sacralit\u00c3\u00a0, ai misteri dei sentimenti.<br \/>\nRaggiungere attraverso la bocca, l&#8217;esofago e lo stomaco la parte pi\u00c3\u00b9 segreta dell&#8217;animo umano.<\/p>\n<p style=\"text-align: justify;\">Sono senza dubbio geniali le riprese mentre Chu prepara i suoi prelibati e raffinati piatti.<br \/>\nAltra scena memorabile \u00c3\u00a8 il momento in cui Chu, chiamato per aiutare (sovrintendendo, of course) nella preparazione di un importante banchetto ufficiale, attraversa la cucina IMMENSA del ristorante e viene accolto dai cuochi come un Primario in sala operatoria.<\/p>\n<p style=\"text-align: justify;\">&#8220;Mangiare Bere Uomo Donna&#8221; per gli appassionati di cucina \u00c3\u00a8 un sogno cinematografico poich\u00c3\u00a9 fin dall\u00e2\u20ac\u2122inizio della pellicola appaiono preparazioni di prelibate pietanze.<br \/>\nManicaretti succulenti, per tutta la durata del film sono presenti numerose volte, preparati da Chu ed anche da Jia-Chien, nei due momenti in cui si sente pi\u00c3\u00b9 libera di potersi esprimere (e che riesce a raggiungere il centro della casa: la cucina)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Mangiare, bere, uomo, donna&#8221; e&#8217; una parte di un antico proverbio cinese sulle necessit\u00c3\u00a0 della vita che d\u00c3\u00a0 il titolo al film di Ang Lee (USA 1994).<\/p>\n","protected":false},"author":2,"featured_media":7522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[129],"class_list":["post-2350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-passatempo","tag-tv_kino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2350"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2350\/revisions"}],"predecessor-version":[{"id":11024,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2350\/revisions\/11024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7522"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}