{"id":2333,"date":"2006-11-02T18:40:27","date_gmt":"2006-11-02T17:40:27","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/brrrr\/"},"modified":"2018-03-25T16:57:25","modified_gmt":"2018-03-25T15:57:25","slug":"brrrr","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/11\/02\/brrrr\/","title":{"rendered":"brrrr"},"content":{"rendered":"<p style=\"text-align: justify;\">Che fresco risveglio e che SORPRESONA ho avuto questa mattina!<!--more--><br \/>\nLa foto scattata non fa altro che rappresentare cio&#8217; che si vedeva fuori dalla finestra intorno alle 8am.<br \/>\nE non si tratta di brina!<\/p>\n<p style=\"text-align: justify;\">E&#8217; vera <b>neve<\/b>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10303\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/neve.0.jpg\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/neve.0.jpg 240w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/neve.0-113x150.jpg 113w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/neve.0-225x300.jpg 225w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/p>\n<p style=\"text-align: justify;\">E le previsioni non promettono nulla di buono per il resto della settimana.<\/p>\n<p style=\"text-align: justify;\">Le temperature continueranno ad essere intorno agli 0 gradi, se non meno, durante tutto l&#8217;arco della giornata, e per i prossimi giorni le condizioni meterorologiche potrebbero peggiorare.<\/p>\n<p>Speriamo solo di riuscire ad attraversare le Alpi sabato, cosi&#8217; da poter tornare nel &#8220;paese del sole&#8221; per qualche altra settimana, prima di tornare qui nuovamente (con richiesta scritta del manager!)<\/p>\n<p style=\"text-align: justify;\">Ho comunque sentito che anche a casa non fa poi tanto caldo,<\/p>\n<p style=\"text-align: justify;\">Bisognera&#8217; ricorrere ai ripari, con l&#8217;accensione del forno e, per il momento, fare un corso accelerato su come montare le catene alla macchina.<\/p>\n<p style=\"text-align: justify;\">Ma&#8230;<br \/>\ne dire che <a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/11\/01\/augsburg-augusta\/\">ieri <\/a>era una giornata di sole, nonostante i 9 gradi \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Buona giornata.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che fresco risveglio e che SORPRESONA ho avuto questa mattina!<\/p>\n","protected":false},"author":2,"featured_media":10303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-2333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2333"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2333\/revisions"}],"predecessor-version":[{"id":10304,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2333\/revisions\/10304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10303"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}