{"id":2326,"date":"2006-11-13T18:40:26","date_gmt":"2006-11-13T17:40:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/grazie-per-la-cioccolata\/"},"modified":"2019-11-28T17:17:47","modified_gmt":"2019-11-28T16:17:47","slug":"grazie-per-la-cioccolata","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/11\/13\/grazie-per-la-cioccolata\/","title":{"rendered":"Cosa vediamo? &#8220;Grazie per la cioccolata&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Sotto le influenze del Cioccoshow che si svolge a Bologna in questi giorni, tutti gli avvenimenti italiani girano intorno a questa prelibatezza<\/p>\n<p style=\"text-align: justify;\"><!--more-->Perche&#8217; non dedicarsi alla visione di questi film cioccolatosi, allora?<\/p>\n<p style=\"text-align: justify;\">GRAZIE PER LA CIOCCOLATA<\/p>\n<figure id=\"attachment_7528\" aria-describedby=\"caption-attachment-7528\" style=\"width: 188px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7528\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/grazie.jpg\" alt=\"\" width=\"188\" height=\"268\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/grazie.jpg 188w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/grazie-105x150.jpg 105w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" \/><figcaption id=\"caption-attachment-7528\" class=\"wp-caption-text\">Grazie per la cioccolata<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In effetti, in questo modo, le visioni a &#8220;stomaco vuoto&#8221; sono decisamente MOLTO MENO caloriche, visto che il mio onnipresente tentativo di essere\/stare a dieta e&#8217; sempre nei miei pensieri&#8230;<\/p>\n<p style=\"text-align: justify;\">Che dire di questo film?<\/p>\n<p style=\"text-align: justify;\">Non mi cimento neppure nella spiegazione, proprio non mi e&#8217; piaciuto.<br \/>\nNon per le tante cioccolate calde preparate come dopo-cena, ma proprio l&#8217;interpretazione dei personaggi.<\/p>\n<p style=\"text-align: justify;\">I personaggi mi sembravano asciutti, sterili, come se fossero consapevoli che una telecamera li stesse riprendendo e niente di emozionante.<\/p>\n<p style=\"text-align: justify;\">Si potrebbe definire uno pseudo-giallo, dal colore del cioccolato, ma niente di bello, almeno per me.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sotto le influenze del Cioccoshow che si svolge a Bologna in questi giorni, tutti gli avvenimenti italiani girano intorno a questa prelibatezza<\/p>\n","protected":false},"author":2,"featured_media":7528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[129],"class_list":["post-2326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-passatempo","tag-tv_kino"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2326"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2326\/revisions"}],"predecessor-version":[{"id":11027,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2326\/revisions\/11027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7528"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}