{"id":2318,"date":"2006-11-22T18:40:26","date_gmt":"2006-11-22T17:40:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/cena-presso-der-pschorr-monaco-germania\/"},"modified":"2019-11-28T17:17:01","modified_gmt":"2019-11-28T16:17:01","slug":"der-pschorr-monaco","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/11\/22\/der-pschorr-monaco\/","title":{"rendered":"Monaco: &#8216;Der Pschorr&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">La mattina non e&#8217; iniziata poi cosi&#8217; male come si poteva prevedere&#8230;<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nC&#8217;era un arcobaleno splendido che si vedeva chiaramente in cielo, come vedete dalla foto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6136\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/arcobaleno.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/arcobaleno.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/arcobaleno-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/arcobaleno-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p style=\"text-align: justify;\">Ma, una volta in ufficio, il dramma e&#8217; iniziato.<br \/>\nNiente funzionava, tutto era fermo (almeno per me), un problema dopo l&#8217;altro fino a che, alla fine, ho avuto il sopravvento nella sistemazione del guasto:<\/p>\n<p style=\"text-align: center;\"><strong>FINALMENTE!<\/strong><\/p>\n<p style=\"text-align: justify;\">Di sera, per cena, mi sono comunque riscattata!<br \/>\nSotto una leggera pioggerella ci siamo diretti in quel di Monaco, noi che veniamo dai paesi del circondario.<br \/>\nPensavo di vedere molti piu&#8217; addobbi natalizi, ma non c&#8217;era molto di piu&#8217; che le candele dell&#8217;Avvento poste sopra uno dei tanti grandi magazzini, giusto come decorazione.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6138 size-full alignleft\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mplatz.jpg\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mplatz.jpg 200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/mplatz-150x113.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p style=\"text-align: justify;\">La Rathaus era gia&#8217; circondata dalle casupole di legno in attesa dell&#8217;inizio del prossimo mercatino natalizio, mentre le fontane era gia&#8217; coperte per evitare il ghiaccio.<\/p>\n<p>Peccato che le casette non fossero state aperte\u00e2\u20ac\u00a6 altrimenti mi sarei dispersa nei loro meandri.<\/p>\n<p style=\"text-align: justify;\">Il locale prescelto per la cena\u00c2\u00a0era il &#8220;<em><strong><a href=\"http:\/\/www.der-pschorr.de\/\">Der Pschorr<\/a><\/strong><\/em>&#8221; e&#8217; veramente immenso, su due piani e, nella bella stagione, e&#8217; possibile anche stare fuori, seduti comodamente.<\/p>\n<p style=\"text-align: justify;\">Tavoloni di legno, panche, soffitti altissimi con arcate come se ci trovassimo in una chiesa, dispense di legno e copri-bicchieri sul tavolo.<br \/>\nAtmosfera calda ed accogliente.<\/p>\n<p style=\"text-align: justify;\">La mia cena e&#8217; stata un&#8217;ottima bistecca con gratin di patate, il tutto innaffiato da della Weissbier della casa, in bottiglia debitamente tappata.<\/p>\n<p style=\"text-align: justify;\">Le patate erano tagliate veramente molto sottili, cosi&#8217; da non richiedere una lunga cottura ed ovviare alla secchezza delle stesse durante la fase di gratinatura nel forno.<br \/>\nHo poi assaggiato un pezzetto di knodel (di sicuro non pre-confezionato, ma di vero pane!) e di carne leggermente affumicata.<\/p>\n<p style=\"text-align: justify;\">Immancabile il dolce: pera lessata, avvolta in una sfoglia di pasta, con cioccolato fuso\u00e2\u20ac\u00a6 un sogno!.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6137 alignright\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/der_ps.jpg\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/der_ps.jpg 200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/der_ps-150x113.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>I dettagli delle portate hanno fatto la loro bella figura, come il nome del posto scritto sul piatto con cacao in polvere.<br \/>\nSembrano sciocchezze, ma mi &#8220;faccio comperare&#8221;\u00c2\u00a0 veramente e con soddisfazione da questi dettaglia, soprattutto dove ne vale la pena\u00e2\u20ac\u00a6 E qui, certamente.<\/p>\n<p style=\"text-align: justify;\">La nota di merito spetta comunque al servizio del personale del &#8220;Der Pshorr&#8221;: splendidamente celere, senza dimenticanze o problemi di alcun tipo, molto gentili e cordiali.<\/p>\n<p style=\"text-align: justify;\">Se fosse stato per me, e non avessi preso nota, mi sarei sicuramente dimenticata la scelta delle porzioni nell&#8217;arco di 30 secondi .. tropo da scegliere e tutto accattivante.<\/p>\n<p style=\"text-align: justify;\">Verso le 22 e&#8217; iniziato anche un duo con canzoni austro-tedesche.<br \/>\nNon fastidioso, ma molto tipico e caratteristico.<\/p>\n<p><strong>Informazioni<\/strong><\/p>\n<p><a href=\"http:\/\/www.der-pschorr.de\/\">Der Pschorr<\/a><br \/>\nSchrannenhalle<br \/>\nMonaco<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mattina non e&#8217; iniziata poi cosi&#8217; male come si poteva prevedere&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[163,110],"tags":[28],"class_list":["post-2318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dove-mangiare","category-monaco","tag-dove_mangiare"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2318"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2318\/revisions"}],"predecessor-version":[{"id":17776,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2318\/revisions\/17776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/6137"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}