{"id":2299,"date":"2006-12-22T18:40:26","date_gmt":"2006-12-22T17:40:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/concerto-di-natale-con-il-classic-jazz-combo-arese\/"},"modified":"2020-09-26T08:50:50","modified_gmt":"2020-09-26T07:50:50","slug":"concerto-jazz-combo-arese","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2006\/12\/22\/concerto-jazz-combo-arese\/","title":{"rendered":"Arese: Concerto di Natale con il &#8220;Classic Jazz combo&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Come immancabilmente succede ogni anno, in tutti i paesi grandi o piccoli che siano, vengono organizzati concerti musicali natalizi, che spaziano dal Gospel alle musiche locali straniere (iraniane, israeliane, etc&#8230;)<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Devo ammettere che mi trovo in un circondario decisamente molto fortunato, oltre all&#8217;invito ed alla presenza di grandi artisti (cantanti o gruppi musicali) puo&#8217; capitare che anche piccoli gruppi possano avere il loro momento di <a href=\"http:\/\/www.comune.arese.mi.it\/\">gloria<\/a>.<\/p>\n<p style=\"text-align: justify;\">Tra i diversi concerti ascolti effettuati nelle chiese vicine a me ( http:\/\/www.insiemegroane.it &#8211; link dove era disponibile anche il calendario), mi sono cosi&#8217; presentata presso la Chiesa San Bernardino di Valera (una frazione di Arese) per ascoltare uno di questi concerti &#8220;minori&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il nome del gruppo &#8220;Classic Jazz combo&#8221; sebbene un po&#8217; altisonante non e&#8217; paragonabile al calibro di Mavis Staples o di Cecilia Chailly (tanto per fare degli esempi) ma si e&#8217; sicuramente fatto sentire.<\/p>\n<p style=\"text-align: justify;\">La voce di Eleonora ha rimbombato tra le navate della piccola chiesa, mentre il basso di Andrea risuonava inesorabile, il tutto avvolto dalla tonalita&#8217; vibrante del vibrafono e della batteria.<br \/>\nMolto apprezzati dal pubblico sono stati gli assoli dei singoli componenti, che hanno dimostrato la loro bravura ed il grande accordo tra i diversi strumenti.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7607\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2991.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2991.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2991-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/IMG_2991-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: justify;\">Il pubblico &#8211; purtroppo non molto corposo &#8211; era tra gli &#8220;affezionati&#8221; e conoscenti (mi conto anche io tra di loro, lo devo ammettere&#8230; sono un po&#8217; di parte, conoscendo Andrea da almeno 25 anni&#8230;).<br \/>\nSono sicura che, nonostante tutto, l&#8217;anno prossimo molte piu&#8217; persone accorreranno ad ascoltarli.<\/p>\n<p style=\"text-align: justify;\">Ma loro non si fermano a questi sporadici concerti, con altri gruppi o con questa formazione si fanno sentire spesso.<br \/>\n<a href=\"http:\/\/www.andreamassimo.it\/\">Qui<\/a> i loro eventi a calendario.<\/p>\n<p>&nbsp;<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come immancabilmente succede ogni anno, in tutti i paesi grandi o piccoli che siano, vengono organizzati concerti musicali natalizi, che spaziano dal Gospel alle musiche locali straniere (iraniane, israeliane, etc&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":7607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-2299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2299"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2299\/revisions"}],"predecessor-version":[{"id":25833,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2299\/revisions\/25833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/7607"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}