{"id":2292,"date":"2007-02-13T18:40:26","date_gmt":"2007-02-13T17:40:26","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/cavallucci-toscana\/"},"modified":"2019-11-28T17:20:28","modified_gmt":"2019-11-28T16:20:28","slug":"cavallucci-toscana","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2007\/02\/13\/cavallucci-toscana\/","title":{"rendered":"Toscana: Cavallucci"},"content":{"rendered":"<p style=\"text-align: justify;\">I cavallucci sono, tra i dolci toscani, quelli meno conosciuti.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Come si puo&#8217; vedere dalla foto fatta, sono una specie di pallina di pasta, cotta al forno con l&#8217;aggiunta di altri ingredienti, dalla forma vagamente sferica, grandi all\u00e2\u20ac\u2122incirca come una susina.<\/p>\n<p style=\"text-align: justify;\">Troviamo quindi farina di frumento, zucchero, arancio candito, nocciole, acqua, miele, coriandoli, semi di anice, spezie varie.<\/p>\n<p style=\"text-align: justify;\">Dire che sono una ulteriore botta calorica, e&#8217; forse fare un complimento a questo dolcetto, ma rispetto al panforte e ai ricciarelli senesi sono meno dolci.<\/p>\n<p style=\"text-align: justify;\">Sotto Natale, alzi la mano chi riesce a resistere alla pur minima tentazione!<br \/>\nO, almeno, dalla voglia di provare nuovi sapori.<\/p>\n<p style=\"text-align: justify;\">Per poter garantire la freschezza del prodotto, che va sempre conservato in luogo fresco e asciutto, la lavorazione avviene soltanto nel periodo che va da settembre a Pasqua.<\/p>\n<figure id=\"attachment_8987\" aria-describedby=\"caption-attachment-8987\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8987\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/TOSCANA-1.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/TOSCANA-1.jpg 320w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/TOSCANA-1-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/TOSCANA-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-8987\" class=\"wp-caption-text\">Cavallucci toscani<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">I cavallucci si mangiano a Natale e anche dopo, nei mesi freddi, da soli o col vinsanto.<\/p>\n<p style=\"text-align: justify;\">Se non vengono mangiati subito, immancabilmente dopo un po&#8217; di giorni si seccano.<\/p>\n<p style=\"text-align: justify;\">Molti affermano che quando i Cavallucci sono secchi, allora sono pi\u00c3\u00b9 buoni perche&#8217; per mangiarli\u00c2\u00a0 si inzuppano nel vino o nel vinsanto, affinche si ammorbidiscano un poco.<\/p>\n<p style=\"text-align: justify;\">Il loro nome deriverebbe dall\u00e2\u20ac\u2122apprezzamento che avevano per questi biscotti i cavallai delle stazioni di posta, ovvero coloro che avevano il compito di cambiare i cavalli (mentre il nome originale di questi dolcetti era &#8221; <strong>berriguocoli<\/strong> &#8220;, nome con cui compaiono anche in documenti del Cinquecento).<\/p>\n<p style=\"text-align: justify;\">La passione dei cavallai e della servit\u00c3\u00b9 per questi dolciumi era probabilmente legata alle loro tipica&#8230; durezza (tanto per mangiarli inzuppati!).<\/p>\n<p style=\"text-align: justify;\">Tra la maggior parte dei dolci senesi (ricciarelli, cantuccini, etc..) i cavallucci sono forse quelli che hanno conosciuto una minore popolarit\u00c3\u00a0, ma fanno parte della pi\u00c3\u00b9 pura e autentica tradizione senese, e tra i toscani hanno molti estimatori.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I cavallucci sono, tra i dolci toscani, quelli meno conosciuti.<\/p>\n","protected":false},"author":2,"featured_media":3402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,25],"tags":[41,40],"class_list":["post-2292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-italia","tag-natale","tag-toscana"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2292"}],"version-history":[{"count":4,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2292\/revisions"}],"predecessor-version":[{"id":17793,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2292\/revisions\/17793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/3402"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}