{"id":2272,"date":"2007-12-23T18:40:25","date_gmt":"2007-12-23T17:40:25","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/chez-zii\/"},"modified":"2019-11-28T17:26:07","modified_gmt":"2019-11-28T16:26:07","slug":"chez-zii","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2007\/12\/23\/chez-zii\/","title":{"rendered":"Chez&#8230;  Zii"},"content":{"rendered":"<p style=\"text-align: justify;\">Che dire?<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Mi aspettavo una giornata con un freddo infernale, una bufera di neve, qualsiasi agente atmosferico per impedirci di andare a pranzo dagli Zii.<\/p>\n<p style=\"text-align: justify;\">In effetti e&#8217; qualche tempo che stiamo tendando di autoinvitarci ma, fino ad oggi, pare non abbiano sentito le nostre richieste.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5955\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/noi.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/noi.jpg 400w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/noi-150x113.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/noi-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: justify;\">Il Nonno e&#8217; passato da noi per mezzogiorno (abitavamo ancora a Bollate) ed all&#8217;uscita di casa ho pensato bene di prendermi una storta camminando su una lattina.<\/p>\n<p style=\"text-align: justify;\">Ma non ho voluto tirarmi indietro, nonostante un inizio di giornata non &#8220;troppo brillante&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il pranzo e&#8217; stato un mix tra cibo di due nazioni Italia e Croazia:<\/p>\n<ul>\n<li style=\"text-align: justify;\">antipasto con tartine e maionese<\/li>\n<li style=\"text-align: justify;\">ravioli di grano saraceno burro\/salvia<\/li>\n<li style=\"text-align: justify;\">peperoni ripieni (Croazia) con pure di patate<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5954 alignnone\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/uno.jpg\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/uno.jpg 200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/uno-150x113.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5953 alignnone\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due.jpg\" alt=\"\" width=\"200\" height=\"150\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due.jpg 200w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/due-150x113.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<ul>\n<li style=\"text-align: justify;\">il dolce e&#8217; stato fatto con biscotti, niente maraschino (almeno in fase di allattamento), bianco d&#8217;uovo cotto nel latte e crema pasticcera.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><strong>Fantastico<\/strong>!<\/p>\n<p style=\"text-align: justify;\">Speriamo che ripetano un&#8217;altra volta questa meravigliosa esperienza di invito, senza dover aspettare altri 7 anni, o che Tobias torni dal militare!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che dire?<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-2272","post","type-post","status-publish","format-standard","hentry","category-life"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2272"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2272\/revisions"}],"predecessor-version":[{"id":5956,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2272\/revisions\/5956"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}