{"id":2259,"date":"2008-01-10T18:40:24","date_gmt":"2008-01-10T17:40:24","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/mars-fritti-deep-fried-mars\/"},"modified":"2021-04-24T17:17:10","modified_gmt":"2021-04-24T15:17:10","slug":"mars-fritti-deep-fried-mars","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2008\/01\/10\/mars-fritti-deep-fried-mars\/","title":{"rendered":"Regno Unito: Mars fritti (Deep-fried Mars) ??"},"content":{"rendered":"<p style=\"text-align: justify;\">Ebbene si, succede anche questo un po&#8217; piu&#8217; a Nord rispetto a noi.<br \/>\nNon avevo mai pensato a questa possibilita&#8217; sino a quando non ho visto un documentario &#8211; Galileo &#8211; che ne parlava.<br \/>\n<!--more--><br \/>\nIl tutto succede ad <strong>Edimburgo\/Scozia<\/strong>, la patria del fritto.<br \/>\nPare che una friggitoria abbia iniziato a friggere di tutto, oltre al consueto fish-and-chips (piatto tradizionale, altro che ossobuco!).<\/p>\n<p style=\"text-align: justify;\">Sono poi passati a diverse fasi di &#8220;lavorazione&#8221; tra cui formaggio, pizza (ORRORE&#8230;!!!), frutta e sono approdati anche al cioccolato.<\/p>\n<figure id=\"attachment_16631\" aria-describedby=\"caption-attachment-16631\" style=\"width: 339px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16631\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2008\/01\/swi0024l-deep-mars.jpg\" alt=\"\" width=\"339\" height=\"400\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2008\/01\/swi0024l-deep-mars.jpg 339w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2008\/01\/swi0024l-deep-mars-127x150.jpg 127w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2008\/01\/swi0024l-deep-mars-254x300.jpg 254w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><figcaption id=\"caption-attachment-16631\" class=\"wp-caption-text\">Tratta dal Web<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">In effetti, se lo fanno, significa che la richiesta del mercato e&#8217; presente ma &#8230; bleah&#8230; che gusti!<br \/>\npensate se prima friggono il pesce e nello stesso olio passano al cioccolato \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Sempre nello stesso programma televisivo, era stato invitato anche un &#8220;mastro cioccolataio&#8221; per testare il <strong>Mars fritto<\/strong> e, pare, ne sia stato colpito.<br \/>\nMa in modo positivo &#8220;il mou interno si era sciolto in maniera perfetta tanto da unirsi positivamente al cioccolato esterno, secondo lui&#8221;.<br \/>\nNon so se e&#8217; stato &#8220;pagato&#8221; per essere presente al fatto, ma di sicuro, se fossi stata in lui, mi sarei rifiutata categoricamente ad intervenire e, soprattutto, commentare.<\/p>\n<p style=\"text-align: justify;\">Altro lato curioso..<br \/>\nDurante le riprese per la tv, mostravano l&#8217;immersione dei diversi &#8220;bocconcini&#8221; prima di immergerli nell&#8217;olio, questo stranamente limpido e privo di qualsiasi crosticina galleggiante.<br \/>\nAnche il cioccolato non veniva inquinato da un eventuale scoria rimasta nell&#8217;olio riusato, ma veniva letteralmente &#8220;pucciato&#8221; in una vasca a parte.<\/p>\n<p style=\"text-align: justify;\">Ma sara&#8217; vero che lo lasceranno a parte?<br \/>\nOppure e&#8217; solo l&#8217;esito dell&#8217;effetto tv, che rende tutto piu&#8217; &#8220;pulito e buono&#8221;?<\/p>\n<p style=\"text-align: justify;\">La situazione e&#8217; sospetta e puzza (.. di fritto \ud83d\ude09 )<br \/>\nHo fatto anche una ricerchina in Internet.<br \/>\nPotete trovare dei video di &#8220;cavie&#8221; che si prestano a questo sacrificio mangereccio.<\/p>\n<p>E.. notizianotizia&#8230; anche in\u00c2\u00a0 <em><strong><a href=\"http:\/\/it.wikipedia.org\/wiki\/Mars_fritto\">wikipedia<\/a><\/strong><\/em>\u00c2\u00a0 viene pubblicata.<\/p>\n<p style=\"text-align: justify;\">Non voglio pero&#8217; togliervi ulteriore il gusto di cercare (&#8220;Deep-fried Mars&#8221; ) e farvi venire l&#8217;acquolina, prima di tentare un esperimento casareccio.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ebbene si, succede anche questo un po&#8217; piu&#8217; a Nord rispetto a noi. Non avevo mai pensato a questa possibilita&#8217; sino a quando non ho visto un documentario &#8211; Galileo &#8211; che ne parlava.<\/p>\n","protected":false},"author":2,"featured_media":3502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58,168,22],"tags":[],"class_list":["post-2259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","category-europa","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2259"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2259\/revisions"}],"predecessor-version":[{"id":31174,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2259\/revisions\/31174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/3502"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}