{"id":22559,"date":"2020-08-22T15:11:55","date_gmt":"2020-08-22T14:11:55","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=22559"},"modified":"2020-08-12T17:44:33","modified_gmt":"2020-08-12T16:44:33","slug":"harry-potter-cursed-child","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/08\/22\/harry-potter-cursed-child\/","title":{"rendered":"Cosa leggiamo? \u00e2\u20ac\u0153Harry Potter and the cursed child&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Finalmente la nostra biblioteca ha riaperto i battenti ai primi di maggio.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Non senza averci mostrato, fotograficamente, tutta la procedura per la sicurezza nostra e dei dipendenti: di come e dove depositare i libri letti, che verranno sanificati e quindi non disponibili per 72 ore, come accedere ed uscire dai locali, come usare le scale e la necessita&#8217; di avere sempre la mascherina che copra bocca e naso.<\/p>\n<p>Nonostante questo&#8230; si va ugualmente a prendere libri!<\/p>\n<p style=\"text-align: justify;\">In uno dei &#8220;nuovi&#8221; giro, tra i diversi libri presi in prestito, ho selezionato anche quest&#8217;ultimo di Harry Potter, \u00e2\u20ac\u0153<strong>Harry Potter and the cursed child<\/strong>&#8221; (&#8220;Harry Potter e la maledizione dell&#8217;erede&#8221;).<\/p>\n<p style=\"text-align: justify;\">Alla sua uscita in libreria lo volevo acquistare, ma poi ho tentennato un bel po&#8217; pensando alla sua teatralita&#8217;.<\/p>\n<p>Ma alla fine.. l&#8217;ho preso in prestito. La curiosita&#8217; di continuare la storia e&#8217; stata decisamente piu&#8217; grande.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-22560 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200521_125233-e1590074762256-576x1024.jpg\" alt=\"\" width=\"525\" height=\"933\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200521_125233-e1590074762256-576x1024.jpg 576w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200521_125233-e1590074762256-84x150.jpg 84w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200521_125233-e1590074762256-169x300.jpg 169w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200521_125233-e1590074762256-768x1365.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Questo volume di Harry Potter \u00c3\u00a8, infatti, un&#8217;opera teatrale in due parti di Jack Thorne su soggetto di J. K. Rowling, John Tiffany e dello stesso Thorne.<br \/>\nIl dramma, ambientato diciannove anni dopo &#8220;Harry Potter e i Doni della Morte&#8221;, racconta la storia di Albus Severus Potter, secondogenito di Harry Potter e Ginny Weasley.<\/p>\n<p style=\"text-align: justify;\">Personalmente penso che, se una persona non ha letto i precedenti volumi o, almeno, non li ha visti al cinema\/tv, puo&#8217; sembrare un po&#8217; difficile da comprendere questo ottavo libro della saga, a causa dei diversi riferimenti di persone o di oggetti utilizzati.<\/p>\n<p style=\"text-align: justify;\">Non si narrano gli anni intercorsi, ma ci si presenta subito a 19anni di distanza dalla vittoria su Voldemort.<\/p>\n<p style=\"text-align: justify;\">In questo volume troviamo la maestria della scrittrice\u00c2\u00a0 di trovare un equilibrio tra il passato e il presente, che poi \u00c3\u00a8 il fulcro della trama del libro.<\/p>\n<p style=\"text-align: justify;\">Da una parte abbiamo i nuovi personaggi, Albus Severus Potter, Scorpius Malfoy, Rose Granger-Weasley e Delphi Diggory che ci conquisteranno con le loro avventure, ma allo stesso tempo J.K. Rowling ci ha permesso di rivedere i personaggi che pi\u00c3\u00b9 abbiamo amato (e odiato) e che pensavamo di non vedere pi\u00c3\u00b9 in azione.<\/p>\n<p style=\"text-align: justify;\">Anche i vecchi personaggi presenti rispecchiano la loro unicita&#8217; e le loro passate caratteristiche, a mio avviso forse in maniera piu&#8217; decisiva (come Ron, sempre piu&#8217; nel suo mondo) o del tutto inaspettata (Harry, titubante nel suo comportamento e molto controverso).<br \/>\nL&#8217;obiettivita&#8217; di Ginny e la sua fermezza e&#8217; veramente un punto di forza per l&#8217;unione familiare, mentre Ermione mi e&#8217; sembrata un po&#8217; piu&#8217; &#8220;svanita&#8221;.<\/p>\n<figure id=\"attachment_22576\" aria-describedby=\"caption-attachment-22576\" style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22576\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/harry.jpg\" alt=\"\" width=\"474\" height=\"474\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/harry.jpg 474w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/harry-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/harry-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/harry-100x100.jpg 100w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><figcaption id=\"caption-attachment-22576\" class=\"wp-caption-text\">Da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ma non vi voglio raccontare nulla, se non che anche in questo caso l&#8217;amicizia segna la svolta di questo volume.<br \/>\nUn&#8217;amicizia salda, inaspettata, che puo&#8217; anche fare male ma che non sara&#8217; mai distruttrice di un vero rapporto tra le persone.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente la nostra biblioteca ha riaperto i battenti ai primi di maggio.<\/p>\n","protected":false},"author":2,"featured_media":22575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,101],"tags":[125],"class_list":["post-22559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","category-passatempo","tag-lettura"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/22559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=22559"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/22559\/revisions"}],"predecessor-version":[{"id":22577,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/22559\/revisions\/22577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/22575"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=22559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=22559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=22559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}