{"id":2249,"date":"2008-05-08T18:40:24","date_gmt":"2008-05-08T17:40:24","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/che-fareste\/"},"modified":"2019-11-28T17:30:48","modified_gmt":"2019-11-28T16:30:48","slug":"che-fareste","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2008\/05\/08\/che-fareste\/","title":{"rendered":"Cosa Leggiamo: Che fareste???"},"content":{"rendered":"<p style=\"text-align: justify;\">Cosa fareste, voi???<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Ho un sacco di riviste di cucina (CucinareBene dal primo numero, ad esempio), Cucina Moderna e tanto altro ancora, e non so come comportarmi&#8230;<\/p>\n<p style=\"text-align: justify;\">Ci sono alcune ricette che non farei mai, altre che sono complicate o per gli ingrediente contenuti non mi ispirano molto&#8230;<\/p>\n<p style=\"text-align: justify;\">Avevo pensato di strappare le pagine e di tenere, archiviandole in qualche modo, solo quelle che reputo &#8220;interessanti&#8221;.<br \/>\nIn questo modo eviterei di passare gli indici di tutte le annate alla ricerca di qualche cosa di &#8220;appetibile&#8221;<\/p>\n<p style=\"text-align: justify;\">Cosa fareste, voi?<\/p>\n<p style=\"text-align: justify;\">Strappare e archiviare?<br \/>\nTenere tutta la rivista?<\/p>\n<p style=\"text-align: justify;\">Come vi comportate sotto questo punto di vista??<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosa fareste, voi???<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-2249","post","type-post","status-publish","format-standard","hentry","category-passatempo"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2249"}],"version-history":[{"count":2,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2249\/revisions"}],"predecessor-version":[{"id":13324,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2249\/revisions\/13324"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}