{"id":22336,"date":"2020-05-14T11:30:21","date_gmt":"2020-05-14T09:30:21","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=22336"},"modified":"2024-01-07T17:05:18","modified_gmt":"2024-01-07T16:05:18","slug":"nuova-zelanda_anzac-biscuits","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/05\/14\/nuova-zelanda_anzac-biscuits\/","title":{"rendered":"# 63 &#8211; Nuova Zelanda. Anzac Biscuits"},"content":{"rendered":"<p style=\"text-align: justify;\">Giusto in anticipo del nostro pasto della <strong>Nuova Zelanda<\/strong>, ho preparato dei biscotti tipici, gli <strong>Anzac<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il biscotto Anzac \u00c3\u00a8 un biscotto dolce, popolare in Australia e Nuova Zelanda, realizzato con fiocchi d&#8217;avena, farina, zucchero, burro (o margarina), sciroppo d&#8217;oro, bicarbonato di sodio, acqua bollente e (facoltativamente) cocco essiccato.<br \/>\nI biscotti Anzac sono stati a lungo associati al Corpo d&#8217;armata australiano e neozelandese (ANZAC) istituito nella prima guerra mondiale.<\/p>\n<p style=\"text-align: justify;\">\u00c3\u02c6 stato affermato che i biscotti venivano inviati da mogli e gruppi di donne ai soldati all&#8217;estero perch\u00c3\u00a9 gli ingredienti non si deteriorano facilmente e i biscotti venivano conservati bene durante il trasporto navale.<br \/>\nTuttavia, questa informazione \u00c3\u00a8 stata contraddetta dall&#8217;affermazione che i biscotti Anzac non furono mai inviati ai soldati e furono invece mangiati dagli australiani e dai kiwi a casa per raccogliere fondi per la guerra.<\/p>\n<p style=\"text-align: justify;\">La ricetta che ho seguito era stata presa da questo link ( http:\/\/\u00c2\u00a0 whanaushow.co.nz\u00c2\u00a0 \/biscuits-cakes\/anzac-biscuits ), ora non piu&#8217; raggiungibile<\/p>\n<p><strong>Ingredienti<\/strong> &#8211; <strong>Anzac<\/strong> biscuits<\/p>\n<pre>125 grammi di farina\r\n100 grammi di burro\r\n150 grammi di zucchero\r\n1 cucchiaio di sciroppo d'oro\r\n1 tazza di cocco\u00c2\u00a0\u00c2\u00a0 (100gr)\r\n\u00c2\u00bd cucchiaino di bicarbonato di sodio\r\n1 tazza di fiocchi d'avena\u00c2\u00a0 (85gr)\r\n2 cucchiai di acqua bollente<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Preriscaldate il forno a 180 \u00c2\u00b0 C.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22343\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_135309-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_135309-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_135309-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_135309-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_135309-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mescolate la farina, lo zucchero, il cocco ed i fiocchi d&#8217;avena.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22344\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_140650-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_140650-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_140650-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_140650-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_140650-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Sciogliete il burro e lo sciroppo.<br \/>\nSciogliete il bicarbonato di sodio nell&#8217;acqua bollente e aggiungelo al burro e allo sciroppo.<br \/>\nFate un pozzo al centro della farina, aggiungete il liquido.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22345\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_141236-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_141236-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_141236-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_141236-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_141236-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Mettete l&#8217;impasto su delle teglie unte, aiutandovi con un cucchiaio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22346\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_142228-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_142228-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_142228-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_142228-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_142228-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Cuocete 15-20 minuti, in forno statico<\/p>\n<figure id=\"attachment_22347\" aria-describedby=\"caption-attachment-22347\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22347 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_143955-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_143955-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_143955-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_143955-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_143955-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-22347\" class=\"wp-caption-text\">Nuova Zelanda. Anzac Biscuits<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Non avendo lo &#8220;sciroppo&#8221; ho usato dello sciroppo di riso.<\/li>\n<li style=\"text-align: justify;\">Non so esattamente il suo utilizzo, magari solo per fornire un po&#8217; piu&#8217; di colore al biscotto.<\/li>\n<li style=\"text-align: justify;\">Non ho messo l&#8217;impasto sulla teglia unta, ma l&#8217;ho foderata con carta forno.<\/li>\n<li style=\"text-align: justify;\">Sarebbe meglio lasciare spazio sulla teglia tra un biscotto e l&#8217;altro&#8230;<\/li>\n<\/ul>\n<figure id=\"attachment_22348\" aria-describedby=\"caption-attachment-22348\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22348 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_144216-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_144216-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_144216-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_144216-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/05\/IMG_20200513_144216-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-22348\" class=\"wp-caption-text\">Nuova Zelanda. Anzac Biscuits<\/figcaption><\/figure>\n<hr \/>\n<p style=\"text-align: justify;\">La prima ricetta conosciuta che combina le parole &#8220;<strong>anzac<\/strong>&#8221; e &#8220;biscotto&#8221; \u00c3\u00a8 una ricetta del 1916 per &#8220;ANZAC GINGER BISCUITS&#8221;, pubblicata nell&#8217;edizione di Perth del Sunday Times.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, questa ricetta non contiene alcuna menzione dell&#8217;avena presente nei moderni biscotti anzac.<br \/>\nLa prima ricetta per qualcosa chiamato &#8220;Biscotti Anzac&#8221; appare in una pubblicazione australiana, il War Chest Cookery Book (Sydney, 1917), ma questa ricetta era anche per un biscotto diverso piuttosto che quello che sappiamo essere il moderno biscotto Anzac.<br \/>\nLa stessa pubblicazione, il War Chest Cookery Book (Sydney, 1917), includeva anche le prime due ricette di biscotti simili ai moderni biscotti Anzac, con il nome di &#8220;Biscotti arrotolati di avena&#8221; e solo &#8220;Biscotti&#8221;.<br \/>\nLa prima istanza registrata della combinazione del nome &#8220;biscotto Anzac&#8221; e la ricetta ora associata ad essa fu trovata ad Adelaide risalente alla &#8220;fine del 1919 o all&#8217;inizio del 1920&#8221;.<br \/>\nUn&#8217;altra prima ricetta per il biscotto Anzac risale al 1921 in un giornale australiano chiamato The Argus.<br \/>\nQueste prime ricette non contenevano cocco essiccato, presente in molti moderni biscotti Anzac.<br \/>\nLa prima ricetta per un biscotto Anzac contenente il cocco essiccato \u00c3\u00a8 stata registrata dalla citt\u00c3\u00a0 di Adelaide nel 1924.<\/p>\n<p>Good Appetite<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giusto in anticipo del nostro pasto della Nuova Zelanda, ho preparato dei biscotti tipici, gli Anzac.<\/p>\n","protected":false},"author":2,"featured_media":22341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,69,22,237],"tags":[176,218,54,107],"class_list":["post-22336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biscotti","category-dessert","category-food","category-oceania","tag-176","tag-australasia","tag-cereali","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/22336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=22336"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/22336\/revisions"}],"predecessor-version":[{"id":43992,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/22336\/revisions\/43992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/22341"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=22336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=22336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=22336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}