{"id":2212,"date":"2008-08-23T18:40:23","date_gmt":"2008-08-23T17:40:23","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/alkermes-questo-sconosciuto\/"},"modified":"2019-11-28T17:40:14","modified_gmt":"2019-11-28T16:40:14","slug":"alkermes-questo-sconosciuto","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2008\/08\/23\/alkermes-questo-sconosciuto\/","title":{"rendered":"Alkermes&#8230; questo sconosciuto"},"content":{"rendered":"<p style=\"text-align: justify;\">Ci sono, a volte, dei prodotti che non si acquistano dato che se ne usa solamente una piccolissima parte e, il resto, viene totalmente dimenticato.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Questo e&#8217; un tipico esempio&#8230; l&#8217;<strong>ALKERMES<\/strong><\/p>\n<p style=\"text-align: justify;\">Ne avrei bisogno per bagnare la torta di compleanno del piccolo Tobias e.. non si trova proprio!<\/p>\n<p style=\"text-align: justify;\">Ok&#8230;ok&#8230;<\/p>\n<p style=\"text-align: justify;\">E&#8217; difficile trovarlo sicuramente a Patatolandia ma, nonostante il giro in 2 gelaterie _italiane_ che fanno anche da &#8220;Bar&#8221;, entrambe mi hanno guardato decisamente male ma, piu&#8217; che altro, direi stralunati.<\/p>\n<figure id=\"attachment_10538\" aria-describedby=\"caption-attachment-10538\" style=\"width: 211px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10538\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/alchermes.jpg\" alt=\"\" width=\"211\" height=\"239\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/alchermes.jpg 211w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2018\/01\/alchermes-132x150.jpg 132w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><figcaption id=\"caption-attachment-10538\" class=\"wp-caption-text\">Alchermes &#8211; da Internet<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ma che cosa e&#8217; mai?<\/p>\n<p style=\"text-align: justify;\">Ebbene da qui:<\/p>\n<p style=\"text-align: justify;\">Il nome Alkermes, che contraddistingue il liquore fiorentino, deriva dalla parola spagnola &#8220;alquermes&#8221;, a sua volta derivante dall&#8217;arabo &#8220;quirmiz&#8221;, ovvero &#8220;cocciniglia&#8221;.<br \/>\nIl colore rosso dell&#8217;Alkermes (di quello vero, non delle imitazioni) infatti viene ancora oggi ottenuto con il colorante ottenuto dalle coccinelle, e forse proprio al suo colore questo liquore deve la sua inziale fortuna.<br \/>\nLa ricetta originale dell&#8217;Alkermes \u00c3\u00a8 quella dettata da fra&#8217; Cosimo Bucelli, direttore dell&#8217;Officina di Santa Maria Novella gi\u00c3\u00a0 nel 1743, trovata nel ricettario della Fonderia dell\u00e2\u20ac\u2122Officina stessa.<br \/>\nLa nascita dell&#8217;Alkermes per\u00c3\u00b2 ha origini ancora pi\u00c3\u00b9 lontane: la sua origine sembra risalire alle Suore dell\u00e2\u20ac\u2122Ordine di Santa Maria dei Servi di Firenze, fondato nel 1233, che lo impiegavano come elixir di lunga vita.<\/p>\n<p style=\"text-align: justify;\">Ancora oggi, la produzione dell&#8217;Alkermes viene fatta dai frati domenicani di Santa Maria Novella, e per tutto il rinascimento veniva indicato anche come l&#8217;elisir di lunga vita.<br \/>\nNella sua composizione troviamo altre spezie, come il cardamomo, la vaniglia, i chiodi di garofano e la cannella, e l&#8217;acqua di rose (o giulebbe).<br \/>\nL&#8217;Alkermes ebbe subito grande diffusione, e dalla corte de&#8217; Medici arriv\u00c3\u00b2 ben presto anche in Vaticano, mentre Caterina lo port\u00c3\u00b2 alla corte di Francia dove veniva chiamato il liquore de&#8217; Medici.<\/p>\n<p style=\"text-align: justify;\">L&#8217;abitudine di bere un bicchierino di Alkermes \u00c3\u00a8 oramai quasi sparita, ma il suo uso \u00c3\u00a8 rimasto nella preparazione di dolci, e risulta un ingrediente indispensabile della zuppa inglese (dolce italianissimo, nonostante il nome, le cui origini alcuni fanno risalire alla Corte dei Medici, ma questa \u00c3\u00a8 un&#8217;altra storia&#8230;), delle pesche di Prato e della versione toscana del tiramis\u00c3\u00b9, che ancora oggi su usa preparare con i biscotti intrisi del magico rosso scarlatto dell&#8217;Alkermes.<\/p>\n<p style=\"text-align: justify;\">La produzione dell&#8217;Alkermes \u00c3\u00a8 limitata ai 250 litri all&#8217;anno prodotti nell&#8217;Officina erboristica di Santa Maria Novella a Firenze, venduti quasi interamente nel negozio attiguo, e solo una minima parte arriva tramite grossisti al di fuori della provincia di Firenze.<\/p>\n<p style=\"text-align: justify;\">Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sono, a volte, dei prodotti che non si acquistano dato che se ne usa solamente una piccolissima parte e, il resto, viene totalmente dimenticato.<\/p>\n","protected":false},"author":2,"featured_media":10538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[149,22],"tags":[],"class_list":["post-2212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bevande","category-food"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2212"}],"version-history":[{"count":5,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2212\/revisions"}],"predecessor-version":[{"id":19273,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2212\/revisions\/19273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/10538"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}