{"id":2209,"date":"2008-09-04T18:40:22","date_gmt":"2008-09-04T16:40:22","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/india-pollo-tandoori\/"},"modified":"2023-05-15T14:21:15","modified_gmt":"2023-05-15T12:21:15","slug":"india_pollo-tandoori","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2008\/09\/04\/india_pollo-tandoori\/","title":{"rendered":"India: Pollo Tandoori"},"content":{"rendered":"<p style=\"text-align: justify;\">Questa volta parliamo e cuciniamo il &#8230;. <strong>Pollo Tandoori<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Si tratta di uno dei piatti piu&#8217; famosi della cucina indiana, assai aromatico e marinato nello yoghurt.<\/p>\n<p style=\"text-align: justify;\">Il piatto e&#8217; originario della regione del Punjab, regione a Nord del Paese, con una cucina molto semplice ma ben curata e con tutti gli ingredienti (dato che i punjabi non sono vegetariani o induisti).<br \/>\nSebbene la gastronomia di queste parti sia speziata, non e&#8217; niente confrontandola con\u00c2\u00a0 il Sud del paese.<\/p>\n<p style=\"text-align: justify;\">Il nome di questo piatto prende il nome dal rudimentale forno verticale di terracotta, il<strong> tandoor<\/strong>, una specie di grosso recipiente infisso nel terreno sopra la carbonella.<br \/>\nIn questo particolare forno vengono cotti anche alcuni tipi di verdura, spiedini, gamberi ed il naan (ossia il pane), che accompagna questo tipo di preparazione.<\/p>\n<p style=\"text-align: justify;\">Sebbene la preparazione richiedesse un pollo, io ho usato solo le cosce e sovraccosce.<br \/>\nE&#8230; non ho aggiunto peperoncino (sperando nell&#8217;assaggio da parte di Tobias, che ha gradito!!)<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti &#8211; Pollo Tandoori<br \/>\n<\/strong><\/p>\n<pre>1 pollo\r\n200 gr yoghurt intero naturale\r\n1 spicchio d'aglio\r\n2 cucchiai olio di semi\r\n1\/2 limone\r\n1 cucchiaino di zenzero fresco grattugiato\r\n1 cucchiaino di peperoncino in polvere (non ho inserito)\r\n1 cucchiaino di coriandolo in polvere\r\n1 presa di curcuma, chiodi di garofano, cannella, cumino, cardamomo, zafferano (per velocizzare il tutto ho aperto una bustina di \"vin brule'\" del mercato equo-solidale, che contiene inoltre noce moscata)\r\nlimone\r\nsale<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Se necessario fiammeggiate il pollo per eliminare gli eventuali residui di piume.<\/p>\n<p style=\"text-align: justify;\">Lavate il pollo accuratamente e asciugatelo con carta assorbente da cucina<\/p>\n<p style=\"text-align: justify;\">Tagliate il pollo a pezzetti regolari, quindi eliminate la pelle e incideteli in superficie con 2-3 taglietti in diagonale<\/p>\n<p style=\"text-align: justify;\">Allineate i pezzi di pollo in un solo strato in un piatto profondo e capace.<\/p>\n<p style=\"text-align: justify;\">Mescolate in una ciotola lo yoghurt con l&#8217;olio, il succo del limone, tutte le spezie e un&#8217;abbondante presa di sale, sbattendo il tutto con una forchetta fino ad ottenere una crema ben omogenea.<\/p>\n<p style=\"text-align: justify;\">Unite l&#8217;aglio precedentemente pestato e versate il composto sui petti di pollo rigirandoli in modo che risultino ben rivestiti dalla crema di yoghurt<\/p>\n<p style=\"text-align: justify;\">Coprite la preparazione con pellicola trasparente e lasciate riposare in un luogo fresco (non in frigo) per circa 3 ore, mescolando ogni tanto i pezzi di pollo in modo che siano sempre ben coperti dalla crema di yoghurt.<\/p>\n<p style=\"text-align: justify;\">Accendete il forno a 150-170.<\/p>\n<p style=\"text-align: justify;\">Trasferite i pezzi di pollo in una pirofila e non appena il forno sara&#8217; ben caldo cuoceteli per mezz&#8217;ora circa o fino a quando saranno cotti e ben dorati<br \/>\nA cottura ultimata, trasferite i pezzi di pollo su un piatto da portata e guarnite con fettine di spicchi di lime.<\/p>\n<p style=\"text-align: justify;\">A parte, avevo preparato un fuso di pollo alquanto &#8220;triste&#8221; per Tobias: me lo sono dovuta mangiare io, mentre lui e&#8217; stato ben contento di mangiare il pollo tandoori.<\/p>\n<p style=\"text-align: justify;\">Purtroppo ultimamente sono carente in fatto di foto&#8230; perdonatemi!<\/p>\n<p>Un po&#8217; qua &#8230; und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa volta parliamo e cuciniamo il &#8230;. Pollo Tandoori.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[230,64,22,60],"tags":[233,183],"class_list":["post-2209","post","type-post","status-publish","format-standard","hentry","category-asia","category-carne","category-food","category-secondi_piatti","tag-asia_meridionale","tag-yoghurt"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2209"}],"version-history":[{"count":6,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2209\/revisions"}],"predecessor-version":[{"id":31164,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2209\/revisions\/31164"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}