{"id":21992,"date":"2020-04-23T14:19:37","date_gmt":"2020-04-23T12:19:37","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21992"},"modified":"2022-02-28T15:20:09","modified_gmt":"2022-02-28T14:20:09","slug":"principato-monaco_salade-nicoise","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/04\/23\/principato-monaco_salade-nicoise\/","title":{"rendered":"# 57 &#8211; Principato di Monaco. Salade ni\u00c3\u00a7oise"},"content":{"rendered":"<p style=\"text-align: justify;\">Oramai non so piu&#8217; che cosa cucinare.<br \/>\nIl tempo inizia a riscaldarsi, quindi niente zuppe invernali.<\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nIn compenso e&#8217; difficile trovare gli ingredienti adatti per tutte le preparazioni: esco una volta ogni 10-12 giorni, faccio un carrello immenso e spesso devo dirottare le mie idee al volo.<\/p>\n<p style=\"text-align: justify;\">Quello che non capisco ancora e&#8217; come facciano, certe persone, ad avere degli esili e snelli carrelli della spesa&#8230; bah&#8230;<\/p>\n<p style=\"text-align: justify;\">Ad ogni modo, oggi ho affrontato il <strong>Principato di Monaco<\/strong>, pranzo preparato velocemente giusto al ritorno dell&#8217;ennesima spesa (questa volta c&#8217;era carenza di riso, di lievito sotto ogni forma e .. di elastico per le mutande ).<br \/>\nL&#8217;altra idea di preparazione, la socca, vorrei affrontarla con calma, magari domenica per accompagnare la grigliata.<\/p>\n<p style=\"text-align: justify;\">L\u00e2\u20ac\u2122<strong>insalata Nizzarda (Salade ni\u00c3\u00a7oise)<\/strong>, tipica ricetta provenzale originaria di Nizza (Francia), \u00c3\u00a8 una preparazione dalle caratteristiche mediterranee, formata da verdure crude dal gusto molto deciso, che racchiudono tutto il sapore del sole, e dal tonno.<\/p>\n<p style=\"text-align: justify;\">Saporita e fresca, \u00c3\u00a8 ideale per essere consumata durante la stagione estiva perch\u00c3\u00a9 ricca di sali minerali, fibre, vitamine e proteine.<\/p>\n<p style=\"text-align: justify;\">L\u00e2\u20ac\u2122insalata nizzarda si \u00c3\u00a8 diffusa a livello internazionale, anche se con miriadi di varianti, che spesso, ne fanno perdere l\u00e2\u20ac\u2122originale e tipica composizione, sottoposta, invece, a Nizza, a regole severe: data la sua ricca consistenza, l\u00e2\u20ac\u2122insalata nizzarda pu\u00c3\u00b2 essere servita sia come piatto adatto a coprire la prima parte di un pasto estivo, sia come piatto unico o, perche&#8217; no, un leggero antipasto.<\/p>\n<p style=\"text-align: justify;\">A Nizza la preparazione deve rispettare regole severe: possono essere aggiunti alla ricetta originale anche altri ingredienti a proprio piacimento, come sedano, fave fresche e lattuga, ma l\u00e2\u20ac\u2122importante \u00c3\u00a8 che siano verdure crude. Non sono infatti ammessi<strong> fagiolini<\/strong> o patate lessate per completare il piatto\u00c2\u00a0che, invece,\u00c2\u00a0fanno parte del cosiddetto <strong>condiglione<\/strong>, piatto tipico della zona ligure molto simile all&#8217;insalata nizzarda. A Nizza, infine, non si pu\u00c3\u00b2\u00c2\u00a0condire l&#8217;insalata nizzarda con l&#8217;aceto.<\/p>\n<p>Partendo da questo presupposto, ecco la mia.<\/p>\n<p><strong>Ingredienti &#8211; Salade ni\u00c3\u00a7oise \/ Insalata nizzarda<br \/>\n<\/strong><\/p>\n<pre>Insalata\r\npomodori\r\npeperone giallo\r\ncetrioli\r\ntonno sott'olio\r\nuova sode\r\ncuore di carciofo (in scatola)\r\ncipollotto\r\nolive nere<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p>Preparate tutti gli ingredienti e condite con sale, pepe ed olio d&#8217;oliva.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21997\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200423_131355-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200423_131355-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200423_131355-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200423_131355-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200423_131355-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><b><br \/>\nMonaco<\/b> (pronuncia italiana \/\u00cb\u02c6m\u00c9\u201dnako\/; pronuncia francese: \/m\u00c9\u201dna\u00cb\u02c6ko\/; M\u00c3\u00b9negu in ligure comune e monegasco, pronuncia \/\u00cb\u02c6munegu\/), per esteso <b>Principato di Monaco<\/b> (<i>Principaut\u00c3\u00a9 de Monaco<\/i> in francese; <i>Principatu de Mu\u00cc\u008dnegu<\/i> in monegasco), \u00c3\u00a8 una citt\u00c3\u00a0-Stato indipendente dell&#8217;Europa occidentale, confinante con la sola Francia e bagnata dal Mar Ligure.<\/p>\n<p style=\"text-align: justify;\">La sua localit\u00c3\u00a0 pi\u00c3\u00b9 conosciuta e prestigiosa \u00c3\u00a8 Monte Carlo, ossia il quartiere pi\u00c3\u00b9 centrale della citt\u00c3\u00a0-Stato, nelle cui strade \u00c3\u00a8 ricavato il celebre circuito automobilistico di Formula 1, uno dei pi\u00c3\u00b9 difficili al mondo per via della sua tortuosit\u00c3\u00a0 e variet\u00c3\u00a0 di percorso.<\/p>\n<figure id=\"attachment_31058\" aria-describedby=\"caption-attachment-31058\" style=\"width: 470px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-31058\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2019\/11\/mappa-europa-capitali-e1619257906254.jpg\" alt=\"\" width=\"470\" height=\"410\" \/><figcaption id=\"caption-attachment-31058\" class=\"wp-caption-text\">Da Internet: Mappa dell&#8217;Europa con le capitali<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La lingua ufficiale dello stato \u00c3\u00a8 il francese ma, a causa della vocazione turistica internazionale del principato e dell&#8217;alta presenza di residenti stranieri di svariate nazionalit\u00c3\u00a0, sono largamente diffusi anche l&#8217;italiano e l&#8217;inglese.<\/p>\n<p style=\"text-align: justify;\">Alcuni anni fa abbiamo avuto la possibilita&#8217; di spendere alcune ore nel Principato.<br \/>\nSe siete curiosi di vedere qualche monumento, o qualche foto sporadica\u00c2\u00a0 non vi resta che cliccare <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2017\/06\/13\/principato-di-monaco\/\">QUI<\/a><\/strong><\/em>.<\/p>\n<p>Profitez de votre repas<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oramai non so piu&#8217; che cosa cucinare. Il tempo inizia a riscaldarsi, quindi niente zuppe invernali.<\/p>\n","protected":false},"author":2,"featured_media":21998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,22,60,61],"tags":[176,243,256],"class_list":["post-21992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-food","category-secondi_piatti","category-uova-formaggio","tag-176","tag-europa_sud","tag-vegetariano"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21992"}],"version-history":[{"count":9,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21992\/revisions"}],"predecessor-version":[{"id":31138,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21992\/revisions\/31138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21998"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}