{"id":21966,"date":"2020-04-21T12:35:57","date_gmt":"2020-04-21T10:35:57","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21966"},"modified":"2022-01-23T16:03:34","modified_gmt":"2022-01-23T15:03:34","slug":"swaziland_brasato_carne","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/04\/21\/swaziland_brasato_carne\/","title":{"rendered":"# 56 &#8211; Regno dello Swaziland. Brasato di carne (Schmorfleisch)"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;<b>eSwatini<\/b>, ufficialmente <b>Regno di eSwatini<\/b>, nome adottato alla proclamazione dell&#8217;indipendenza ma poco usato, \u00c3\u00a8 uno Stato indipendente dell&#8217;Africa meridionale noto fino al 2018 come <b>Swaziland<\/b>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Si trova sul fianco orientale dei monti dei Draghi e confina con il Mozambico a est e con il Sudafrica a nord, ovest e sud.<br \/>\nNon ha sbocco sul mare e dista circa 80\u00c2\u00a0km dall&#8217;Oceano Indiano.<br \/>\nLe lingue ufficiali sono l&#8217;inglese e lo swati (siswati), parlati da gran parte della popolazione. D&#8217;uso comune \u00c3\u00a8 anche l&#8217;afrikaans.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30475\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2021\/04\/africa-e1618414835640.png\" alt=\"\" width=\"480\" height=\"465\" \/><\/p>\n<p style=\"text-align: justify;\">Che fare?<br \/>\nFortuna che avevo preso alcuni appunti (e ricette!) dal meraviglioso libro in prestito dalla libreria, <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/05\/so-kocht-afrika\/\">&#8220;So kocht Afrika&#8221; di Dorah Sitole<\/a><\/strong><\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20829\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200219_152641-e1582137522831-1024x1024.jpg\" alt=\"\" width=\"525\" height=\"525\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200219_152641-e1582137522831-1024x1024.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200219_152641-e1582137522831-150x150.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200219_152641-e1582137522831-300x300.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200219_152641-e1582137522831-768x768.jpg 768w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/02\/IMG_20200219_152641-e1582137522831-100x100.jpg 100w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><strong>Ingredienti <\/strong>per lo<strong> Schmorfleisch (brasato di carne) <\/strong>&#8211; x 4-6 persone<\/p>\n<pre>4 cucchiai di olio\r\n750gr di stinco di manzo\r\n3 cucchiai di farina\r\nsale e pepe q.b.\r\n2 cipolle tagliate\r\n1 spicchio di aglio, pressato\r\n1 cucchiaino di cumino macinato\r\n1 cucchiaino di koriandolo\r\n3 patate a fette\r\n4 carote a fette\r\n500ml di brodo di carne<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Scaldate l&#8217;olio, dorate la carne a pezzetti dopo averla salata, pepata ed infarinata.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21987\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_101844-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_101844-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_101844-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_101844-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_101844-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nRimuovetela dalla pentola e tenetela al caldo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21986\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102318-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102318-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102318-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102318-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102318-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Inserite le cipolle, l&#8217;aglio, il cumino ed il coriandolo nell&#8217;olio e dorate il tutto.<br \/>\n{ <em>Avendo inserito poco olio non ne avevo molto a disposizione, ho cosi&#8217; inserito un goccio d&#8217;acqua e fatto deglassare il tutto, cosi&#8217; da poter meglio scaldare gli ulteriori ingredienti<\/em> }.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21985\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102956-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102956-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102956-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102956-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_102956-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Inserite gli ulteriori ingredienti nella pentola, aggiungendo anche la carne.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21983\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_103428-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_103428-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_103428-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_103428-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_103428-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nCuocete a fuoco medio per 45minuti circa.<\/p>\n<figure id=\"attachment_21982\" aria-describedby=\"caption-attachment-21982\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21982 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122811-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122811-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122811-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122811-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122811-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21982\" class=\"wp-caption-text\">Regno dello Swaziland. Brasato di carne (Schmorfleisch)<\/figcaption><\/figure>\n<p><strong>Note Personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">non avendo trovato lo &#8220;stinco di manzo&#8221; ho ripiegato per un normale pezzo da brasato<\/li>\n<li style=\"text-align: justify;\">una cipolla ed uno scalogno&#8230;<\/li>\n<li style=\"text-align: justify;\">e neppure patate..<\/li>\n<\/ul>\n<figure id=\"attachment_21981\" aria-describedby=\"caption-attachment-21981\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21981 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122826-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122826-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122826-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122826-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200421_122826-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21981\" class=\"wp-caption-text\">Regno dello Swaziland. Brasato di carne (Schmorfleisch)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Non avendo poi molta voglia di preparare della polenta o del riso, abbiamo accompagnato questo brasato con del pane.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">La cucina del <strong>Regno dello Swaziland<\/strong> si basa sua una cucina di un paese piuttosto povero economicamente e nelle risorse, la maggior parte dei piatti tipici sono a base di verdure e derivati del latte.<br \/>\nGli swazi sono per\u00c3\u00b2 per tradizione un popolo di consumatori di carne e pesce e molte ricette conservano ancora gli antichi sapori.<br \/>\nCon le carni le preparazioni pi\u00c3\u00b9 comuni sono in forma di stufato, servito di norma con la tipica purea di mais o il riso, denominatori comuni dell&#8217;Africa meridionale in cucina.<br \/>\nLa birra e&#8217; spesso prodotta dalla fermentazione del sorgo o del mais.<\/p>\n<p>Geniet u maaltyd<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;eSwatini, ufficialmente Regno di eSwatini, nome adottato alla proclamazione dell&#8217;indipendenza ma poco usato, \u00c3\u00a8 uno Stato indipendente dell&#8217;Africa meridionale noto fino al 2018 come Swaziland.<\/p>\n","protected":false},"author":2,"featured_media":21969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173,64,22,60],"tags":[176,223],"class_list":["post-21966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-carne","category-food","category-secondi_piatti","tag-176","tag-africa_del_sud"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21966"}],"version-history":[{"count":10,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21966\/revisions"}],"predecessor-version":[{"id":30534,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21966\/revisions\/30534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21969"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}