{"id":21732,"date":"2020-04-14T15:05:45","date_gmt":"2020-04-14T13:05:45","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21732"},"modified":"2021-04-17T10:47:37","modified_gmt":"2021-04-17T08:47:37","slug":"dulce-de-leche-pap","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/04\/14\/dulce-de-leche-pap\/","title":{"rendered":"Dulce de leche &#8211; in Pentola a Pressione"},"content":{"rendered":"<p style=\"text-align: justify;\">Il <strong>dulce de leche<\/strong> (\/&#8217;dul\u00ce\u00b8e de &#8216;let\u00ca\u0192e\/) in spagnolo o doce de leite (\/\u00cb\u02c6do.si d\u00cd\u00a1\u00ca\u2019i \u00cb\u02c6lej.t\u00ca\u0192i\/) in portoghese, \u00c3\u00a8 un dessert a base di latte.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00c3\u02c6 un dolce originario dell&#8217;<strong>America Latina.<\/strong><br \/>\n\u00c3\u02c6 molto popolare in gran parte del Sudamerica e viene preparato facendo cuocere a lungo il latte e lo zucchero fino a ottenere una crema, e il suo sapore \u00c3\u00a8 molto simile a quello delle caramelle al mou.<\/p>\n<p style=\"text-align: justify;\">Il nome tradotto alla lettera significa \u00e2\u20ac\u0153dolce di latte\u00e2\u20ac\u009d, o meglio, &#8220;confettura di latte&#8221;, in quanto si prepara in modo simile a una marmellata di frutta, ma con il latte al posto della frutta (dulce significa &#8220;dolce [generico]&#8221;, anche chiamato postre, che sta per dessert; erroneamente alcuni lo traducono come marmellata, che invece in spagnolo si dice mermelada).<\/p>\n<p style=\"text-align: justify;\">Il dolce francese confiture de lait \u00c3\u00a8 molto simile alla variante spalmabile del dulce de leche. Ne esistono versioni pi\u00c3\u00b9 o meno simili in Messico (la cajeta), in Per\u00c3\u00b9 (il manjarblanco), in Cile ed Ecuador (il manjar), e in Colombia e Venezuela (l&#8217;arequipe), Cuba (fanguito, fatto con il latte concentrato cotto in pentola a pressione per 45 minuti).<\/p>\n<p style=\"text-align: justify;\">Esistono pi\u00c3\u00b9 modi di fare il dulce de leche, sicuramente utilizzando la pentola a pressione per la sua cottura \u00c3\u00a8 il pi\u00c3\u00b9 rapido, veloce e semplice.<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<pre>1 barattolino di latte condensato zuccherato in lattina<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Inserite il barattolino di latte condensato nella pentola a pressione (magari togliendo la sua etichetta di carta prima&#8230;).<br \/>\nVersate l\u00e2\u20ac\u2122acqua nella pentola a pressione in modo che ricopra abbondantemente il barattolo, e che quindi ne dovr\u00c3\u00a0 essere completamente sommerso.<br \/>\nNon sapendo se il barattolino del latte condensato si fosse arrugginito, ho usato la pentola alta da 8litri e il cestello, cosi&#8217; da evitare il contatto diretto con il fondo della pentola.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21756\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093136-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093136-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093136-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093136-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093136-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Chiudete la pentola a pressione e calcolate 25 minuti dal fischio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21755\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093452-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093452-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093452-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093452-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093452-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Spegnete, lasciate uscire il vapore normalmente prima di aprire la pentola.<br \/>\nAvendo un piano a cottura ad induzione, ho spostato la pentola cosi&#8217; da non lasciare il magnete ancora a contatto (e far cuocere ulteriormente il preparato).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21754\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093610-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093610-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093610-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093610-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_093610-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nTirate fuori il barattolino con <strong><span style=\"color: #ff0000;\">MOLTA<\/span><\/strong> attenzione dato che <span style=\"color: #ff0000;\">scotta<\/span> tremendamente e lasciatelo raffreddare prima di aprilo, mi raccomando!<br \/>\nPer raffreddarsi completamente, ci vorranno alcune ore.<\/p>\n<p style=\"text-align: justify;\">Se non utilizzate subito il dulce de leche, e&#8217; meglio travasare il contenuto in un nuovo barattolo di vetro sterilizzato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21760\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155325-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155325-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155325-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155325-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155325-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21758\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155438-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155438-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155438-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155438-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155438-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21759\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155404-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155404-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155404-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155404-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200411_155404-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Potete usare il <strong>dulce de leche<\/strong> cosi&#8217; (piccoli esempi)<\/p>\n<ul>\n<li style=\"text-align: justify;\">per variegare il gelato<\/li>\n<li style=\"text-align: justify;\">per farcire torte, panna cotta, biscotti o muffin<\/li>\n<li style=\"text-align: justify;\">per aromatizzare ulteriormente una crema al latte<\/li>\n<li style=\"text-align: justify;\">in aggiunta ad un milk shake<\/li>\n<li style=\"text-align: justify;\">\u00c2\u00a0consumato o spalmato su pane fresco o tostato<\/li>\n<li style=\"text-align: justify;\">La confiture de lait francese viene generalmente servita con fromage blanc.<\/li>\n<\/ul>\n<figure id=\"attachment_21816\" aria-describedby=\"caption-attachment-21816\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21816 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200413_103222-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200413_103222-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200413_103222-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200413_103222-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200413_103222-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21816\" class=\"wp-caption-text\">Dulce de Leche sopra pancake<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em>Le origini di questa crema?<\/em><\/p>\n<p style=\"text-align: justify;\">Ci sono diverse versioni storiche sulla nascita del dulce de leche.<br \/>\nLa pi\u00c3\u00b9 famosa riguarda il caudillo argentino Juan Manuel de Rosas del XIX secolo.<br \/>\nLa storia narra che in un pomeriggio d&#8217;inverno, a casa di de Rosas, la domestica stesse preparando della lechada (una bevanda a base di latte e zucchero fatta bollire fino a caramellarsi) quando sent\u00c3\u00ac bussare alla porta Lasci\u00c3\u00b2 la lechada sul fornello e and\u00c3\u00b2 ad aprire; quando torn\u00c3\u00b2 in cucina, la lechada si era cotta fino a trasformarsi in una crema marrone: il dulce de leche.<\/p>\n<p style=\"text-align: justify;\">Oppure potrebbe anche essere nato in Europa, forse come la confiture de lait francese: una leggenda popolare molto simile e risalente al XIV secolo viene tramandata nella regione della Normandia, e narra del cuoco di una guarnigione militare che ebbe lo stesso incidente mentre preparava del latte zuccherato per colazione.<\/p>\n<p style=\"text-align: justify;\">Nel 2003 il giornalista argentino V\u00c3\u00adctor Ego Ducrot ha dimostrato che il dulce de leche si origin\u00c3\u00b2 in Cile, arrivando a Cuyo e successivamente a Tucum\u00c3\u00a1n, dove si utilizz\u00c3\u00b2 come ripieno per gli alfajores.<\/p>\n<p style=\"text-align: justify;\">Anche se esistono registri del consumo di dulce de leche fin dall&#8217;epoca coloniale, il Cile non ha mai reclamato la paternit\u00c3\u00a0 del prodotto.<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il dulce de leche (\/&#8217;dul\u00ce\u00b8e de &#8216;let\u00ca\u0192e\/) in spagnolo o doce de leite (\/\u00cb\u02c6do.si d\u00cd\u00a1\u00ca\u2019i \u00cb\u02c6lej.t\u00ca\u0192i\/) in portoghese, \u00c3\u00a8 un dessert a base di latte.<\/p>\n","protected":false},"author":2,"featured_media":21758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,152,69,22,226],"tags":[53,160],"class_list":["post-21732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al_cucchiaio","category-confetture","category-dessert","category-food","category-stati-americhe","tag-pentola_a_pressione","tag-sud_america"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21732"}],"version-history":[{"count":13,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21732\/revisions"}],"predecessor-version":[{"id":30764,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21732\/revisions\/30764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21758"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}