{"id":2164,"date":"2009-02-10T18:40:21","date_gmt":"2009-02-10T17:40:21","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/index.php\/2018\/01\/20\/torta-di-banane\/"},"modified":"2019-11-28T17:45:39","modified_gmt":"2019-11-28T16:45:39","slug":"torta-di-banane","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2009\/02\/10\/torta-di-banane\/","title":{"rendered":"Torta di banane"},"content":{"rendered":"<p style=\"text-align: justify;\">Dopo l&#8217;ondata di &#8220;sole banane&#8221;, siamo passati a quella di &#8220;solo pere&#8221;.<br \/>\nCosi&#8217; mi avanzavano alcune banane&#8230;<!--more--><\/p>\n<p style=\"text-align: justify;\">Ecco come le ho usate, dal ricettario di mia mamma&#8230; &#8221; <strong>torta di banane<\/strong>&#8221; \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\">So, comunque, che non e&#8217; bene cambiare le dosi ai dolci, ma mi sembrava decisamente TROPPO zuccherosa, cosi&#8217; troverete le 2 varianti:<\/p>\n<p style=\"text-align: justify;\"><strong>Ingredienti<\/strong><\/p>\n<pre style=\"text-align: justify;\">300 gr di farina\r\n 250 gr di burro (ne ho usati 130gr scarsi)\r\n 250 gr di zucchero (meno di 180gr)\r\n 4 uova\r\n 1 bustina di lievito\r\n 2 banane schiacciate\r\n 1 pizzico di cannella\r\n IN PIU': cioccolato grattugiato\r\n 1 banana per la \"decorazione\", che poi non si e' vista ;)<\/pre>\n<p style=\"text-align: justify;\"><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Sbattete il burro e lo zucchero, aggiungete le uova una alla volta e sbattete sempre bene.<br \/>\nDopo aver frullato le banane, unitele all&#8217;impasto, mettete il lievito e la cannella.<br \/>\nSbattete per almeno 5 minuti.<br \/>\nUngete la teglia e infarinatela<\/p>\n<p style=\"text-align: justify;\">Una grattatina di cioccolato (meglio se a gocce!!) nell&#8217;impasto ed una banana tagliata a fettine sul fondo della teglia<\/p>\n<p style=\"text-align: justify;\">Mettete in forno a 200 per 45 minuti.<\/p>\n<p>Un po&#8217; qua &#8230; und ein bisschen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l&#8217;ondata di &#8220;sole banane&#8221;, siamo passati a quella di &#8220;solo pere&#8221;. Cosi&#8217; mi avanzavano alcune banane&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,22,79],"tags":[107],"class_list":["post-2164","post","type-post","status-publish","format-standard","hentry","category-dessert","category-food","category-torte","tag-frutta"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=2164"}],"version-history":[{"count":3,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2164\/revisions"}],"predecessor-version":[{"id":19394,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/2164\/revisions\/19394"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=2164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=2164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=2164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}