{"id":21521,"date":"2020-04-01T13:28:10","date_gmt":"2020-04-01T11:28:10","guid":{"rendered":"https:\/\/strudeldimele.dnshome.de\/?p=21521"},"modified":"2022-01-24T17:50:34","modified_gmt":"2022-01-24T16:50:34","slug":"sudafrica-xhosa_inkukhi-nembotj","status":"publish","type":"post","link":"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/04\/01\/sudafrica-xhosa_inkukhi-nembotj\/","title":{"rendered":"# 39 &#8211; SudAfrica\/Xhosa. Inkukhi Nembotji."},"content":{"rendered":"<p style=\"text-align: justify;\">Oggi ritorniamo in <em><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/08\/sudafrica-kapmalaien_bobotie\/\"><strong>SudAfrica<\/strong><\/a><\/em>\u00c2\u00a0 e,\u00c2\u00a0 con questo cibo &#8220;Inkukhu Nembotji&#8221; (letteralmente &#8220;pollo e fagioli&#8221;), veniamo a celebrare il gruppo degli Xhosa.<br \/>\nCi troviamo dunque nella provincia di <em>Pretoria<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">La ricetta seguita e&#8217; stata presa dal <em><strong><a href=\"https:\/\/strudeldimele.dnshome.de\/index.php\/2020\/03\/05\/so-kocht-afrika\/\">libro<\/a><\/strong><\/em> e, devo ammettere, e&#8217; veramente semplice e veloce.<br \/>\nMagari ho perso qualche step?<\/p>\n<p><strong>Ingredienti<\/strong> per 4-6 persone di &#8220;<strong>Inkukhi Nembotji<\/strong>&#8221;<\/p>\n<pre>500ml di olio\r\n1 cipolla tagliuzzata\r\n3 petti di pollo, tagliati a striscie\r\nsale q.b.\r\n1 cucchiaino di Garam Masala\r\n150gr di cornetti\/fagiolini (puliti)\r\n250ml di brodo di pollo<\/pre>\n<p><strong>Procedimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Mettete l&#8217;olio in una pentola e fatelo scaldare, inserite poi le cipolle e fatele brasare, fino a quando non assumeranno un colore dorato.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21527\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_122830-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_122830-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_122830-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_122830-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_122830-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nA questo punto aggiungete il petto di pollo a striscioline e fatelo cuocere, portandolo a fine cottura.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21528\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_123236-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_123236-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_123236-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_123236-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_123236-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21529\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_124607-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_124607-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_124607-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_124607-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_124607-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nAggiungete il sale, se necessario, ed insaporite con il Garam Masala.<\/p>\n<p style=\"text-align: justify;\">Inserite i fagiolini, lasciandoli interi o a piccoli pezzetti, unendoli al brodo di pollo.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21530\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125139-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125139-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125139-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125139-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125139-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><br \/>\nMescolate bene e portate a fine cottura.<br \/>\nSalate se necessario.<\/p>\n<p style=\"text-align: justify;\">Potete accompagnarla con della polenta, come abbiamo fatto noi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21531\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125142-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125142-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125142-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125142-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_125142-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify;\">Questa volta ho usato della farina di polenta precotta, di Molino Rossetto, cosi&#8217; da impiegare solo 5 minuti di cottura.<br \/>\nNon valeva la pena cuocerla nella pentola a pressione.<\/p>\n<figure id=\"attachment_21532\" aria-describedby=\"caption-attachment-21532\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21532 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130045-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130045-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130045-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130045-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130045-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21532\" class=\"wp-caption-text\">SudAfrica\/Xhosa. Inkukhi Nembotji<\/figcaption><\/figure>\n<figure id=\"attachment_21533\" aria-describedby=\"caption-attachment-21533\" style=\"width: 525px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21533 size-large\" src=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130217-1024x576.jpg\" alt=\"\" width=\"525\" height=\"295\" srcset=\"https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130217-1024x576.jpg 1024w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130217-150x84.jpg 150w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130217-300x169.jpg 300w, https:\/\/strudeldimele.dnshome.de\/wp-content\/uploads\/2020\/04\/IMG_20200401_130217-768x432.jpg 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><figcaption id=\"caption-attachment-21533\" class=\"wp-caption-text\">SudAfrica\/Xhosa. Inkukhi Nembotji<\/figcaption><\/figure>\n<p><strong>Note personali<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Decisamente non ho adoperato tutto l&#8217;olio menzionato in questa ricetta, ma solo una piccolissima parte<\/li>\n<li style=\"text-align: justify;\">Il Garam Masala utilizzato e&#8217; quello indiano<\/li>\n<li style=\"text-align: justify;\">Non so quanti fagiolini\/cornetti ho utilizzato, ne ho presi a caso dalla confezione surgelata<\/li>\n<li style=\"text-align: justify;\">Al termine il risultato e&#8217; stato abbastanza brodoso, cosi&#8217; che ho addensato il composto con della farina di semi di carruba,<\/li>\n<\/ul>\n<hr \/>\n<p style=\"text-align: justify;\">Gli <strong>xhosa<\/strong> sono parte del gruppo nguni meridionale che migr\u00c3\u00b2 verso sud dalla regione dei dei Grandi Laghi, stabilendosi nel sudest del Sudafrica.<br \/>\nProve linguistiche e archeologiche suggeriscono che siano arrivati in Sudafrica circa 1500 anni fa.<br \/>\nTecnicamente, gli Xhosa furono originariamente un clan, e presero il nome dal leader di tale clan, uXhosa.<br \/>\nLa loro parola per riferirsi al proprio gruppo \u00c3\u00a8 <i>amaXhosa<\/i> e chiamano la loro lingua <i>isiXhosa<\/i>.<br \/>\nIl nome &#8220;xhosa&#8221; viene talvolta usato per indicare un qualsiasi gruppo di lingua xhosa.<\/p>\n<p style=\"text-align: justify;\">La cultura tradizionale degli xhosa sopravvive oggi soprattutto nelle campagne; negli elementi fondamentali, essa \u00c3\u00a8 equivalente a quella degli altri popoli del gruppo nguni come zulu, ndbele e swazi.<br \/>\nOgni nucleo familiare ha un proprio villaggio, dotato di un orto e un recinto per il bestiame, ed \u00c3\u00a8 governato da un capofamiglia.<br \/>\nLa ricchezza della famiglia si conta in capi di bestiame; nel conteggio per\u00c3\u00b2 vengono incluse le donne da marito, perch\u00c3\u00a9 l&#8217;acquisto di una moglie costa allo sposo un certo numero di capi.<\/p>\n<p>Jabulela isidlo sakho<\/p>\n<p>Un po\u00e2\u20ac\u2122 qua \u00e2\u20ac\u00a6 und ein bischen dort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi ritorniamo in SudAfrica\u00c2\u00a0 e,\u00c2\u00a0 con questo cibo &#8220;Inkukhu Nembotji&#8221; (letteralmente &#8220;pollo e fagioli&#8221;), veniamo a celebrare il gruppo degli Xhosa. Ci troviamo dunque nella provincia di Pretoria<\/p>\n","protected":false},"author":2,"featured_media":21131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173,64,22,138,60],"tags":[176,223],"class_list":["post-21521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-carne","category-food","category-piatti_unici","category-secondi_piatti","tag-176","tag-africa_del_sud"],"_links":{"self":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/comments?post=21521"}],"version-history":[{"count":12,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21521\/revisions"}],"predecessor-version":[{"id":35606,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/posts\/21521\/revisions\/35606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media\/21131"}],"wp:attachment":[{"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/media?parent=21521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/categories?post=21521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strudeldimele.dnshome.de\/index.php\/wp-json\/wp\/v2\/tags?post=21521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}